{"id":22185,"date":"2024-04-06T14:35:58","date_gmt":"2024-04-06T14:35:58","guid":{"rendered":"https:\/\/cosmosan.ch\/?page_id=22185"},"modified":"2025-06-27T07:03:22","modified_gmt":"2025-06-27T07:03:22","slug":"menopause","status":"publish","type":"page","link":"https:\/\/cosmosan.ch\/en\/menopause\/","title":{"rendered":"menopausal problems"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"22185\" class=\"elementor elementor-22185\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6226197 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle sc_fly_static\" data-id=\"6226197\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ced10d sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"4ced10d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30fb7f47 scheme_default elementor-section-boxed elementor-section-height-default elementor-section-height-default sc_fly_static\" data-id=\"30fb7f47\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3a6a8bad sc_inner_width_none sc_content_align_inherit sc_layouts_column_icons_position_left sc_fly_static\" data-id=\"3a6a8bad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aeeedd4 sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"aeeedd4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e867c8 elementor-hidden-mobile sc_fly_static elementor-widget elementor-widget-image\" data-id=\"2e867c8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/cosmosan.ch\/en\/gut-zu-wissen\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"24\" height=\"24\" src=\"https:\/\/cosmosan.ch\/wp-content\/uploads\/2024\/07\/cosmosan-back-button.svg\" class=\"attachment-large size-large wp-image-24815\" alt=\"cosmosan back button\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74cc8dd sc_fly_static elementor-widget elementor-widget-trx_sc_title\" data-id=\"74cc8dd\" data-element_type=\"widget\" data-widget_type=\"trx_sc_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\t\tclass=\"sc_title sc_title_default\" ><span class=\"sc_item_subtitle sc_title_subtitle sc_align_center sc_item_subtitle_above sc_item_title_style_default\">good to know: tcm &amp; acupuncture can help with<\/span><h1 class=\"sc_item_title sc_title_title sc_align_center sc_item_title_style_default sc_item_title_tag\"\n\t\t\t><span class=\"sc_item_title_text\">menopausal problems<\/span><\/h1><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41d80a9 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"41d80a9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-403dfbd elementor-widget__width-initial elementor-widget-mobile__width-inherit sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"403dfbd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>even at the mere thought of menopause, some women get an outbreak of sweat. some are lucky and don\u2019t get bothered by the hormonal change, but many suffer from symptoms such as hot flushes, sweating, a reddened face, heart palpitations, high blood pressure, dizziness, tinnitus, back pain, night sweats, dry mouth, eyes, hair and vagina, constipation, irritability, depression, increased facial hair growth, etc.\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c57ddee sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"c57ddee\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ec6ec5 sc_fly_static elementor-widget elementor-widget-image\" data-id=\"6ec6ec5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/cosmosan.ch\/wp-content\/uploads\/2024\/03\/menopause.svg\" class=\"attachment-large size-large wp-image-22330\" alt=\"menopause cosmosan praxis f\u00fcr traditionelle chinesische medizin\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ffd9e9 sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"0ffd9e9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c765b32 elementor-widget__width-initial elementor-widget-mobile__width-inherit sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"c765b32\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>the list of possible signs is long. and when the menopausal symptoms are too heavy, the option to take a hormone replacement is very tempting. comprehensible, and especially if a woman already has suffered from monthly complaints for decades \u2013 this on top is too much!<\/p><p>traditional chinese medicine (tcm) understands this change as a natural process, which occurs at the age of about 7x7 years. during menopause, which lasts about one to two years, the equilibrium of yin and yang, respectively the substances and the functional aspects of the body are out of balance.\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-635bf22 sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"635bf22\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d2cb07 sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"5d2cb07\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h3 class=\"elementor-heading-title elementor-size-default\">\u00abthe option to take a hormone replacement is very tempting\u00bb<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-031dc9a sc_height_small sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"031dc9a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2daa02e elementor-widget__width-initial elementor-widget-mobile__width-inherit sc_fly_static elementor-widget elementor-widget-text-editor\" data-id=\"2daa02e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>blood (yin) dries up, which is why heat (yang) rises. it is similar to a scale, you remove a bit from one bowl, the other bowl automatically rises. ideally, the two weigh bowls settle down again after a few months, because nature strives for harmony. but depending on your personal gynaecological history, the rebalancing can be very difficult or even not be possible to happen on its own. there are numerous unpleasant symptoms that persist if not treated.<\/p><p>in this case traditional chinese medicine (tcm) can provide a harmonizing service with acupuncture and herbs and rebalance the imbalance of yin (estrogen) and yang (progesterone). interestingly, sometimes yin and yang 'sink' equally. then symptoms like shivering, cold hands and feet, facial pallor and swollen ankles occur on top. in both cases tcm can mediate a balancing effect. if the complaints are only mild and bearable, it is advisable to experience the process, to trust nature and to let it run its course. however, if the quality of life is impaired, it is advisable to help nature gently. for best results, a good therapist will also give recommendations for nutrition and nutritional supplements. in the end, tcm may help women to stay cool.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bacfa85 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"bacfa85\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0096bf scheme_default sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"e0096bf\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"https:\/\/booking.localsearch.ch\/bookings\/cosmosan-praxis-fur-traditionelle-chinesische-medizin\/services?locale=de-CH\" class=\"sc_button sc_button_hover sc_button_size_normal sc_button_icon_left color_style_link2\" target=\"_blank\" rel=\"noopener\"><span class=\"sc_button_text\"><span class=\"sc_button_title\">book a consultation<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1adc74 sc_height_large sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"d1adc74\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-a656ca2 e-flex e-con-boxed sc_inner_width_none sc_layouts_column_icons_position_left e-con e-parent\" data-id=\"a656ca2\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65cbe02 sc_fly_static elementor-widget elementor-widget-heading\" data-id=\"65cbe02\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">these topics could also be of interest for you:<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e1e3b5 sc_height_tiny sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"6e1e3b5\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7bdd19 e-con-full e-flex sc_inner_width_none sc_layouts_column_icons_position_left e-con e-child\" data-id=\"c7bdd19\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17eeb37 scheme_light sc_fly_static elementor-widget elementor-widget-trx_sc_icons\" data-id=\"17eeb37\" data-element_type=\"widget\" data-widget_type=\"trx_sc_icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div \tclass=\"sc_icons color_style_dark scheme_light sc_icons_decoration sc_icons_size_large sc_align_center\" ><div  class=\"sc_icons_slider sc_item_slider slider_swiper_outer slider_outer slider_outer_controls slider_outer_controls_bottom slider_outer_nopagination slider_outer_nocentered slider_outer_overflow_hidden slider_outer_multi\">\n\t<div  data-slides-per-view-breakpoints=\"{&quot;1024&quot;:2,&quot;2399&quot;:&quot;5&quot;}\" class=\"slider_container swiper-slider-container slider_swiper slider_noresize slider_controls slider_controls_bottom slider_nopagination slider_nocentered slider_overflow_hidden slider_multi\" data-slides-per-view=\"5\" data-slides-space=\"20\" data-effect=\"slide\" data-slides-min-width=\"250\" data-pagination=\"bullets\" data-direction=\"horizontal\" data-mouse-wheel=\"0\" data-autoplay=\"1\" data-loop=\"1\" data-free-mode=\"0\" data-slides-centered=\"0\" data-slides-overflow=\"0\">\n\t\t<div class=\"slides slider-wrapper swiper-wrapper sc_item_columns_5\"><div class=\"slider-slide swiper-slide\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_icon sc_icon_type_svg\" style=\"color: #FFFFFF\" ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"500\" viewbox=\"0 0 375 374.999991\" height=\"500\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"282bc37967\"><path d=\"M 38 69 L 337.5 69 L 337.5 327 L 38 327 Z M 38 69 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><path fill=\"#e10e49\" d=\"M 251.386719 179.863281 C 251.292969 179.863281 251.167969 179.847656 251.054688 179.847656 L 232.800781 178.015625 C 231 177.832031 229.675781 176.214844 229.855469 174.402344 C 230.039062 172.601562 231.636719 171.238281 233.46875 171.457031 L 244.132812 172.527344 L 237.046875 163.300781 C 235.921875 161.847656 236.195312 159.796875 237.648438 158.6875 C 239.101562 157.554688 241.167969 157.847656 242.265625 159.285156 L 254 174.566406 C 254.796875 175.597656 254.910156 177.015625 254.273438 178.179688 C 253.695312 179.214844 252.585938 179.863281 251.386719 179.863281 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><g clip-path=\"url(#282bc37967)\"><path fill=\"#e10e49\" d=\"M 329.621094 168.128906 C 323.769531 164.546875 310.214844 153.433594 303.550781 152.46875 L 277.207031 146.925781 C 277.515625 143.058594 277.457031 139.242188 277.078125 135.410156 C 292.175781 133.972656 304.402344 115.113281 302.40625 101 C 302.152344 98.875 300.207031 97.273438 298.121094 97.527344 C 271.214844 100.054688 259.691406 81.8125 237.199219 74.5625 C 235.164062 73.800781 232.875 74.796875 232.09375 76.835938 C 230.332031 82.972656 239.597656 83.15625 243.449219 85.832031 C 261.273438 94.296875 271.246094 106.25 294.59375 105.667969 C 293.5 115.484375 285.691406 128.199219 273.480469 127.5625 L 243.46875 120.660156 C 227.027344 117.476562 210.890625 136.121094 203.675781 151.652344 L 196.535156 151.253906 C 186.03125 109.375 143.046875 117.023438 149.3125 162.898438 C 150.710938 173.65625 148.5 177.941406 138.558594 178.835938 C 137.5 172.125 135.488281 165.605469 133.8125 159.101562 C 125.367188 124.855469 143.789062 85.832031 178.453125 76.910156 C 180.542969 76.3125 181.777344 74.132812 181.179688 72.023438 C 180.578125 69.933594 178.398438 68.699219 176.292969 69.300781 C 137.597656 79.230469 116.6875 122.820312 126.148438 161.039062 C 129.710938 175.066406 136.070312 191.691406 125.203125 201.269531 C 120.242188 205.484375 100.710938 224.792969 95.371094 227.304688 C 78.671875 238.933594 64.996094 257.265625 53.75 273.144531 C 42.40625 289.984375 37.378906 306.1875 38.359375 322.667969 C 38.484375 324.761719 40.226562 326.375 42.304688 326.375 C 44.574219 326.375 46.40625 324.449219 46.261719 322.179688 C 45.394531 307.515625 49.988281 292.90625 60.308594 277.554688 C 71.210938 262.277344 83.964844 244.851562 100.191406 233.605469 C 110.148438 237.167969 127.078125 246.453125 136.722656 270.015625 C 144.648438 288.671875 154.515625 292.433594 162.855469 287.75 C 174.605469 301.664062 181.679688 312.582031 185.671875 323.777344 C 186.414062 325.84375 188.722656 326.886719 190.742188 326.136719 C 192.792969 325.386719 193.847656 323.121094 193.101562 321.070312 C 188.722656 308.984375 181.523438 297.558594 169.0625 282.898438 C 166.082031 279.390625 165.339844 272.460938 168.714844 269.375 L 196.820312 243.59375 C 209.542969 252.226562 229.070312 271.300781 237.679688 248.445312 C 238.792969 245.289062 238.792969 245.289062 241.824219 242.289062 C 244.386719 239.746094 245.496094 236.292969 244.808594 232.898438 C 248.460938 231.679688 251.765625 228.476562 252.183594 223.046875 C 252.453125 219.527344 253.019531 218 254.363281 215.34375 L 259.632812 216.765625 C 267.121094 218.964844 273.222656 212.113281 271.953125 204.664062 C 271.859375 203.046875 267.667969 177.46875 268.300781 176.6875 L 279.292969 185.589844 C 278.691406 187.582031 279.015625 189.746094 279.820312 191.585938 C 274.660156 195.128906 272.953125 202.648438 278.273438 208.464844 L 285.433594 216.128906 C 287.917969 220.835938 285.757812 229.738281 286.289062 235.660156 C 286.46875 244.53125 293.390625 247.523438 294.046875 254.902344 L 294.046875 322.746094 C 294.046875 324.765625 295.660156 326.375 297.660156 326.375 C 299.679688 326.375 301.289062 324.761719 301.289062 322.746094 L 301.289062 254.902344 C 301.289062 249.851562 299.003906 246.457031 296.984375 243.457031 C 289.226562 234.609375 297.859375 220.476562 290.972656 211.445312 L 283.558594 203.503906 C 280.671875 200.632812 283.320312 195.660156 286.390625 197.710938 L 298.910156 204.199219 C 302.234375 206.628906 305.429688 203.015625 301.632812 200.21875 L 287.988281 190.484375 C 284.40625 187.917969 287.460938 181.90625 291.257812 183.996094 L 305.519531 191.808594 C 310.0625 194.296875 311.480469 189.550781 308.425781 187.375 L 295.183594 177.902344 C 293.074219 176.671875 291.78125 175.144531 291.835938 173.632812 C 292.074219 171.203125 294.503906 169.382812 297.125 171.09375 L 312.183594 179.742188 C 315.328125 181.832031 318.144531 177.777344 314.75 175.488281 L 301.175781 165.082031 C 298.304688 163.15625 294.941406 162.789062 291.871094 163.808594 L 273.667969 159.996094 C 271.140625 159.71875 269.632812 157.050781 271.558594 154.90625 C 272.160156 154.234375 273.285156 153.523438 275.246094 153.941406 L 302.0625 159.574219 C 306.875 160.191406 321.179688 171.53125 325.5 174.113281 C 330.171875 177.308594 330.171875 177.308594 330.171875 182.957031 L 330.171875 322.746094 C 330.171875 324.765625 331.789062 326.375 333.789062 326.375 C 335.800781 326.375 337.417969 324.761719 337.417969 322.746094 L 337.417969 182.949219 C 337.433594 174.8125 336.34375 172.726562 329.621094 168.128906 M 263.339844 208.953125 C 263.175781 209.082031 262.777344 209.445312 261.707031 209.136719 L 253.351562 206.886719 C 251.511719 206.394531 249.664062 207.230469 248.804688 208.898438 C 246.421875 213.535156 244.753906 216.128906 244.296875 222.4375 C 244.097656 225.070312 242.445312 225.503906 241.503906 225.542969 C 235.941406 224.851562 230.621094 220.941406 223.949219 223.433594 C 221.898438 224.164062 220.824219 226.433594 221.574219 228.484375 C 222.300781 230.539062 224.550781 231.59375 226.625 230.867188 C 229.222656 229.90625 232.746094 231.394531 235.761719 232.355469 C 237.324219 233.738281 237.5625 235.539062 236.109375 236.824219 C 232.347656 240.535156 231.871094 241.113281 230.222656 245.839844 C 229.152344 248.871094 227.804688 250.671875 226.226562 251.199219 C 224.082031 251.890625 220.449219 250.597656 216.109375 247.546875 L 198.792969 235.296875 C 194.777344 232.351562 190.78125 229.558594 187.65625 226.214844 C 186.164062 224.613281 183.65625 224.527344 182.074219 226.015625 C 177.539062 231.304688 187.125 235.808594 190.289062 238.863281 L 163.359375 263.546875 C 158.949219 267.601562 157.875 274.050781 159.148438 279.828125 L 159.128906 279.828125 C 159.214844 280.578125 158.546875 281.320312 157.566406 281.570312 C 155.238281 282.140625 149.351562 279.9375 144.046875 267.019531 C 134.65625 244.109375 118.972656 233.207031 107.640625 228.101562 C 107.839844 227.917969 108.003906 227.792969 108.222656 227.613281 L 130.546875 207.101562 C 137.039062 201.15625 139.183594 194.09375 139.21875 186.714844 C 152.789062 185.878906 159.65625 177.050781 157.148438 161.859375 C 152.554688 123.632812 182.640625 121.90625 189.542969 155.917969 C 189.945312 157.648438 191.414062 158.882812 193.175781 158.988281 L 205.96875 159.714844 C 207.65625 159.828125 209.21875 158.824219 209.855469 157.261719 C 216.125 141.910156 230.824219 126.210938 241.835938 128.394531 L 269.015625 134.644531 C 269.742188 138.945312 269.285156 143.363281 269.453125 147.703125 C 263.925781 150.066406 261.65625 157.609375 265.054688 162.496094 C 262.441406 167.671875 259.476562 173.285156 260.53125 180.828125 L 264.128906 205.808594 C 264.34375 207.304688 263.886719 208.464844 263.339844 208.953125 M 285.433594 169.855469 C 284.382812 172.199219 284.34375 174.90625 285.359375 177.289062 C 284.414062 177.738281 283.5625 178.378906 282.800781 179.101562 L 270.574219 169.183594 C 270.9375 168.441406 271.300781 167.691406 271.703125 166.933594 C 271.867188 166.972656 272.007812 167.058594 272.191406 167.097656 Z M 285.433594 169.855469 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#e10e49\" d=\"M 194.953125 112.316406 L 184.890625 112.316406 C 183.730469 112.316406 182.640625 111.675781 182.058594 110.679688 C 181.457031 109.664062 181.457031 108.40625 182.039062 107.390625 L 192.59375 88.859375 L 187.976562 88.859375 C 186.160156 88.859375 184.527344 87.914062 183.601562 86.332031 C 182.691406 84.769531 182.691406 82.828125 183.582031 81.265625 L 201.441406 49.941406 C 202.027344 48.90625 203.113281 48.269531 204.292969 48.269531 L 217.648438 48.269531 C 218.828125 48.269531 219.917969 48.886719 220.496094 49.90625 C 221.097656 50.921875 221.097656 52.175781 220.515625 53.195312 L 211.753906 68.585938 L 222.636719 68.585938 C 224.707031 68.597656 226.507812 69.816406 227.308594 71.6875 C 228.089844 73.558594 227.691406 75.703125 226.308594 77.15625 L 197.476562 111.148438 C 196.84375 111.878906 195.917969 112.316406 194.953125 112.316406 M 190.582031 105.722656 L 193.429688 105.722656 L 219.375 75.179688 L 206.074219 75.179688 C 204.914062 75.179688 203.820312 74.5625 203.238281 73.546875 C 202.640625 72.527344 202.640625 71.273438 203.222656 70.253906 L 212 54.863281 L 206.222656 54.863281 L 190.59375 82.265625 L 198.28125 82.265625 C 199.445312 82.265625 200.53125 82.90625 201.132812 83.898438 C 201.714844 84.917969 201.714844 86.171875 201.132812 87.191406 Z M 221.40625 72.765625 C 221.394531 72.78125 221.355469 72.820312 221.355469 72.835938 Z M 221.40625 72.765625 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 120.300781 107.5 C 119.046875 107.5 117.847656 106.773438 117.304688 105.558594 C 116.558594 103.902344 117.304688 101.941406 118.953125 101.195312 C 120.390625 100.5625 121.589844 99.363281 122.261719 97.90625 C 122.917969 96.503906 123.042969 94.960938 122.605469 93.671875 C 121.320312 89.820312 122.1875 85.316406 124.894531 81.898438 C 127.640625 78.480469 131.871094 76.628906 135.890625 77.03125 C 137.269531 77.15625 138.703125 76.707031 139.90625 75.757812 C 141.191406 74.761719 142.085938 73.324219 142.375 71.796875 C 142.738281 70.015625 144.5 68.871094 146.242188 69.214844 C 148.042969 69.5625 149.203125 71.292969 148.863281 73.085938 C 148.246094 76.171875 146.5 78.972656 143.976562 80.953125 C 141.449219 82.917969 138.253906 83.882812 135.238281 83.589844 C 133.492188 83.445312 131.402344 84.332031 130.058594 86.003906 C 128.734375 87.675781 128.277344 89.820312 128.859375 91.582031 C 129.839844 94.511719 129.625 97.742188 128.242188 100.707031 C 126.878906 103.59375 124.554688 105.921875 121.667969 107.207031 C 121.222656 107.410156 120.773438 107.5 120.300781 107.5 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 107.710938 207.0625 C 106.367188 207.0625 105.097656 206.207031 104.601562 204.863281 C 103.570312 201.902344 103.621094 198.613281 104.765625 195.636719 C 105.949219 192.582031 108.148438 190.183594 110.929688 188.878906 C 112.617188 188.058594 113.851562 186.257812 114.144531 184.152344 C 114.417969 182.027344 113.722656 179.953125 112.304688 178.738281 C 109.976562 176.703125 108.507812 173.816406 108.203125 170.578125 C 107.890625 167.398438 108.707031 164.199219 110.507812 161.636719 C 111.539062 160.128906 113.59375 159.765625 115.085938 160.824219 C 116.574219 161.855469 116.941406 163.910156 115.90625 165.402344 C 115.011719 166.671875 114.597656 168.328125 114.761719 169.941406 C 114.902344 171.472656 115.59375 172.84375 116.613281 173.738281 C 119.683594 176.371094 121.246094 180.714844 120.664062 185.039062 C 120.082031 189.34375 117.429688 193.089844 113.742188 194.832031 C 112.503906 195.414062 111.472656 196.558594 110.910156 198.015625 C 110.347656 199.484375 110.308594 201.191406 110.816406 202.664062 C 111.433594 204.390625 110.527344 206.261719 108.800781 206.859375 C 108.4375 207.011719 108.074219 207.0625 107.710938 207.0625 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 300.585938 143.257812 C 298.914062 143.257812 297.476562 141.988281 297.316406 140.261719 C 297.023438 137.152344 297.878906 133.992188 299.730469 131.359375 C 301.65625 128.683594 304.363281 126.90625 307.382812 126.324219 C 309.210938 125.976562 310.851562 124.523438 311.652344 122.542969 C 312.472656 120.5625 312.304688 118.367188 311.214844 116.839844 C 310.179688 115.347656 310.546875 113.296875 312.050781 112.238281 C 313.558594 111.207031 315.59375 111.585938 316.628906 113.074219 C 318.957031 116.421875 319.390625 120.976562 317.773438 125.007812 C 316.140625 129.046875 312.636719 132.023438 308.632812 132.804688 C 307.289062 133.058594 306 133.910156 305.113281 135.1875 C 304.183594 136.476562 303.734375 138.113281 303.875 139.65625 C 304.039062 141.453125 302.714844 143.070312 300.894531 143.234375 C 300.789062 143.257812 300.695312 143.257812 300.585938 143.257812 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/cosmosan.ch\/en\/kopfschmerzen\/\" target=\"_blank\">\n                                    migraine &amp; headache                                    <\/a><\/h4><div class=\"sc_icons_item_description\" style=\"color:#5D5D5D;\"><span>some wake up with it in the mornings. others get attacked by it in the afternoons or evenings, or upon weather change, and women before their menses: headache, in extreme cases migraine headache. the main difference is...<\/span><\/div><a href=\"https:\/\/cosmosan.ch\/en\/kopfschmerzen\/\" class=\"sc_icons_item_more_link\" target=\"_blank\">\n                        <span class=\"link_text\">read more<\/span><span class=\"link_icon\"><\/span>\n                        <\/a><a href=\"https:\/\/cosmosan.ch\/en\/kopfschmerzen\/\" class=\"sc_icons_item_link\" target=\"_blank\">\n                        <\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_icon sc_icon_type_svg\" style=\"color: #FFFFFF\" ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"500\" viewbox=\"0 0 375 374.999991\" height=\"500\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"b7796256f0\"><path d=\"M 37.5 158 L 299 158 L 299 337.5 L 37.5 337.5 Z M 37.5 158 \" clip-rule=\"nonzero\"><\/path><\/clippath><clippath id=\"c4c108907c\"><path d=\"M 172 37.5 L 337.5 37.5 L 337.5 203 L 172 203 Z M 172 37.5 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><g clip-path=\"url(#b7796256f0)\"><path fill=\"#e10e49\" d=\"M 47.175781 337.5 L 56.855469 337.5 C 57.488281 337.5 58.117188 337.4375 58.742188 337.3125 C 59.363281 337.1875 59.96875 337.003906 60.554688 336.761719 C 61.144531 336.515625 61.699219 336.21875 62.230469 335.867188 C 62.757812 335.511719 63.246094 335.113281 63.695312 334.664062 C 64.144531 334.214844 64.542969 333.722656 64.898438 333.195312 C 65.25 332.667969 65.550781 332.109375 65.792969 331.523438 C 66.035156 330.9375 66.21875 330.332031 66.34375 329.710938 C 66.46875 329.085938 66.53125 328.457031 66.53125 327.824219 L 66.53125 322.984375 L 269.757812 322.984375 L 269.757812 327.824219 C 269.757812 328.457031 269.820312 329.085938 269.945312 329.710938 C 270.070312 330.332031 270.253906 330.9375 270.496094 331.523438 C 270.742188 332.109375 271.039062 332.667969 271.390625 333.195312 C 271.746094 333.722656 272.148438 334.214844 272.597656 334.664062 C 273.046875 335.113281 273.535156 335.511719 274.0625 335.867188 C 274.589844 336.21875 275.148438 336.515625 275.734375 336.761719 C 276.320312 337.003906 276.925781 337.1875 277.546875 337.3125 C 278.171875 337.4375 278.800781 337.5 279.433594 337.5 L 289.113281 337.5 C 289.75 337.5 290.378906 337.4375 291 337.3125 C 291.625 337.1875 292.226562 337.003906 292.816406 336.761719 C 293.402344 336.515625 293.957031 336.21875 294.488281 335.867188 C 295.015625 335.511719 295.503906 335.113281 295.953125 334.664062 C 296.402344 334.214844 296.804688 333.722656 297.15625 333.195312 C 297.507812 332.667969 297.808594 332.109375 298.050781 331.523438 C 298.292969 330.9375 298.476562 330.332031 298.601562 329.710938 C 298.726562 329.085938 298.789062 328.457031 298.789062 327.824219 L 298.789062 279.433594 C 298.789062 278.800781 298.726562 278.171875 298.601562 277.546875 C 298.476562 276.925781 298.292969 276.320312 298.050781 275.734375 C 297.808594 275.148438 297.507812 274.589844 297.15625 274.0625 C 296.804688 273.535156 296.402344 273.046875 295.953125 272.597656 C 295.503906 272.148438 295.015625 271.746094 294.488281 271.390625 C 293.957031 271.039062 293.402344 270.742188 292.816406 270.496094 C 292.226562 270.253906 291.621094 270.070312 291 269.945312 C 290.378906 269.820312 289.75 269.757812 289.113281 269.757812 L 279.433594 269.757812 C 278.800781 269.757812 278.171875 269.820312 277.546875 269.945312 C 276.925781 270.070312 276.320312 270.253906 275.734375 270.496094 C 275.148438 270.742188 274.589844 271.039062 274.0625 271.390625 C 273.535156 271.746094 273.046875 272.148438 272.597656 272.597656 C 272.148438 273.046875 271.746094 273.535156 271.390625 274.0625 C 271.039062 274.589844 270.742188 275.148438 270.496094 275.734375 C 270.253906 276.320312 270.070312 276.925781 269.945312 277.546875 C 269.820312 278.171875 269.757812 278.800781 269.757812 279.433594 L 269.757812 289.113281 L 264.917969 289.113281 L 264.917969 264.917969 C 264.917969 263.808594 264.863281 262.703125 264.753906 261.601562 C 264.644531 260.496094 264.480469 259.402344 264.261719 258.3125 C 264.042969 257.226562 263.773438 256.152344 263.453125 255.089844 C 263.128906 254.03125 262.753906 252.988281 262.332031 251.964844 C 261.90625 250.9375 261.429688 249.9375 260.910156 248.960938 C 260.386719 247.984375 259.816406 247.03125 259.199219 246.109375 C 258.582031 245.1875 257.921875 244.300781 257.21875 243.441406 C 256.515625 242.585938 255.769531 241.765625 254.988281 240.980469 C 254.203125 240.195312 253.382812 239.453125 252.523438 238.75 C 251.667969 238.046875 250.777344 237.386719 249.855469 236.769531 C 248.933594 236.152344 247.984375 235.582031 247.007812 235.058594 C 246.03125 234.535156 245.027344 234.0625 244.003906 233.636719 C 242.980469 233.210938 241.9375 232.839844 240.875 232.515625 C 239.816406 232.191406 238.742188 231.921875 237.652344 231.707031 C 236.566406 231.488281 235.46875 231.324219 234.367188 231.214844 C 233.261719 231.105469 232.15625 231.050781 231.046875 231.046875 L 172.984375 231.046875 C 172.03125 231.050781 171.136719 230.824219 170.296875 230.375 C 169.457031 229.925781 168.773438 229.304688 168.246094 228.511719 C 167.773438 227.789062 167.242188 227.113281 166.652344 226.484375 C 166.0625 225.855469 165.421875 225.277344 164.734375 224.757812 C 164.046875 224.238281 163.320312 223.777344 162.554688 223.382812 C 161.785156 222.984375 160.992188 222.65625 160.171875 222.394531 C 159.347656 222.132812 158.507812 221.945312 157.652344 221.828125 C 156.800781 221.710938 155.941406 221.664062 155.078125 221.695312 C 154.214844 221.722656 153.363281 221.824219 152.515625 222 C 151.671875 222.175781 150.847656 222.421875 150.042969 222.734375 L 143.953125 210.550781 C 143.03125 208.699219 141.890625 207 140.53125 205.445312 C 139.171875 203.890625 137.636719 202.53125 135.925781 201.375 C 134.214844 200.214844 132.386719 199.292969 130.4375 198.605469 C 128.488281 197.921875 126.484375 197.492188 124.425781 197.324219 C 124.882812 196.730469 125.304688 196.113281 125.703125 195.480469 C 126.097656 194.847656 126.464844 194.195312 126.800781 193.527344 C 127.136719 192.859375 127.441406 192.179688 127.714844 191.480469 C 127.988281 190.785156 128.226562 190.078125 128.433594 189.359375 C 128.640625 188.640625 128.816406 187.914062 128.953125 187.179688 C 129.09375 186.445312 129.199219 185.707031 129.269531 184.960938 C 129.339844 184.214844 129.378906 183.472656 129.378906 182.722656 C 129.378906 181.976562 129.347656 181.230469 129.28125 180.484375 C 129.210938 179.738281 129.109375 179 128.972656 178.265625 C 128.839844 177.527344 128.667969 176.800781 128.464844 176.082031 C 128.261719 175.363281 128.023438 174.652344 127.753906 173.957031 C 127.484375 173.257812 127.183594 172.574219 126.851562 171.90625 C 126.515625 171.238281 126.152344 170.585938 125.761719 169.949219 C 125.367188 169.3125 124.945312 168.695312 124.492188 168.097656 C 124.042969 167.503906 123.566406 166.929688 123.0625 166.375 C 122.558594 165.824219 122.027344 165.296875 121.476562 164.792969 C 120.921875 164.289062 120.347656 163.8125 119.75 163.363281 C 119.152344 162.914062 118.535156 162.492188 117.898438 162.101562 C 117.261719 161.707031 116.609375 161.34375 115.9375 161.011719 C 115.269531 160.679688 114.585938 160.382812 113.886719 160.113281 C 113.1875 159.84375 112.480469 159.609375 111.761719 159.40625 C 111.039062 159.203125 110.3125 159.035156 109.578125 158.898438 C 108.84375 158.765625 108.101562 158.664062 107.355469 158.597656 C 106.613281 158.53125 105.867188 158.5 105.117188 158.503906 C 104.371094 158.503906 103.625 158.542969 102.878906 158.617188 C 102.136719 158.6875 101.398438 158.792969 100.664062 158.933594 C 99.929688 159.074219 99.203125 159.25 98.484375 159.457031 C 97.765625 159.667969 97.058594 159.90625 96.363281 160.183594 C 95.667969 160.457031 94.984375 160.761719 94.316406 161.097656 C 93.648438 161.4375 93 161.804688 92.367188 162.199219 C 91.734375 162.597656 91.121094 163.023438 90.527344 163.480469 C 89.933594 163.933594 89.359375 164.414062 88.8125 164.921875 C 88.261719 165.429688 87.738281 165.960938 87.238281 166.519531 C 86.738281 167.074219 86.265625 167.652344 85.820312 168.253906 C 85.375 168.851562 84.957031 169.472656 84.566406 170.109375 C 84.179688 170.75 83.820312 171.40625 83.492188 172.078125 C 83.164062 172.75 82.871094 173.433594 82.605469 174.136719 C 82.339844 174.835938 82.109375 175.542969 81.910156 176.265625 C 81.714844 176.988281 81.550781 177.714844 81.417969 178.453125 C 81.289062 179.1875 81.191406 179.929688 81.132812 180.675781 C 81.070312 181.417969 81.042969 182.164062 81.050781 182.914062 C 81.058594 183.660156 81.097656 184.40625 81.175781 185.152344 C 81.253906 185.894531 81.363281 186.632812 81.507812 187.367188 C 81.65625 188.101562 81.835938 188.824219 82.046875 189.542969 C 82.257812 190.257812 82.503906 190.964844 82.785156 191.660156 C 83.0625 192.351562 83.371094 193.03125 83.710938 193.699219 C 84.054688 194.363281 84.425781 195.011719 84.828125 195.640625 C 85.226562 196.273438 85.660156 196.882812 86.117188 197.476562 C 86.140625 197.507812 86.171875 197.53125 86.199219 197.5625 C 85.554688 197.671875 84.917969 197.816406 84.289062 197.992188 C 83.660156 198.167969 83.042969 198.375 82.433594 198.613281 C 81.824219 198.855469 81.230469 199.125 80.652344 199.421875 C 80.070312 199.722656 79.507812 200.050781 78.960938 200.410156 C 78.414062 200.765625 77.886719 201.148438 77.378906 201.558594 C 76.871094 201.972656 76.386719 202.40625 75.921875 202.867188 C 75.460938 203.328125 75.019531 203.808594 74.605469 204.316406 C 74.191406 204.820312 73.804688 205.347656 73.445312 205.890625 C 73.082031 206.433594 72.75 206.996094 72.449219 207.574219 C 72.144531 208.152344 71.871094 208.746094 71.628906 209.351562 C 71.386719 209.957031 71.175781 210.574219 70.996094 211.203125 C 70.816406 211.832031 70.667969 212.46875 70.550781 213.109375 C 70.4375 213.753906 70.355469 214.398438 70.304688 215.050781 C 70.257812 215.703125 70.242188 216.355469 70.257812 217.007812 C 70.277344 217.660156 70.328125 218.3125 70.410156 218.957031 C 70.492188 219.605469 70.609375 220.25 70.757812 220.882812 L 79.738281 259.792969 L 76.539062 261.472656 C 76.226562 261.636719 75.9375 261.832031 75.667969 262.058594 C 68.984375 267.722656 70.101562 276.601562 78.992188 288.445312 L 79.492188 289.113281 L 66.53125 289.113281 L 66.53125 231.046875 C 66.53125 230.414062 66.46875 229.785156 66.34375 229.160156 C 66.21875 228.539062 66.035156 227.933594 65.792969 227.347656 C 65.550781 226.761719 65.25 226.203125 64.898438 225.675781 C 64.542969 225.144531 64.144531 224.65625 63.695312 224.207031 C 63.246094 223.757812 62.757812 223.359375 62.230469 223.003906 C 61.699219 222.652344 61.144531 222.355469 60.554688 222.109375 C 59.96875 221.867188 59.363281 221.683594 58.742188 221.558594 C 58.117188 221.433594 57.488281 221.371094 56.855469 221.371094 L 47.175781 221.371094 C 46.542969 221.371094 45.914062 221.433594 45.289062 221.558594 C 44.667969 221.683594 44.0625 221.867188 43.476562 222.109375 C 42.890625 222.355469 42.332031 222.652344 41.804688 223.003906 C 41.277344 223.359375 40.785156 223.757812 40.335938 224.207031 C 39.886719 224.65625 39.488281 225.144531 39.132812 225.675781 C 38.78125 226.203125 38.484375 226.761719 38.238281 227.347656 C 37.996094 227.933594 37.8125 228.539062 37.6875 229.160156 C 37.5625 229.785156 37.5 230.414062 37.5 231.046875 L 37.5 327.824219 C 37.5 328.457031 37.5625 329.085938 37.6875 329.710938 C 37.8125 330.332031 37.996094 330.9375 38.238281 331.523438 C 38.484375 332.109375 38.78125 332.667969 39.132812 333.195312 C 39.488281 333.722656 39.886719 334.214844 40.335938 334.664062 C 40.785156 335.113281 41.277344 335.511719 41.804688 335.867188 C 42.332031 336.21875 42.890625 336.515625 43.476562 336.761719 C 44.0625 337.003906 44.667969 337.1875 45.289062 337.3125 C 45.914062 337.4375 46.542969 337.5 47.175781 337.5 Z M 150.910156 233.277344 C 151.222656 233.117188 151.511719 232.921875 151.78125 232.691406 C 152.085938 232.433594 152.417969 232.210938 152.769531 232.019531 C 153.125 231.832031 153.492188 231.679688 153.878906 231.570312 C 154.265625 231.460938 154.65625 231.390625 155.058594 231.359375 C 155.457031 231.332031 155.855469 231.347656 156.253906 231.402344 C 156.648438 231.457031 157.035156 231.554688 157.414062 231.695312 C 157.789062 231.832031 158.148438 232.007812 158.488281 232.21875 C 158.828125 232.433594 159.140625 232.679688 159.425781 232.960938 C 159.714844 233.238281 159.96875 233.546875 160.191406 233.878906 C 160.835938 234.820312 161.574219 235.679688 162.410156 236.453125 L 131.835938 254.292969 L 136.710938 262.644531 L 174.289062 240.726562 L 231.046875 240.726562 C 231.839844 240.726562 232.628906 240.765625 233.417969 240.84375 C 234.207031 240.921875 234.988281 241.039062 235.765625 241.195312 C 236.542969 241.351562 237.308594 241.542969 238.066406 241.773438 C 238.824219 242.003906 239.570312 242.273438 240.300781 242.574219 C 241.035156 242.878906 241.75 243.21875 242.449219 243.589844 C 243.144531 243.964844 243.824219 244.371094 244.484375 244.8125 C 245.140625 245.253906 245.777344 245.722656 246.390625 246.226562 C 247 246.730469 247.585938 247.261719 248.148438 247.820312 C 248.707031 248.378906 249.238281 248.964844 249.742188 249.578125 C 250.246094 250.191406 250.714844 250.828125 251.15625 251.484375 C 251.597656 252.144531 252.003906 252.820312 252.375 253.519531 C 252.75 254.21875 253.089844 254.933594 253.394531 255.664062 C 253.695312 256.398438 253.964844 257.140625 254.195312 257.898438 C 254.425781 258.65625 254.617188 259.425781 254.773438 260.203125 C 254.925781 260.976562 255.042969 261.761719 255.121094 262.550781 C 255.203125 263.335938 255.242188 264.128906 255.242188 264.917969 L 255.242188 289.113281 L 91.585938 289.113281 L 86.734375 282.640625 C 83.882812 278.84375 79.546875 272.25 81.652344 269.71875 Z M 90.84375 180.832031 C 90.957031 179.964844 91.144531 179.113281 91.410156 178.277344 C 91.671875 177.445312 92.011719 176.640625 92.421875 175.867188 C 92.832031 175.09375 93.308594 174.363281 93.851562 173.675781 C 94.390625 172.992188 94.992188 172.359375 95.648438 171.777344 C 96.304688 171.199219 97.007812 170.683594 97.757812 170.234375 C 98.507812 169.78125 99.292969 169.398438 100.109375 169.089844 C 100.929688 168.777344 101.769531 168.542969 102.628906 168.386719 C 103.488281 168.226562 104.355469 168.148438 105.234375 168.144531 C 105.847656 168.144531 106.460938 168.183594 107.074219 168.261719 C 108.019531 168.382812 108.941406 168.59375 109.847656 168.898438 C 110.75 169.199219 111.617188 169.585938 112.445312 170.058594 C 113.273438 170.53125 114.046875 171.082031 114.765625 171.707031 C 115.484375 172.332031 116.136719 173.019531 116.71875 173.773438 C 117.304688 174.527344 117.808594 175.332031 118.234375 176.183594 C 118.65625 177.035156 118.996094 177.921875 119.246094 178.84375 C 119.496094 179.761719 119.65625 180.699219 119.722656 181.648438 C 119.789062 182.597656 119.761719 183.546875 119.644531 184.492188 C 119.523438 185.4375 119.3125 186.363281 119.007812 187.265625 C 118.707031 188.171875 118.320312 189.035156 117.847656 189.863281 C 117.375 190.691406 116.824219 191.464844 116.199219 192.183594 C 115.574219 192.902344 114.886719 193.554688 114.132812 194.136719 C 113.378906 194.722656 112.574219 195.226562 111.722656 195.652344 C 110.867188 196.078125 109.984375 196.414062 109.0625 196.667969 C 108.144531 196.917969 107.207031 197.074219 106.257812 197.140625 C 105.308594 197.210938 104.359375 197.183594 103.414062 197.0625 C 102.46875 196.941406 101.542969 196.730469 100.640625 196.429688 C 99.734375 196.125 98.871094 195.738281 98.042969 195.265625 C 97.214844 194.792969 96.441406 194.242188 95.722656 193.617188 C 95.003906 192.992188 94.351562 192.304688 93.765625 191.550781 C 93.183594 190.796875 92.679688 189.992188 92.253906 189.140625 C 91.828125 188.289062 91.492188 187.402344 91.238281 186.480469 C 90.988281 185.5625 90.832031 184.628906 90.761719 183.675781 C 90.695312 182.726562 90.722656 181.777344 90.84375 180.832031 Z M 82.046875 210.507812 C 82.960938 209.351562 84.082031 208.453125 85.410156 207.8125 C 86.742188 207.171875 88.140625 206.851562 89.617188 206.855469 L 122.3125 206.855469 C 123.660156 206.851562 124.984375 207.03125 126.28125 207.398438 C 127.582031 207.765625 128.804688 208.300781 129.949219 209.011719 C 131.097656 209.71875 132.125 210.574219 133.035156 211.570312 C 133.941406 212.566406 134.695312 213.671875 135.292969 214.878906 L 141.503906 227.292969 L 88.59375 255.132812 L 80.1875 218.710938 C 79.851562 217.273438 79.847656 215.835938 80.175781 214.394531 C 80.5 212.957031 81.125 211.660156 82.046875 210.507812 Z M 47.175781 231.046875 L 56.855469 231.046875 L 56.855469 293.953125 C 56.855469 294.269531 56.886719 294.585938 56.949219 294.894531 C 57.007812 295.207031 57.101562 295.511719 57.222656 295.804688 C 57.34375 296.097656 57.492188 296.375 57.671875 296.640625 C 57.847656 296.90625 58.046875 297.148438 58.273438 297.375 C 58.496094 297.597656 58.742188 297.796875 59.003906 297.976562 C 59.269531 298.152344 59.546875 298.300781 59.839844 298.421875 C 60.136719 298.542969 60.4375 298.636719 60.75 298.699219 C 61.0625 298.757812 61.375 298.789062 61.695312 298.789062 L 274.597656 298.789062 C 274.914062 298.789062 275.230469 298.757812 275.539062 298.699219 C 275.851562 298.636719 276.15625 298.542969 276.449219 298.421875 C 276.742188 298.300781 277.019531 298.152344 277.285156 297.976562 C 277.550781 297.796875 277.792969 297.597656 278.019531 297.375 C 278.242188 297.148438 278.445312 296.90625 278.621094 296.640625 C 278.796875 296.375 278.945312 296.097656 279.066406 295.804688 C 279.1875 295.511719 279.28125 295.207031 279.34375 294.894531 C 279.40625 294.585938 279.4375 294.269531 279.433594 293.953125 L 279.433594 279.433594 L 289.113281 279.433594 L 289.113281 327.824219 L 279.433594 327.824219 L 279.433594 318.144531 C 279.4375 317.828125 279.40625 317.511719 279.34375 317.199219 C 279.28125 316.890625 279.1875 316.585938 279.066406 316.292969 C 278.945312 316 278.796875 315.722656 278.621094 315.457031 C 278.445312 315.191406 278.242188 314.949219 278.019531 314.722656 C 277.792969 314.5 277.550781 314.296875 277.285156 314.121094 C 277.019531 313.945312 276.742188 313.796875 276.449219 313.675781 C 276.15625 313.554688 275.851562 313.460938 275.539062 313.398438 C 275.230469 313.335938 274.914062 313.304688 274.597656 313.304688 L 61.695312 313.304688 C 61.375 313.304688 61.0625 313.335938 60.75 313.398438 C 60.4375 313.460938 60.136719 313.554688 59.839844 313.675781 C 59.546875 313.796875 59.269531 313.945312 59.003906 314.121094 C 58.742188 314.296875 58.496094 314.5 58.273438 314.722656 C 58.046875 314.949219 57.847656 315.191406 57.671875 315.457031 C 57.492188 315.722656 57.34375 316 57.222656 316.292969 C 57.101562 316.585938 57.007812 316.890625 56.949219 317.199219 C 56.886719 317.511719 56.855469 317.828125 56.855469 318.144531 L 56.855469 327.824219 L 47.175781 327.824219 Z M 47.175781 231.046875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#e10e49\" d=\"M 75.835938 54.289062 C 75.585938 53.886719 75.28125 53.53125 74.925781 53.21875 C 74.570312 52.90625 74.175781 52.652344 73.746094 52.457031 C 73.3125 52.261719 72.863281 52.128906 72.394531 52.0625 C 71.925781 52 71.457031 52 70.992188 52.074219 C 70.300781 52.179688 69.617188 52.308594 68.9375 52.457031 C 68.253906 52.609375 67.582031 52.777344 66.910156 52.96875 C 66.238281 53.160156 65.578125 53.371094 64.917969 53.605469 C 64.261719 53.835938 63.613281 54.089844 62.972656 54.359375 C 62.328125 54.632812 61.695312 54.925781 61.074219 55.238281 C 60.449219 55.546875 59.835938 55.878906 59.234375 56.226562 C 58.628906 56.578125 58.039062 56.945312 57.457031 57.328125 C 56.878906 57.714844 56.308594 58.121094 55.753906 58.539062 C 55.199219 58.960938 54.65625 59.398438 54.128906 59.851562 C 53.601562 60.308594 53.085938 60.777344 52.585938 61.261719 C 52.085938 61.75 51.601562 62.25 51.132812 62.765625 C 50.664062 63.28125 50.214844 63.8125 49.777344 64.355469 C 49.34375 64.902344 48.921875 65.457031 48.523438 66.027344 C 48.121094 66.597656 47.738281 67.179688 47.371094 67.773438 C 47.007812 68.367188 46.660156 68.96875 46.332031 69.585938 C 46.003906 70.199219 45.695312 70.824219 45.40625 71.457031 C 45.117188 72.089844 44.84375 72.734375 44.59375 73.382812 C 44.347656 74.035156 44.117188 74.691406 43.90625 75.355469 C 43.699219 76.023438 43.507812 76.691406 43.339844 77.367188 C 43.171875 78.046875 43.027344 78.726562 42.898438 79.410156 C 42.773438 80.097656 42.671875 80.785156 42.585938 81.476562 C 42.503906 82.171875 42.441406 82.863281 42.402344 83.558594 C 42.359375 84.253906 42.339844 84.953125 42.34375 85.648438 C 42.347656 86.347656 42.371094 87.042969 42.417969 87.738281 C 42.460938 88.433594 42.527344 89.125 42.617188 89.816406 C 42.707031 90.507812 42.816406 91.195312 42.945312 91.882812 C 43.078125 92.566406 43.230469 93.246094 43.402344 93.921875 C 43.574219 94.597656 43.769531 95.265625 43.980469 95.929688 C 44.195312 96.59375 44.429688 97.246094 44.683594 97.898438 C 44.941406 98.546875 45.214844 99.1875 45.507812 99.816406 C 45.804688 100.449219 46.117188 101.070312 46.449219 101.683594 C 46.78125 102.296875 47.132812 102.898438 47.503906 103.488281 C 47.871094 104.078125 48.261719 104.65625 48.664062 105.226562 C 49.070312 105.792969 49.492188 106.34375 49.933594 106.886719 C 50.375 107.425781 50.828125 107.953125 51.300781 108.464844 C 51.773438 108.980469 52.261719 109.476562 52.765625 109.957031 C 53.265625 110.441406 53.785156 110.90625 54.316406 111.359375 C 54.847656 111.808594 55.394531 112.242188 55.953125 112.660156 C 56.511719 113.074219 57.082031 113.476562 57.664062 113.855469 C 58.25 114.238281 58.84375 114.601562 59.449219 114.945312 C 60.054688 115.289062 60.667969 115.617188 61.296875 115.921875 C 61.921875 116.230469 62.554688 116.515625 63.199219 116.785156 C 63.84375 117.050781 64.492188 117.300781 65.152344 117.527344 C 65.8125 117.753906 66.476562 117.960938 67.148438 118.148438 C 67.820312 118.335938 68.496094 118.5 69.179688 118.644531 C 69.859375 118.789062 70.546875 118.914062 71.234375 119.015625 C 71.925781 119.117188 72.617188 119.199219 73.3125 119.257812 C 74.003906 119.316406 74.699219 119.355469 75.398438 119.371094 C 76.09375 119.386719 76.792969 119.382812 77.488281 119.355469 C 78.183594 119.328125 78.878906 119.28125 79.574219 119.210938 C 80.265625 119.140625 80.957031 119.050781 81.644531 118.9375 C 82.332031 118.828125 83.015625 118.695312 83.695312 118.539062 C 84.375 118.386719 85.050781 118.210938 85.71875 118.015625 C 86.386719 117.816406 87.050781 117.601562 87.703125 117.363281 C 88.359375 117.128906 89.007812 116.871094 89.648438 116.59375 C 90.289062 116.316406 90.917969 116.019531 91.539062 115.707031 C 92.160156 115.390625 92.769531 115.054688 93.371094 114.703125 C 93.972656 114.347656 94.5625 113.976562 95.140625 113.585938 C 95.71875 113.195312 96.28125 112.789062 96.835938 112.363281 C 97.386719 111.9375 97.925781 111.496094 98.453125 111.039062 C 98.976562 110.582031 99.488281 110.109375 99.984375 109.617188 C 100.480469 109.128906 100.960938 108.625 101.425781 108.105469 C 101.890625 107.585938 102.335938 107.050781 102.769531 106.503906 C 103.203125 105.957031 103.617188 105.398438 104.011719 104.824219 C 104.285156 104.4375 104.492188 104.019531 104.640625 103.566406 C 104.785156 103.117188 104.867188 102.65625 104.878906 102.183594 C 104.890625 101.707031 104.832031 101.242188 104.707031 100.785156 C 104.582031 100.328125 104.394531 99.902344 104.144531 99.5 C 103.894531 99.097656 103.589844 98.738281 103.234375 98.425781 C 102.878906 98.113281 102.484375 97.859375 102.054688 97.664062 C 101.625 97.464844 101.175781 97.335938 100.707031 97.269531 C 100.238281 97.203125 99.769531 97.207031 99.300781 97.28125 C 98.136719 97.464844 96.964844 97.5625 95.789062 97.574219 C 94.609375 97.589844 93.4375 97.515625 92.273438 97.355469 C 91.105469 97.199219 89.957031 96.957031 88.824219 96.628906 C 87.695312 96.300781 86.589844 95.894531 85.519531 95.40625 C 84.449219 94.917969 83.417969 94.355469 82.429688 93.71875 C 81.4375 93.078125 80.5 92.371094 79.613281 91.597656 C 78.730469 90.820312 77.902344 89.984375 77.140625 89.089844 C 76.375 88.191406 75.683594 87.246094 75.054688 86.246094 C 74.429688 85.25 73.882812 84.210938 73.410156 83.132812 C 72.933594 82.054688 72.542969 80.949219 72.230469 79.8125 C 71.917969 78.675781 71.691406 77.523438 71.550781 76.355469 C 71.40625 75.1875 71.347656 74.011719 71.378906 72.835938 C 71.40625 71.660156 71.519531 70.488281 71.71875 69.328125 C 71.921875 68.167969 72.203125 67.027344 72.570312 65.910156 C 72.9375 64.789062 73.382812 63.703125 73.90625 62.648438 C 74.433594 61.597656 75.03125 60.585938 75.703125 59.621094 C 75.972656 59.230469 76.183594 58.808594 76.332031 58.359375 C 76.476562 57.910156 76.558594 57.449219 76.570312 56.972656 C 76.582031 56.5 76.523438 56.035156 76.398438 55.578125 C 76.273438 55.121094 76.085938 54.691406 75.835938 54.289062 Z M 88.238281 106.484375 C 87.566406 106.871094 86.878906 107.222656 86.175781 107.539062 C 85.46875 107.859375 84.75 108.140625 84.019531 108.390625 C 83.289062 108.640625 82.546875 108.855469 81.792969 109.035156 C 81.039062 109.210938 80.28125 109.355469 79.515625 109.460938 C 78.75 109.566406 77.980469 109.632812 77.207031 109.667969 C 76.433594 109.699219 75.664062 109.695312 74.890625 109.652344 C 74.117188 109.609375 73.351562 109.53125 72.585938 109.414062 C 71.820312 109.296875 71.0625 109.144531 70.3125 108.957031 C 69.5625 108.769531 68.824219 108.546875 68.09375 108.285156 C 67.367188 108.027344 66.652344 107.734375 65.953125 107.40625 C 65.25 107.078125 64.570312 106.71875 63.902344 106.324219 C 63.238281 105.929688 62.589844 105.507812 61.964844 105.050781 C 61.339844 104.59375 60.738281 104.109375 60.160156 103.597656 C 59.582031 103.085938 59.027344 102.546875 58.503906 101.980469 C 57.976562 101.414062 57.476562 100.824219 57.007812 100.210938 C 56.535156 99.597656 56.097656 98.960938 55.6875 98.304688 C 55.277344 97.648438 54.898438 96.976562 54.554688 96.285156 C 54.210938 95.589844 53.898438 94.882812 53.621094 94.160156 C 53.34375 93.441406 53.101562 92.707031 52.894531 91.960938 C 52.691406 91.214844 52.519531 90.460938 52.382812 89.703125 C 52.25 88.941406 52.152344 88.171875 52.089844 87.402344 C 52.03125 86.632812 52.007812 85.859375 52.019531 85.085938 C 52.03125 84.3125 52.082031 83.542969 52.167969 82.773438 C 52.257812 82.003906 52.378906 81.242188 52.539062 80.488281 C 52.699219 79.730469 52.894531 78.984375 53.128906 78.246094 C 53.359375 77.507812 53.625 76.78125 53.925781 76.070312 C 54.226562 75.359375 54.5625 74.660156 54.929688 73.980469 C 55.300781 73.300781 55.699219 72.640625 56.128906 72 C 56.5625 71.355469 57.023438 70.738281 57.511719 70.140625 C 58.003906 69.542969 58.523438 68.96875 59.066406 68.421875 C 59.613281 67.875 60.183594 67.351562 60.78125 66.859375 C 61.375 66.367188 61.992188 65.902344 62.632812 65.46875 C 62.371094 66.558594 62.164062 67.660156 62.011719 68.773438 C 61.855469 69.886719 61.757812 71.003906 61.71875 72.125 C 61.675781 73.246094 61.6875 74.367188 61.757812 75.488281 C 61.828125 76.609375 61.953125 77.722656 62.132812 78.828125 C 62.3125 79.9375 62.546875 81.035156 62.835938 82.117188 C 63.125 83.203125 63.464844 84.269531 63.859375 85.320312 C 64.253906 86.371094 64.703125 87.402344 65.199219 88.40625 C 65.695312 89.414062 66.242188 90.394531 66.835938 91.34375 C 67.429688 92.296875 68.070312 93.21875 68.757812 94.105469 C 69.441406 94.996094 70.171875 95.847656 70.941406 96.664062 C 71.710938 97.480469 72.519531 98.257812 73.367188 98.992188 C 74.214844 99.726562 75.097656 100.417969 76.015625 101.066406 C 76.929688 101.714844 77.875 102.316406 78.851562 102.871094 C 79.828125 103.425781 80.828125 103.929688 81.855469 104.386719 C 82.882812 104.839844 83.929688 105.242188 84.996094 105.59375 C 86.0625 105.945312 87.140625 106.242188 88.238281 106.484375 Z M 88.238281 106.484375 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 255.242188 90.726562 C 229.175781 90.726562 208.78125 115.660156 207.925781 116.71875 C 207.578125 117.148438 207.3125 117.625 207.128906 118.148438 C 206.945312 118.667969 206.855469 119.207031 206.855469 119.757812 C 206.855469 120.3125 206.945312 120.847656 207.128906 121.367188 C 207.3125 121.890625 207.578125 122.367188 207.925781 122.796875 C 208.78125 123.855469 229.175781 148.789062 255.242188 148.789062 C 281.308594 148.789062 301.703125 123.855469 302.558594 122.796875 C 302.90625 122.367188 303.171875 121.890625 303.355469 121.367188 C 303.539062 120.847656 303.628906 120.3125 303.628906 119.757812 C 303.628906 119.207031 303.539062 118.667969 303.355469 118.148438 C 303.171875 117.625 302.90625 117.148438 302.558594 116.71875 C 301.703125 115.660156 281.308594 90.726562 255.242188 90.726562 Z M 235.128906 133.167969 C 228.859375 129.488281 223.21875 125.019531 218.203125 119.757812 C 223.21875 114.496094 228.859375 110.027344 235.128906 106.347656 C 234.46875 107.332031 233.882812 108.363281 233.371094 109.4375 C 232.863281 110.507812 232.4375 111.613281 232.089844 112.75 C 231.746094 113.886719 231.484375 115.039062 231.308594 116.214844 C 231.136719 117.390625 231.046875 118.570312 231.046875 119.757812 C 231.046875 120.945312 231.136719 122.125 231.308594 123.300781 C 231.484375 124.476562 231.746094 125.628906 232.089844 126.765625 C 232.4375 127.902344 232.863281 129.007812 233.371094 130.082031 C 233.882812 131.152344 234.46875 132.183594 235.128906 133.167969 Z M 255.242188 134.273438 C 254.289062 134.273438 253.34375 134.179688 252.410156 133.996094 C 251.476562 133.808594 250.566406 133.535156 249.6875 133.167969 C 248.804688 132.804688 247.96875 132.355469 247.175781 131.828125 C 246.382812 131.296875 245.652344 130.695312 244.976562 130.023438 C 244.304688 129.347656 243.703125 128.617188 243.171875 127.824219 C 242.644531 127.03125 242.195312 126.195312 241.832031 125.3125 C 241.464844 124.433594 241.191406 123.523438 241.003906 122.589844 C 240.820312 121.65625 240.726562 120.710938 240.726562 119.757812 C 240.726562 118.804688 240.820312 117.859375 241.003906 116.925781 C 241.191406 115.992188 241.464844 115.082031 241.832031 114.203125 C 242.195312 113.324219 242.644531 112.484375 243.171875 111.691406 C 243.703125 110.902344 244.304688 110.167969 244.976562 109.492188 C 245.652344 108.820312 246.382812 108.21875 247.175781 107.6875 C 247.96875 107.160156 248.804688 106.710938 249.6875 106.347656 C 250.566406 105.980469 251.476562 105.707031 252.410156 105.519531 C 253.34375 105.335938 254.289062 105.242188 255.242188 105.242188 C 256.195312 105.242188 257.140625 105.335938 258.074219 105.519531 C 259.007812 105.707031 259.917969 105.980469 260.796875 106.347656 C 261.675781 106.710938 262.515625 107.160156 263.304688 107.6875 C 264.097656 108.21875 264.832031 108.820312 265.507812 109.492188 C 266.179688 110.167969 266.78125 110.902344 267.3125 111.691406 C 267.839844 112.484375 268.289062 113.324219 268.652344 114.203125 C 269.019531 115.082031 269.292969 115.992188 269.480469 116.925781 C 269.664062 117.859375 269.757812 118.804688 269.757812 119.757812 C 269.757812 120.710938 269.664062 121.65625 269.476562 122.589844 C 269.289062 123.523438 269.015625 124.429688 268.648438 125.3125 C 268.285156 126.191406 267.835938 127.027344 267.308594 127.820312 C 266.777344 128.609375 266.175781 129.34375 265.5 130.019531 C 264.828125 130.691406 264.09375 131.292969 263.304688 131.824219 C 262.511719 132.351562 261.675781 132.800781 260.792969 133.164062 C 259.914062 133.53125 259.007812 133.804688 258.074219 133.992188 C 257.136719 134.179688 256.195312 134.273438 255.242188 134.273438 Z M 275.355469 133.167969 C 276.015625 132.183594 276.601562 131.152344 277.109375 130.082031 C 277.621094 129.007812 278.046875 127.902344 278.394531 126.765625 C 278.738281 125.628906 279 124.476562 279.171875 123.300781 C 279.347656 122.125 279.433594 120.945312 279.433594 119.757812 C 279.433594 118.570312 279.347656 117.390625 279.171875 116.214844 C 279 115.039062 278.738281 113.886719 278.394531 112.75 C 278.046875 111.613281 277.621094 110.507812 277.109375 109.4375 C 276.601562 108.363281 276.015625 107.332031 275.355469 106.347656 C 281.625 110.027344 287.265625 114.496094 292.277344 119.757812 C 287.265625 125.019531 281.625 129.488281 275.355469 133.167969 Z M 275.355469 133.167969 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><g clip-path=\"url(#c4c108907c)\"><path fill=\"#e10e49\" d=\"M 255.242188 37.5 C 253.894531 37.5 252.550781 37.53125 251.207031 37.597656 C 249.859375 37.664062 248.519531 37.765625 247.179688 37.894531 C 245.839844 38.027344 244.503906 38.191406 243.171875 38.390625 C 241.839844 38.585938 240.515625 38.816406 239.195312 39.082031 C 237.875 39.34375 236.5625 39.636719 235.253906 39.964844 C 233.949219 40.292969 232.652344 40.652344 231.363281 41.042969 C 230.074219 41.433594 228.796875 41.855469 227.53125 42.308594 C 226.261719 42.761719 225.007812 43.246094 223.761719 43.761719 C 222.519531 44.277344 221.289062 44.820312 220.070312 45.398438 C 218.855469 45.972656 217.652344 46.578125 216.464844 47.214844 C 215.277344 47.847656 214.109375 48.511719 212.953125 49.203125 C 211.796875 49.894531 210.660156 50.613281 209.542969 51.363281 C 208.421875 52.109375 207.320312 52.886719 206.242188 53.6875 C 205.160156 54.488281 204.097656 55.316406 203.058594 56.171875 C 202.015625 57.027344 201 57.90625 200 58.808594 C 199.003906 59.714844 198.027344 60.640625 197.078125 61.59375 C 196.125 62.542969 195.195312 63.519531 194.292969 64.515625 C 193.386719 65.515625 192.507812 66.535156 191.65625 67.574219 C 190.800781 68.613281 189.972656 69.675781 189.171875 70.757812 C 188.371094 71.839844 187.59375 72.9375 186.847656 74.058594 C 186.097656 75.175781 185.378906 76.3125 184.6875 77.46875 C 183.996094 78.625 183.332031 79.792969 182.695312 80.980469 C 182.0625 82.167969 181.457031 83.371094 180.882812 84.589844 C 180.304688 85.804688 179.761719 87.035156 179.246094 88.277344 C 178.730469 89.523438 178.246094 90.777344 177.792969 92.046875 C 177.339844 93.3125 176.917969 94.589844 176.527344 95.878906 C 176.136719 97.167969 175.777344 98.464844 175.449219 99.769531 C 175.121094 101.078125 174.828125 102.390625 174.5625 103.710938 C 174.300781 105.03125 174.070312 106.355469 173.875 107.6875 C 173.675781 109.019531 173.511719 110.355469 173.378906 111.695312 C 173.246094 113.035156 173.148438 114.378906 173.082031 115.722656 C 173.015625 117.066406 172.984375 118.410156 172.984375 119.757812 C 172.984375 121.105469 173.015625 122.449219 173.082031 123.792969 C 173.148438 125.140625 173.246094 126.480469 173.378906 127.820312 C 173.511719 129.160156 173.675781 130.496094 173.875 131.828125 C 174.070312 133.160156 174.300781 134.484375 174.5625 135.804688 C 174.828125 137.125 175.121094 138.4375 175.449219 139.746094 C 175.777344 141.050781 176.136719 142.347656 176.527344 143.636719 C 176.917969 144.925781 177.339844 146.203125 177.792969 147.46875 C 178.246094 148.738281 178.730469 149.992188 179.246094 151.238281 C 179.761719 152.480469 180.304688 153.710938 180.882812 154.929688 C 181.457031 156.144531 182.0625 157.347656 182.695312 158.535156 C 183.332031 159.722656 183.996094 160.890625 184.6875 162.046875 C 185.378906 163.203125 186.097656 164.339844 186.847656 165.457031 C 187.59375 166.578125 188.371094 167.679688 189.171875 168.757812 C 189.972656 169.839844 190.800781 170.902344 191.65625 171.941406 C 192.507812 172.984375 193.386719 174 194.292969 175 C 195.195312 175.996094 196.125 176.972656 197.078125 177.921875 C 198.027344 178.875 199.003906 179.804688 200 180.707031 C 201 181.609375 202.015625 182.492188 203.058594 183.34375 C 204.097656 184.199219 205.160156 185.027344 206.242188 185.828125 C 207.320312 186.628906 208.421875 187.40625 209.542969 188.152344 C 210.660156 188.902344 211.796875 189.621094 212.953125 190.3125 C 214.109375 191.003906 215.277344 191.667969 216.464844 192.304688 C 217.652344 192.9375 218.855469 193.542969 220.070312 194.117188 C 221.289062 194.695312 222.519531 195.238281 223.761719 195.753906 C 225.007812 196.269531 226.261719 196.753906 227.53125 197.207031 C 228.796875 197.660156 230.074219 198.082031 231.363281 198.472656 C 232.652344 198.863281 233.949219 199.222656 235.253906 199.550781 C 236.5625 199.878906 237.875 200.171875 239.195312 200.433594 C 240.515625 200.699219 241.839844 200.929688 243.171875 201.125 C 244.503906 201.324219 245.839844 201.488281 247.179688 201.621094 C 248.519531 201.753906 249.859375 201.851562 251.207031 201.917969 C 252.550781 201.984375 253.894531 202.015625 255.242188 202.015625 C 256.589844 202.015625 257.933594 201.984375 259.277344 201.917969 C 260.621094 201.851562 261.964844 201.753906 263.304688 201.621094 C 264.644531 201.488281 265.980469 201.324219 267.3125 201.125 C 268.644531 200.929688 269.96875 200.699219 271.289062 200.433594 C 272.609375 200.171875 273.921875 199.878906 275.230469 199.550781 C 276.535156 199.222656 277.832031 198.863281 279.121094 198.472656 C 280.410156 198.082031 281.6875 197.660156 282.953125 197.207031 C 284.222656 196.753906 285.476562 196.269531 286.71875 195.753906 C 287.964844 195.238281 289.195312 194.695312 290.410156 194.117188 C 291.628906 193.542969 292.832031 192.9375 294.019531 192.304688 C 295.207031 191.667969 296.375 191.003906 297.53125 190.3125 C 298.6875 189.621094 299.824219 188.902344 300.941406 188.152344 C 302.0625 187.40625 303.160156 186.628906 304.242188 185.828125 C 305.324219 185.027344 306.386719 184.199219 307.425781 183.34375 C 308.464844 182.492188 309.484375 181.609375 310.484375 180.707031 C 311.480469 179.804688 312.457031 178.875 313.40625 177.921875 C 314.359375 176.972656 315.285156 175.996094 316.191406 175 C 317.09375 174 317.972656 172.984375 318.828125 171.941406 C 319.683594 170.902344 320.511719 169.839844 321.3125 168.757812 C 322.113281 167.679688 322.890625 166.578125 323.636719 165.457031 C 324.386719 164.339844 325.105469 163.203125 325.796875 162.046875 C 326.488281 160.890625 327.152344 159.722656 327.785156 158.535156 C 328.421875 157.347656 329.027344 156.144531 329.601562 154.929688 C 330.179688 153.710938 330.722656 152.480469 331.238281 151.238281 C 331.753906 149.992188 332.238281 148.738281 332.691406 147.46875 C 333.144531 146.203125 333.566406 144.925781 333.957031 143.636719 C 334.347656 142.347656 334.707031 141.050781 335.035156 139.746094 C 335.363281 138.4375 335.65625 137.125 335.917969 135.804688 C 336.183594 134.484375 336.410156 133.160156 336.609375 131.828125 C 336.808594 130.496094 336.972656 129.160156 337.105469 127.820312 C 337.234375 126.480469 337.335938 125.140625 337.402344 123.792969 C 337.46875 122.449219 337.5 121.105469 337.5 119.757812 C 337.5 118.414062 337.464844 117.066406 337.398438 115.722656 C 337.328125 114.378906 337.230469 113.039062 337.09375 111.699219 C 336.960938 110.359375 336.796875 109.023438 336.597656 107.691406 C 336.398438 106.363281 336.167969 105.035156 335.902344 103.714844 C 335.640625 102.398438 335.34375 101.085938 335.015625 99.777344 C 334.6875 98.472656 334.328125 97.175781 333.9375 95.890625 C 333.546875 94.601562 333.121094 93.324219 332.667969 92.058594 C 332.214844 90.792969 331.730469 89.535156 331.214844 88.292969 C 330.699219 87.050781 330.152344 85.820312 329.578125 84.605469 C 329 83.386719 328.394531 82.1875 327.761719 81 C 327.125 79.8125 326.460938 78.644531 325.769531 77.488281 C 325.078125 76.335938 324.355469 75.199219 323.609375 74.078125 C 322.859375 72.960938 322.085938 71.859375 321.285156 70.78125 C 320.480469 69.699219 319.652344 68.640625 318.800781 67.597656 C 317.945312 66.558594 317.066406 65.539062 316.164062 64.542969 C 315.257812 63.546875 314.332031 62.570312 313.378906 61.621094 C 312.429688 60.667969 311.453125 59.742188 310.457031 58.835938 C 309.460938 57.933594 308.441406 57.054688 307.402344 56.199219 C 306.359375 55.347656 305.300781 54.519531 304.21875 53.714844 C 303.140625 52.914062 302.039062 52.140625 300.921875 51.390625 C 299.800781 50.644531 298.664062 49.921875 297.511719 49.230469 C 296.355469 48.539062 295.1875 47.875 294 47.238281 C 292.8125 46.605469 291.613281 46 290.394531 45.421875 C 289.179688 44.847656 287.949219 44.300781 286.707031 43.785156 C 285.464844 43.269531 284.207031 42.785156 282.941406 42.332031 C 281.675781 41.878906 280.398438 41.453125 279.109375 41.0625 C 277.824219 40.671875 276.527344 40.3125 275.21875 39.984375 C 273.914062 39.65625 272.601562 39.359375 271.285156 39.097656 C 269.964844 38.832031 268.636719 38.601562 267.308594 38.402344 C 265.976562 38.203125 264.640625 38.039062 263.300781 37.90625 C 261.960938 37.769531 260.621094 37.671875 259.277344 37.601562 C 257.933594 37.535156 256.585938 37.5 255.242188 37.5 Z M 255.242188 192.339844 C 254.054688 192.339844 252.867188 192.308594 251.679688 192.25 C 250.496094 192.191406 249.308594 192.105469 248.128906 191.988281 C 246.945312 191.871094 245.765625 191.726562 244.59375 191.554688 C 243.417969 191.378906 242.246094 191.175781 241.082031 190.945312 C 239.917969 190.710938 238.757812 190.453125 237.605469 190.164062 C 236.453125 189.875 235.308594 189.558594 234.171875 189.214844 C 233.035156 188.867188 231.910156 188.496094 230.789062 188.097656 C 229.671875 187.695312 228.5625 187.269531 227.464844 186.8125 C 226.367188 186.359375 225.285156 185.878906 224.210938 185.371094 C 223.136719 184.863281 222.074219 184.328125 221.027344 183.769531 C 219.980469 183.207031 218.945312 182.625 217.929688 182.011719 C 216.910156 181.402344 215.90625 180.765625 214.917969 180.105469 C 213.929688 179.445312 212.960938 178.761719 212.003906 178.054688 C 211.050781 177.347656 210.117188 176.617188 209.195312 175.863281 C 208.277344 175.109375 207.378906 174.335938 206.5 173.535156 C 205.621094 172.738281 204.757812 171.921875 203.917969 171.082031 C 203.078125 170.242188 202.261719 169.378906 201.464844 168.5 C 200.664062 167.621094 199.890625 166.722656 199.136719 165.800781 C 198.382812 164.882812 197.652344 163.949219 196.945312 162.996094 C 196.238281 162.039062 195.554688 161.070312 194.894531 160.082031 C 194.234375 159.09375 193.597656 158.089844 192.988281 157.070312 C 192.375 156.054688 191.792969 155.019531 191.230469 153.972656 C 190.671875 152.925781 190.136719 151.863281 189.628906 150.789062 C 189.121094 149.714844 188.640625 148.632812 188.1875 147.535156 C 187.730469 146.4375 187.304688 145.328125 186.902344 144.210938 C 186.503906 143.089844 186.132812 141.964844 185.785156 140.828125 C 185.441406 139.691406 185.125 138.546875 184.835938 137.394531 C 184.546875 136.242188 184.289062 135.082031 184.054688 133.917969 C 183.824219 132.753906 183.621094 131.582031 183.445312 130.40625 C 183.273438 129.234375 183.128906 128.054688 183.011719 126.871094 C 182.894531 125.691406 182.808594 124.503906 182.75 123.320312 C 182.691406 122.132812 182.660156 120.945312 182.660156 119.757812 C 182.660156 118.570312 182.691406 117.382812 182.75 116.195312 C 182.808594 115.011719 182.894531 113.824219 183.011719 112.644531 C 183.128906 111.460938 183.273438 110.285156 183.445312 109.109375 C 183.621094 107.933594 183.824219 106.761719 184.054688 105.597656 C 184.289062 104.433594 184.546875 103.273438 184.835938 102.121094 C 185.125 100.96875 185.441406 99.824219 185.785156 98.6875 C 186.132812 97.550781 186.503906 96.425781 186.902344 95.304688 C 187.304688 94.1875 187.730469 93.078125 188.1875 91.984375 C 188.640625 90.886719 189.121094 89.800781 189.628906 88.726562 C 190.136719 87.652344 190.671875 86.589844 191.230469 85.542969 C 191.792969 84.496094 192.375 83.464844 192.988281 82.445312 C 193.597656 81.425781 194.234375 80.421875 194.894531 79.433594 C 195.554688 78.445312 196.238281 77.476562 196.945312 76.523438 C 197.652344 75.566406 198.382812 74.632812 199.136719 73.714844 C 199.890625 72.796875 200.664062 71.894531 201.464844 71.015625 C 202.261719 70.136719 203.078125 69.277344 203.917969 68.4375 C 204.757812 67.597656 205.621094 66.777344 206.5 65.980469 C 207.378906 65.183594 208.277344 64.40625 209.195312 63.652344 C 210.117188 62.898438 211.050781 62.167969 212.003906 61.460938 C 212.960938 60.753906 213.929688 60.070312 214.917969 59.410156 C 215.90625 58.75 216.910156 58.113281 217.929688 57.503906 C 218.945312 56.894531 219.980469 56.308594 221.027344 55.746094 C 222.074219 55.1875 223.136719 54.652344 224.210938 54.144531 C 225.285156 53.636719 226.367188 53.15625 227.464844 52.703125 C 228.5625 52.246094 229.671875 51.820312 230.789062 51.421875 C 231.910156 51.019531 233.035156 50.648438 234.171875 50.300781 C 235.308594 49.957031 236.453125 49.640625 237.605469 49.351562 C 238.757812 49.0625 239.917969 48.804688 241.082031 48.570312 C 242.246094 48.339844 243.417969 48.136719 244.59375 47.964844 C 245.765625 47.789062 246.945312 47.644531 248.128906 47.527344 C 249.308594 47.410156 250.496094 47.324219 251.679688 47.265625 C 252.867188 47.207031 254.054688 47.175781 255.242188 47.175781 C 256.429688 47.175781 257.617188 47.207031 258.804688 47.265625 C 259.988281 47.324219 261.175781 47.410156 262.355469 47.527344 C 263.539062 47.644531 264.714844 47.789062 265.890625 47.964844 C 267.066406 48.136719 268.238281 48.339844 269.402344 48.570312 C 270.566406 48.804688 271.726562 49.0625 272.878906 49.351562 C 274.03125 49.640625 275.175781 49.957031 276.3125 50.300781 C 277.449219 50.648438 278.574219 51.019531 279.695312 51.421875 C 280.8125 51.820312 281.917969 52.246094 283.015625 52.703125 C 284.113281 53.15625 285.199219 53.636719 286.273438 54.144531 C 287.347656 54.652344 288.410156 55.1875 289.457031 55.746094 C 290.503906 56.308594 291.535156 56.894531 292.554688 57.503906 C 293.574219 58.113281 294.578125 58.75 295.566406 59.410156 C 296.554688 60.070312 297.523438 60.753906 298.476562 61.460938 C 299.433594 62.167969 300.367188 62.898438 301.285156 63.652344 C 302.203125 64.40625 303.105469 65.183594 303.984375 65.980469 C 304.863281 66.777344 305.722656 67.597656 306.5625 68.4375 C 307.402344 69.277344 308.222656 70.136719 309.019531 71.015625 C 309.816406 71.894531 310.59375 72.796875 311.347656 73.714844 C 312.101562 74.632812 312.832031 75.566406 313.539062 76.523438 C 314.246094 77.476562 314.929688 78.445312 315.589844 79.433594 C 316.25 80.421875 316.886719 81.425781 317.496094 82.445312 C 318.105469 83.464844 318.691406 84.496094 319.253906 85.542969 C 319.8125 86.589844 320.347656 87.652344 320.855469 88.726562 C 321.363281 89.800781 321.84375 90.886719 322.296875 91.984375 C 322.753906 93.078125 323.179688 94.1875 323.578125 95.304688 C 323.980469 96.425781 324.351562 97.550781 324.699219 98.6875 C 325.042969 99.824219 325.359375 100.96875 325.648438 102.121094 C 325.9375 103.273438 326.195312 104.433594 326.429688 105.597656 C 326.660156 106.761719 326.863281 107.933594 327.035156 109.109375 C 327.210938 110.285156 327.355469 111.460938 327.472656 112.644531 C 327.589844 113.824219 327.675781 115.011719 327.734375 116.195312 C 327.792969 117.382812 327.824219 118.570312 327.824219 119.757812 C 327.820312 120.945312 327.789062 122.132812 327.730469 123.316406 C 327.671875 124.503906 327.582031 125.6875 327.464844 126.871094 C 327.347656 128.050781 327.203125 129.230469 327.027344 130.402344 C 326.851562 131.578125 326.648438 132.746094 326.414062 133.914062 C 326.183594 135.078125 325.921875 136.234375 325.632812 137.386719 C 325.34375 138.539062 325.023438 139.683594 324.679688 140.816406 C 324.332031 141.953125 323.960938 143.082031 323.558594 144.199219 C 323.160156 145.316406 322.730469 146.425781 322.277344 147.519531 C 321.820312 148.617188 321.339844 149.703125 320.832031 150.777344 C 320.324219 151.847656 319.789062 152.910156 319.230469 153.957031 C 318.667969 155.003906 318.082031 156.035156 317.472656 157.054688 C 316.859375 158.074219 316.226562 159.074219 315.566406 160.0625 C 314.90625 161.050781 314.222656 162.019531 313.515625 162.972656 C 312.808594 163.925781 312.078125 164.863281 311.324219 165.78125 C 310.570312 166.699219 309.792969 167.597656 308.996094 168.476562 C 308.199219 169.355469 307.378906 170.21875 306.539062 171.058594 C 305.699219 171.894531 304.839844 172.714844 303.960938 173.511719 C 303.082031 174.308594 302.183594 175.085938 301.265625 175.839844 C 300.347656 176.59375 299.410156 177.324219 298.457031 178.03125 C 297.503906 178.738281 296.535156 179.421875 295.546875 180.082031 C 294.558594 180.742188 293.554688 181.378906 292.539062 181.988281 C 291.519531 182.597656 290.488281 183.183594 289.441406 183.746094 C 288.394531 184.304688 287.332031 184.839844 286.261719 185.347656 C 285.1875 185.855469 284.101562 186.335938 283.003906 186.792969 C 281.90625 187.246094 280.800781 187.675781 279.683594 188.074219 C 278.566406 188.476562 277.4375 188.851562 276.300781 189.195312 C 275.164062 189.539062 274.023438 189.859375 272.871094 190.148438 C 271.71875 190.4375 270.5625 190.699219 269.394531 190.929688 C 268.230469 191.164062 267.0625 191.367188 265.886719 191.542969 C 264.714844 191.71875 263.535156 191.863281 262.355469 191.980469 C 261.171875 192.097656 259.988281 192.1875 258.800781 192.246094 C 257.617188 192.308594 256.429688 192.335938 255.242188 192.339844 Z M 255.242188 192.339844 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#e10e49\" d=\"M 112.480469 265.582031 L 122.15625 259.933594 L 127.035156 268.285156 L 117.355469 273.9375 Z M 112.480469 265.582031 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 250.402344 61.695312 L 260.082031 61.695312 L 260.082031 81.046875 L 250.402344 81.046875 Z M 250.402344 61.695312 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 275.410156 83.203125 L 285.085938 68.6875 L 293.140625 74.054688 L 283.460938 88.570312 Z M 275.410156 83.203125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 217.363281 74.089844 L 225.371094 68.65625 L 235.21875 83.171875 L 227.210938 88.605469 Z M 217.363281 74.089844 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 250.402344 158.46875 L 260.082031 158.46875 L 260.082031 177.824219 L 250.402344 177.824219 Z M 250.402344 158.46875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 275.410156 156.3125 L 283.460938 150.945312 L 293.140625 165.460938 L 285.085938 170.832031 Z M 275.410156 156.3125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 217.367188 165.429688 L 227.214844 150.914062 L 235.222656 156.347656 L 225.375 170.863281 Z M 217.367188 165.429688 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/cosmosan.ch\/en\/schlafstoerungen\/\" target=\"_blank\">\n                                    sleeping disorders                                    <\/a><\/h4><div class=\"sc_icons_item_description\"><span>it\u2019s not a nice feeling not to have found any rest and being slain in the morning. a bad night can happen once in a while. but if it happens frequently, one should...<\/span><\/div><a href=\"https:\/\/cosmosan.ch\/en\/schlafstoerungen\/\" class=\"sc_icons_item_more_link\" target=\"_blank\">\n                        <span class=\"link_text\">read more<\/span><span class=\"link_icon\"><\/span>\n                        <\/a><a href=\"https:\/\/cosmosan.ch\/en\/schlafstoerungen\/\" class=\"sc_icons_item_link\" target=\"_blank\">\n                        <\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_icon sc_icon_type_svg\" style=\"color: #FFFFFF\" ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"500\" viewbox=\"0 0 375 374.999991\" height=\"500\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"45add1abe3\"><path d=\"M 56.855469 37.5 L 318.089844 37.5 L 318.089844 337.5 L 56.855469 337.5 Z M 56.855469 37.5 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><g clip-path=\"url(#45add1abe3)\"><path fill=\"#e10e49\" d=\"M 206.703125 314.574219 C 206.15625 316.785156 204.191406 318.238281 202.015625 318.238281 C 201.636719 318.238281 201.242188 318.203125 200.84375 318.089844 L 181.488281 313.25 C 178.898438 312.605469 177.3125 309.980469 177.972656 307.390625 C 178.617188 304.800781 181.242188 303.214844 183.832031 303.875 L 203.1875 308.714844 C 205.777344 309.355469 207.363281 311.984375 206.703125 314.574219 Z M 206.34375 267.699219 C 207.535156 270.078125 206.570312 272.988281 204.191406 274.179688 L 184.835938 283.859375 C 184.136719 284.199219 183.398438 284.367188 182.660156 284.367188 C 180.882812 284.367188 179.183594 283.386719 178.332031 281.703125 C 177.140625 279.304688 178.105469 276.390625 180.488281 275.203125 L 199.84375 265.523438 C 202.242188 264.332031 205.152344 265.296875 206.34375 267.699219 Z M 181.242188 244.242188 L 166.726562 258.757812 C 165.78125 259.703125 164.554688 260.175781 163.304688 260.175781 C 162.058594 260.175781 160.832031 259.703125 159.886719 258.757812 C 157.996094 256.867188 157.996094 253.804688 159.886719 251.914062 L 174.402344 237.398438 C 176.292969 235.507812 179.355469 235.507812 181.242188 237.398438 C 183.132812 239.289062 183.132812 242.351562 181.242188 244.242188 Z M 63.109375 113.597656 C 61.222656 111.707031 61.222656 108.644531 63.109375 106.753906 C 65 104.863281 68.0625 104.863281 69.953125 106.753906 L 84.46875 121.269531 C 89.0625 125.863281 82.089844 132.574219 77.628906 128.113281 Z M 290.53125 116.429688 C 300.871094 107.71875 306.238281 96.265625 311.890625 101.914062 C 317.539062 107.566406 306.105469 112.914062 297.371094 123.273438 C 292.894531 127.753906 285.996094 120.96875 290.53125 116.429688 Z M 91.539062 93.503906 C 90.0625 91.292969 90.648438 88.289062 92.878906 86.792969 C 95.109375 85.300781 98.117188 85.90625 99.589844 88.136719 L 109.269531 102.652344 C 110.761719 104.882812 110.15625 107.886719 107.925781 109.363281 C 105.695312 110.855469 102.691406 110.25 101.214844 108.019531 Z M 265.730469 102.652344 C 272.632812 94.183594 275.65625 82.464844 282.121094 86.792969 C 288.621094 91.121094 278.792969 98.664062 273.785156 108.019531 C 270.304688 113.257812 262.140625 108.019531 265.730469 102.652344 Z M 157.578125 112.101562 C 152.796875 103.976562 152.910156 96.507812 153.269531 93.449219 C 164.800781 85 160.453125 99.230469 167.3125 100.421875 C 179.203125 102.5 196.515625 102.464844 208.519531 97.71875 C 208.121094 100.367188 207.6875 103.085938 207.25 105.5625 C 191.847656 104.429688 172.4375 107.925781 157.578125 112.101562 Z M 139.625 67.175781 C 157.542969 65.625 157.75 35.628906 200.277344 51.789062 C 201.902344 52.433594 211.710938 51.941406 211.710938 71.277344 C 211.710938 84.886719 209.253906 86.644531 209.160156 86.699219 C 197.953125 93.597656 179.03125 92.164062 171.851562 91.292969 C 169.921875 86.546875 165.761719 81.144531 158.46875 81.144531 C 155.046875 81.144531 151.492188 82.976562 148.960938 84.640625 C 145.027344 80.519531 141.078125 73.015625 139.625 67.175781 Z M 95.207031 230.214844 C 94.675781 232.917969 86.660156 242.199219 93.617188 245.261719 C 115.902344 255.015625 152.4375 291.96875 153.628906 298.886719 C 153.628906 313.402344 147.089844 313.402344 143.953125 313.402344 C 134.839844 313.402344 130.683594 301.757812 121.554688 293.234375 C 112.914062 285.164062 66.53125 256.601562 66.53125 240.820312 C 66.53125 232.125 68.6875 220.199219 73.261719 211.523438 C 78.894531 217.097656 86.472656 223.921875 95.207031 230.214844 Z M 317.898438 210.277344 C 315.746094 203.773438 296.484375 146.597656 282.441406 135.425781 C 273.066406 127.960938 243.921875 111.761719 216.855469 106.828125 C 218.027344 100.195312 221.390625 77.171875 221.390625 71.277344 C 221.390625 54.964844 214.605469 44.285156 203.207031 42.566406 C 174.589844 32.054688 160.035156 39.257812 147.730469 51.390625 C 136.542969 62.410156 136.449219 54.492188 131.550781 57.78125 C 124.652344 62.507812 134.632812 84.867188 143.613281 92.878906 C 143.195312 97.324219 143.269531 105.847656 148.054688 115.03125 C 128.945312 121.421875 112.574219 130.019531 104.789062 137.960938 C 90.460938 152.628906 63.640625 192.886719 62.507812 194.589844 C 60.066406 198.253906 63.222656 200.957031 66.269531 204.285156 C 59.804688 214.738281 56.855469 229.667969 56.855469 240.820312 C 56.855469 265.242188 106.847656 288.941406 121.988281 308.488281 C 124.238281 311.398438 126.636719 314.421875 129.433594 316.992188 L 129.433594 332.753906 C 129.433594 335.421875 131.609375 337.59375 134.273438 337.59375 C 136.9375 337.59375 139.113281 335.421875 139.113281 332.753906 L 139.113281 322.4375 C 140.625 322.8125 142.210938 323.078125 143.953125 323.078125 C 151.171875 323.078125 163.304688 319.941406 163.304688 298.886719 C 163.304688 286.863281 124.578125 250.914062 101.953125 238.589844 L 103.390625 235.566406 C 108.472656 237.703125 110.457031 231.464844 124.085938 222.277344 C 127.148438 233.242188 129.433594 243.882812 129.433594 250.496094 C 129.433594 253.164062 131.609375 255.335938 134.273438 255.335938 C 136.9375 255.335938 139.113281 253.164062 139.113281 250.496094 C 139.113281 241.21875 135.636719 226.585938 131.402344 212.847656 C 131.382812 212.695312 131.324219 212.582031 131.289062 212.449219 C 127.074219 198.804688 122.140625 186.101562 119.210938 180.507812 C 117.960938 178.144531 115.03125 177.238281 112.671875 178.484375 C 110.308594 179.710938 109.382812 182.640625 110.628906 185.003906 C 113.351562 190.164062 117.414062 200.769531 121.082031 212.296875 L 104.941406 225.1875 C 89.988281 215.246094 77.628906 202.394531 72.636719 196.875 C 79.273438 187.066406 100.214844 156.484375 111.707031 144.726562 C 124.878906 131.269531 168.105469 115.015625 202.015625 115.015625 C 229.554688 115.015625 266.394531 135.03125 276.429688 142.988281 C 284.878906 149.734375 299.507812 186.269531 307.597656 209.972656 C 303.703125 212.316406 294.066406 216.871094 273.59375 221.011719 C 274.484375 207.667969 275.070312 192.925781 274.597656 177.765625 C 274.503906 175.101562 272.234375 172.984375 269.605469 173.078125 C 266.941406 173.171875 264.84375 175.402344 264.917969 178.066406 C 265.730469 204.09375 263.386719 229.175781 261.6875 247.511719 C 258.777344 278.699219 260.761719 260.535156 260.082031 332.753906 C 260.082031 335.421875 262.253906 337.59375 264.917969 337.59375 C 267.585938 337.59375 269.757812 335.421875 269.757812 332.753906 L 269.757812 294.554688 C 306.558594 265.242188 308.46875 261.742188 308.46875 231.144531 C 308.46875 224.753906 298.789062 224.734375 298.789062 231.144531 C 298.789062 256.46875 298.714844 258.925781 269.757812 282.175781 L 269.757812 269.851562 C 269.757812 262.707031 271.382812 249.324219 272.859375 231.011719 C 283.613281 228.929688 321.320312 220.578125 317.898438 210.277344 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><\/svg><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/cosmosan.ch\/en\/rueckenschmerzen\/\" target=\"_blank\">\n                                    neck &amp; back problems                                    <\/a><\/h4><div class=\"sc_icons_item_description\"><span>some experience the pain in the neck or shoulders, or in the back or lower back. the pain can be dull, pulling, spasmodic, or even burning or stabbing, and sometimes it...<\/span><\/div><a href=\"https:\/\/cosmosan.ch\/en\/rueckenschmerzen\/\" class=\"sc_icons_item_more_link\" target=\"_blank\">\n                        <span class=\"link_text\">read more<\/span><span class=\"link_icon\"><\/span>\n                        <\/a><a href=\"https:\/\/cosmosan.ch\/en\/rueckenschmerzen\/\" class=\"sc_icons_item_link\" target=\"_blank\">\n                        <\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_icon sc_icon_type_svg\" style=\"color: #FFFFFF\" ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"500\" viewbox=\"0 0 375 374.999991\" height=\"500\" preserveaspectratio=\"xMidYMid meet\"><path fill=\"#e10e49\" d=\"M 188.011719 71.304688 C 156.664062 71.304688 125.359375 83.253906 101.5 107.109375 C 53.785156 154.824219 53.785156 232.410156 101.5 280.125 C 149.214844 327.839844 226.804688 327.839844 274.519531 280.125 C 322.234375 232.410156 322.234375 154.824219 274.519531 107.109375 C 250.660156 83.253906 219.355469 71.304688 188.011719 71.304688 Z M 188.011719 326.089844 C 154.074219 326.089844 120.140625 313.183594 94.292969 287.335938 C 42.59375 235.675781 42.59375 151.558594 94.292969 99.902344 C 145.949219 48.203125 230.070312 48.203125 281.726562 99.902344 C 333.425781 151.558594 333.425781 235.675781 281.726562 287.335938 C 255.878906 313.183594 221.945312 326.089844 188.011719 326.089844 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 188.011719 71.304688 C 156.664062 71.304688 125.359375 83.253906 101.5 107.109375 C 53.785156 154.824219 53.785156 232.410156 101.5 280.125 C 149.214844 327.839844 226.804688 327.839844 274.519531 280.125 C 322.234375 232.410156 322.234375 154.824219 274.519531 107.109375 C 250.660156 83.253906 219.355469 71.304688 188.011719 71.304688 Z M 188.011719 326.089844 C 154.074219 326.089844 120.140625 313.183594 94.292969 287.335938 C 42.59375 235.675781 42.59375 151.558594 94.292969 99.902344 C 145.949219 48.203125 230.070312 48.203125 281.726562 99.902344 C 333.425781 151.558594 333.425781 235.675781 281.726562 287.335938 C 255.878906 313.183594 221.945312 326.089844 188.011719 326.089844 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 97.878906 288.847656 C 96.5625 288.847656 95.289062 288.332031 94.292969 287.335938 C 92.300781 285.34375 92.300781 282.117188 94.292969 280.125 L 120.140625 254.277344 C 122.132812 252.285156 125.359375 252.285156 127.351562 254.277344 C 129.34375 256.269531 129.34375 259.496094 127.351562 261.484375 L 101.5 287.335938 C 100.507812 288.332031 99.191406 288.847656 97.878906 288.847656 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 253.726562 133 C 252.414062 133 251.097656 132.519531 250.101562 131.523438 C 248.113281 129.53125 248.113281 126.308594 250.101562 124.316406 L 274.519531 99.902344 C 276.507812 97.910156 279.734375 97.910156 281.726562 99.902344 C 283.71875 101.890625 283.71875 105.117188 281.726562 107.109375 L 257.3125 131.523438 C 256.316406 132.519531 255 133 253.726562 133 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 147.464844 144.46875 C 149.972656 183.0625 173.671875 193.617188 188.011719 193.617188 C 202.347656 193.617188 226.046875 183.0625 228.554688 144.46875 C 222.941406 146.777344 214.417969 151.519531 207.40625 160.957031 C 206.050781 162.789062 203.664062 163.507812 201.550781 162.710938 C 199.441406 161.953125 198.085938 159.882812 198.207031 157.613281 C 198.207031 157.574219 198.324219 148.652344 188.011719 135.308594 C 177.695312 148.652344 177.8125 157.613281 177.8125 157.691406 C 177.894531 159.921875 176.5 161.992188 174.386719 162.710938 C 172.277344 163.425781 169.925781 162.75 168.613281 160.957031 C 161.601562 151.519531 153.078125 146.777344 147.464844 144.46875 Z M 188.011719 203.8125 C 169.089844 203.8125 137.027344 189.875 137.027344 137.539062 C 137.027344 136.023438 137.707031 134.632812 138.820312 133.675781 C 139.9375 132.679688 141.449219 132.242188 142.921875 132.519531 C 143.601562 132.601562 157.101562 134.910156 169.769531 146.898438 C 171.878906 141.003906 176.0625 133.078125 184.226562 123.957031 C 186.136719 121.765625 189.882812 121.765625 191.792969 123.957031 C 199.957031 133.078125 204.140625 141.003906 206.25 146.898438 C 218.917969 134.910156 232.417969 132.601562 233.097656 132.519531 C 234.570312 132.242188 236.082031 132.679688 237.199219 133.675781 C 238.3125 134.632812 238.992188 136.023438 238.992188 137.539062 C 238.992188 189.875 206.929688 203.8125 188.011719 203.8125 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 238.710938 216.957031 C 210.3125 231.535156 199.003906 253.800781 194.941406 264.632812 C 201.3125 263.636719 211.945312 259.972656 223.933594 247.664062 C 234.730469 236.632812 237.875 224.523438 238.710938 216.957031 Z M 190.480469 275.1875 C 188.527344 275.1875 187.332031 274.988281 187.132812 274.949219 C 185.78125 274.710938 184.585938 273.953125 183.789062 272.796875 C 183.03125 271.640625 182.753906 270.25 183.03125 268.894531 C 183.390625 267.101562 192.710938 225.042969 241.976562 204.210938 C 243.453125 203.574219 245.164062 203.695312 246.519531 204.53125 C 247.914062 205.328125 248.828125 206.722656 249.027344 208.316406 C 249.148438 209.351562 251.695312 233.804688 231.222656 254.792969 C 213.460938 272.957031 197.289062 275.1875 190.480469 275.1875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 137.308594 216.957031 C 138.144531 224.523438 141.289062 236.632812 152.085938 247.664062 C 164.074219 259.972656 174.707031 263.636719 181.078125 264.632812 C 177.015625 253.800781 165.707031 231.535156 137.308594 216.957031 Z M 185.539062 275.1875 C 178.730469 275.1875 162.558594 272.996094 144.796875 254.792969 C 124.324219 233.804688 126.871094 209.351562 126.992188 208.316406 C 127.191406 206.722656 128.105469 205.328125 129.5 204.53125 C 130.855469 203.695312 132.566406 203.574219 134.042969 204.210938 C 183.308594 225.042969 192.628906 267.101562 192.988281 268.894531 C 193.265625 270.25 192.988281 271.640625 192.230469 272.796875 C 191.433594 273.953125 190.238281 274.710938 188.886719 274.949219 C 188.6875 274.988281 187.492188 275.1875 185.539062 275.1875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 188.011719 275.027344 C 185.183594 275.027344 182.910156 272.757812 182.910156 269.929688 L 182.910156 198.714844 C 182.910156 195.886719 185.183594 193.617188 188.011719 193.617188 C 190.835938 193.617188 193.109375 195.886719 193.109375 198.714844 L 193.109375 269.929688 C 193.109375 272.757812 190.835938 275.027344 188.011719 275.027344 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 194.382812 101.851562 C 194.382812 98.347656 191.515625 95.480469 188.011719 95.480469 C 184.503906 95.480469 181.636719 98.347656 181.636719 101.851562 C 181.636719 105.355469 184.503906 108.226562 188.011719 108.226562 C 191.515625 108.226562 194.382812 105.355469 194.382812 101.851562 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 219.871094 117.144531 C 219.871094 113.640625 217.003906 110.773438 213.5 110.773438 C 209.996094 110.773438 207.128906 113.640625 207.128906 117.144531 C 207.128906 120.652344 209.996094 123.519531 213.5 123.519531 C 217.003906 123.519531 219.871094 120.652344 219.871094 117.144531 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 156.148438 117.144531 C 156.148438 113.640625 159.015625 110.773438 162.519531 110.773438 C 166.023438 110.773438 168.890625 113.640625 168.890625 117.144531 C 168.890625 120.652344 166.023438 123.519531 162.519531 123.519531 C 159.015625 123.519531 156.148438 120.652344 156.148438 117.144531 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/cosmosan.ch\/en\/allergien\/\" target=\"_blank\">\n                                    allergies &amp; intolerances                                    <\/a><\/h4><div class=\"sc_icons_item_description\"><span>hay fever or animal hair allergy usually begins with a tickle in the nose, a sneeze, itchy reddened eyes, tearing, tightness in the chest, and breathing difficulty. in extreme cases...<\/span><\/div><a href=\"https:\/\/cosmosan.ch\/en\/allergien\/\" class=\"sc_icons_item_more_link\" target=\"_blank\">\n                        <span class=\"link_text\">read more<\/span><span class=\"link_icon\"><\/span>\n                        <\/a><a href=\"https:\/\/cosmosan.ch\/en\/allergien\/\" class=\"sc_icons_item_link\" target=\"_blank\">\n                        <\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_icon sc_icon_type_svg\" style=\"color: #FFFFFF\" ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"500\" viewbox=\"0 0 375 374.999991\" height=\"500\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"0af395e789\"><path d=\"M 85 37.5 L 292.5 37.5 L 292.5 337.5 L 85 337.5 Z M 85 37.5 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><g clip-path=\"url(#0af395e789)\"><path fill=\"#e10e49\" d=\"M 292.261719 212.621094 C 292.257812 211.15625 292.183594 209.691406 292.035156 208.230469 C 291.890625 206.769531 291.671875 205.320312 291.382812 203.882812 C 291.097656 202.441406 290.738281 201.019531 290.3125 199.617188 C 289.882812 198.214844 289.390625 196.832031 288.828125 195.476562 C 288.265625 194.121094 287.640625 192.796875 286.949219 191.5 C 286.257812 190.207031 285.503906 188.949219 284.691406 187.730469 C 283.875 186.507812 283.003906 185.328125 282.074219 184.195312 C 281.144531 183.058594 280.164062 181.96875 279.125 180.929688 C 278.089844 179.890625 277.007812 178.902344 275.875 177.96875 C 274.742188 177.035156 273.566406 176.160156 272.351562 175.339844 C 271.132812 174.519531 269.878906 173.761719 268.585938 173.066406 C 267.292969 172.371094 265.972656 171.738281 264.617188 171.171875 C 263.265625 170.605469 261.886719 170.105469 260.484375 169.671875 C 259.082031 169.238281 257.660156 168.875 256.222656 168.582031 C 254.785156 168.289062 253.335938 168.0625 251.878906 167.910156 C 250.417969 167.757812 248.953125 167.679688 247.484375 167.667969 L 244.726562 167.675781 C 268.441406 146.953125 271.949219 111.132812 272.261719 95.328125 C 272.703125 72.722656 254.8125 53.226562 233.191406 52.761719 C 230.914062 52.71875 228.648438 52.863281 226.394531 53.203125 C 224.140625 53.542969 221.933594 54.074219 219.769531 54.789062 C 217.605469 55.503906 215.519531 56.398438 213.507812 57.46875 C 211.496094 58.539062 209.589844 59.773438 207.789062 61.167969 L 207.339844 42.644531 C 207.269531 39.882812 204.941406 37.519531 202.222656 37.773438 C 201.894531 37.78125 201.574219 37.820312 201.253906 37.890625 C 200.933594 37.964844 200.621094 38.066406 200.324219 38.199219 C 200.023438 38.332031 199.738281 38.492188 199.472656 38.683594 C 199.203125 38.871094 198.957031 39.082031 198.730469 39.320312 C 198.503906 39.558594 198.300781 39.816406 198.128906 40.09375 C 197.953125 40.371094 197.804688 40.660156 197.6875 40.96875 C 197.570312 41.273438 197.480469 41.589844 197.425781 41.910156 C 197.371094 42.234375 197.34375 42.558594 197.351562 42.886719 L 197.800781 61.347656 C 197.804688 62.273438 197.9375 63.183594 198.199219 64.070312 C 198.460938 64.960938 198.839844 65.792969 199.335938 66.578125 C 199.832031 67.359375 200.425781 68.058594 201.121094 68.671875 C 201.8125 69.285156 202.578125 69.792969 203.414062 70.195312 C 204.257812 70.601562 205.144531 70.886719 206.070312 71.046875 C 206.996094 71.207031 207.925781 71.234375 208.859375 71.132812 C 209.792969 71.03125 210.691406 70.804688 211.5625 70.449219 C 212.429688 70.09375 213.234375 69.625 213.972656 69.042969 C 216.675781 66.917969 219.660156 65.316406 222.925781 64.238281 C 226.1875 63.15625 229.539062 62.664062 232.976562 62.757812 C 249.195312 63.101562 262.609375 77.929688 262.269531 95.132812 C 261.953125 111.292969 258.117188 150.582031 229.429688 166.296875 C 216.085938 173.605469 199.949219 171.183594 188.929688 167.917969 L 177.015625 163.945312 C 174.453125 163.09375 171.820312 162.664062 169.121094 162.664062 L 167.367188 162.664062 C 164.664062 162.664062 162.03125 163.089844 159.464844 163.945312 C 156.902344 164.800781 154.539062 166.039062 152.378906 167.660156 L 135.449219 167.660156 C 136.019531 166.546875 136.660156 165.476562 137.375 164.449219 C 138.089844 163.421875 138.871094 162.449219 139.71875 161.527344 C 140.566406 160.609375 141.472656 159.75 142.441406 158.953125 C 143.40625 158.15625 144.417969 157.429688 145.484375 156.773438 C 146.550781 156.113281 147.652344 155.53125 148.796875 155.027344 C 149.941406 154.519531 151.117188 154.09375 152.316406 153.746094 C 153.519531 153.398438 154.742188 153.136719 155.980469 152.957031 C 157.21875 152.777344 158.460938 152.683594 159.714844 152.675781 C 162.277344 152.671875 164.703125 152.097656 166.996094 150.953125 C 178.996094 144.957031 188.246094 135.363281 193.039062 123.941406 C 199.949219 107.484375 195.878906 92.457031 190.703125 77.238281 C 186.558594 65.035156 186.683594 62.351562 187.050781 54.375 C 187.191406 51.367188 187.359375 47.722656 187.359375 42.765625 C 187.359375 42.4375 187.328125 42.113281 187.265625 41.789062 C 187.199219 41.46875 187.105469 41.15625 186.980469 40.855469 C 186.855469 40.550781 186.699219 40.261719 186.519531 39.988281 C 186.335938 39.71875 186.128906 39.464844 185.898438 39.234375 C 185.664062 39 185.414062 38.792969 185.140625 38.613281 C 184.867188 38.429688 184.578125 38.277344 184.277344 38.148438 C 183.972656 38.023438 183.660156 37.929688 183.339844 37.867188 C 183.015625 37.800781 182.691406 37.769531 182.363281 37.769531 C 182.035156 37.769531 181.710938 37.800781 181.390625 37.867188 C 181.066406 37.929688 180.753906 38.023438 180.453125 38.148438 C 180.148438 38.277344 179.863281 38.429688 179.589844 38.613281 C 179.316406 38.792969 179.0625 39 178.832031 39.234375 C 178.601562 39.464844 178.394531 39.71875 178.210938 39.988281 C 178.027344 40.261719 177.875 40.550781 177.75 40.855469 C 177.625 41.15625 177.527344 41.46875 177.464844 41.789062 C 177.402344 42.113281 177.367188 42.4375 177.367188 42.765625 C 177.367188 47.527344 177.203125 51.023438 177.070312 53.910156 C 176.671875 62.527344 176.488281 66.464844 181.246094 80.453125 C 185.949219 94.289062 189.390625 106.824219 183.828125 120.074219 C 179.957031 129.289062 172.394531 137.085938 162.523438 142.015625 C 161.640625 142.460938 160.703125 142.679688 159.714844 142.679688 C 157.761719 142.691406 155.820312 142.855469 153.890625 143.167969 C 151.960938 143.480469 150.070312 143.941406 148.210938 144.550781 C 146.355469 145.160156 144.558594 145.910156 142.816406 146.796875 C 141.078125 147.6875 139.417969 148.707031 137.835938 149.855469 C 136.253906 151 134.773438 152.265625 133.390625 153.644531 C 132.003906 155.023438 130.734375 156.503906 129.582031 158.078125 C 128.429688 159.65625 127.40625 161.3125 126.507812 163.050781 C 125.613281 164.785156 124.859375 166.582031 124.242188 168.4375 C 122.964844 168.675781 121.699219 168.964844 120.445312 169.3125 C 119.191406 169.660156 117.957031 170.058594 116.738281 170.511719 C 115.519531 170.96875 114.320312 171.472656 113.148438 172.03125 C 111.972656 172.589844 110.824219 173.195312 109.699219 173.851562 C 108.578125 174.507812 107.488281 175.214844 106.425781 175.964844 C 105.363281 176.71875 104.339844 177.515625 103.34375 178.355469 C 102.351562 179.195312 101.398438 180.078125 100.484375 181 C 99.566406 181.925781 98.695312 182.886719 97.863281 183.882812 C 97.027344 184.882812 96.242188 185.917969 95.5 186.984375 C 94.753906 188.050781 94.058594 189.148438 93.414062 190.277344 C 92.765625 191.40625 92.167969 192.558594 91.621094 193.738281 C 91.070312 194.917969 90.574219 196.117188 90.132812 197.339844 C 89.6875 198.5625 89.296875 199.804688 88.960938 201.058594 C 88.625 202.316406 88.34375 203.585938 88.117188 204.863281 C 87.890625 206.144531 87.722656 207.433594 87.605469 208.730469 C 87.492188 210.023438 87.433594 211.324219 87.433594 212.621094 L 87.433594 276.605469 L 86.648438 278.5625 C 86.167969 279.75 85.800781 280.972656 85.542969 282.226562 C 85.289062 283.480469 85.148438 284.75 85.121094 286.027344 C 85.097656 287.308594 85.1875 288.582031 85.394531 289.84375 C 85.601562 291.109375 85.917969 292.34375 86.351562 293.550781 C 86.78125 294.753906 87.316406 295.910156 87.957031 297.019531 C 88.601562 298.128906 89.335938 299.167969 90.167969 300.140625 C 91 301.117188 91.910156 302.007812 92.90625 302.816406 C 93.898438 303.621094 94.957031 304.335938 96.078125 304.949219 C 97.203125 305.566406 98.371094 306.074219 99.585938 306.476562 C 100.800781 306.878906 102.042969 307.167969 103.3125 307.34375 C 104.582031 307.519531 105.855469 307.578125 107.132812 307.523438 C 108.414062 307.46875 109.675781 307.296875 110.925781 307.011719 C 112.171875 306.726562 113.382812 306.328125 114.558594 305.824219 C 115.734375 305.316406 116.855469 304.707031 117.921875 303.996094 C 118.988281 303.289062 119.980469 302.488281 120.898438 301.59375 C 121.816406 300.703125 122.648438 299.738281 123.394531 298.695312 C 124.546875 300.074219 125.835938 301.3125 127.257812 302.410156 C 128.683594 303.507812 130.207031 304.441406 131.835938 305.203125 C 133.460938 305.96875 135.152344 306.546875 136.90625 306.941406 C 138.660156 307.335938 140.4375 307.539062 142.234375 307.542969 L 169.492188 307.542969 C 170.710938 310.34375 172.394531 312.832031 174.535156 315.003906 C 179.578125 320.109375 182.351562 326.296875 182.351562 332.523438 C 182.351562 332.851562 182.386719 333.171875 182.449219 333.492188 C 182.515625 333.8125 182.609375 334.125 182.734375 334.425781 C 182.863281 334.730469 183.015625 335.015625 183.199219 335.285156 C 183.382812 335.558594 183.589844 335.808594 183.820312 336.039062 C 184.054688 336.269531 184.304688 336.472656 184.578125 336.652344 C 184.851562 336.832031 185.140625 336.984375 185.441406 337.109375 C 185.746094 337.230469 186.054688 337.324219 186.378906 337.386719 C 186.699219 337.449219 187.023438 337.476562 187.347656 337.476562 C 187.679688 337.472656 188.003906 337.4375 188.328125 337.371094 C 188.648438 337.304688 188.960938 337.207031 189.265625 337.082031 C 189.570312 336.953125 189.855469 336.796875 190.128906 336.613281 C 190.402344 336.429688 190.652344 336.21875 190.886719 335.984375 C 191.117188 335.75 191.324219 335.496094 191.507812 335.222656 C 191.6875 334.949219 191.84375 334.660156 191.96875 334.355469 C 192.09375 334.050781 192.1875 333.734375 192.25 333.414062 C 192.3125 333.089844 192.34375 332.765625 192.34375 332.433594 C 192.34375 323.652344 188.542969 314.96875 181.644531 307.984375 C 181.027344 307.355469 180.464844 306.679688 179.964844 305.953125 C 179.46875 305.230469 179.035156 304.464844 178.671875 303.664062 C 178.304688 302.859375 178.015625 302.035156 177.796875 301.179688 C 177.578125 300.324219 177.4375 299.460938 177.375 298.582031 C 177.308594 297.703125 177.324219 296.824219 177.414062 295.949219 C 177.503906 295.074219 177.671875 294.210938 177.914062 293.363281 C 178.160156 292.519531 178.476562 291.699219 178.863281 290.910156 C 179.253906 290.117188 179.707031 289.367188 180.230469 288.65625 C 180.75 287.949219 181.332031 287.289062 181.96875 286.683594 C 182.609375 286.074219 183.292969 285.527344 184.03125 285.042969 C 184.765625 284.558594 185.535156 284.140625 186.347656 283.789062 C 187.15625 283.441406 187.988281 283.167969 188.847656 282.964844 C 189.703125 282.765625 190.574219 282.640625 191.453125 282.59375 C 192.332031 282.546875 193.210938 282.574219 194.082031 282.683594 C 194.957031 282.792969 195.816406 282.976562 196.65625 283.234375 C 197.5 283.496094 198.3125 283.828125 199.09375 284.230469 C 203.644531 286.535156 208.464844 287.644531 213.5625 287.5625 L 242.304688 287.5625 C 242.957031 287.5625 243.609375 287.527344 244.261719 287.464844 C 244.914062 287.398438 245.558594 287.300781 246.199219 287.175781 C 246.839844 287.046875 247.476562 286.886719 248.101562 286.695312 C 248.726562 286.503906 249.34375 286.285156 249.945312 286.035156 C 250.550781 285.785156 251.140625 285.503906 251.71875 285.195312 C 252.296875 284.886719 252.855469 284.550781 253.398438 284.1875 C 253.945312 283.824219 254.46875 283.433594 254.972656 283.019531 C 255.480469 282.601562 255.964844 282.164062 256.425781 281.703125 C 256.890625 281.238281 257.328125 280.753906 257.742188 280.25 C 258.160156 279.742188 258.546875 279.21875 258.910156 278.675781 C 259.273438 278.132812 259.613281 277.570312 259.921875 276.992188 C 260.230469 276.417969 260.507812 275.828125 260.757812 275.222656 C 261.011719 274.617188 261.230469 274.003906 261.421875 273.375 C 261.609375 272.75 261.769531 272.117188 261.898438 271.476562 C 262.027344 270.832031 262.125 270.1875 262.1875 269.535156 C 262.253906 268.886719 262.285156 268.234375 262.285156 267.578125 L 262.285156 217.621094 C 262.285156 216.964844 262.253906 216.3125 262.1875 215.660156 C 262.125 215.011719 262.027344 214.363281 261.898438 213.722656 C 261.769531 213.082031 261.609375 212.449219 261.421875 211.820312 C 261.230469 211.195312 261.011719 210.582031 260.757812 209.976562 C 260.507812 209.371094 260.230469 208.78125 259.921875 208.203125 C 259.613281 207.628906 259.273438 207.066406 258.910156 206.523438 C 258.546875 205.980469 258.160156 205.453125 257.742188 204.949219 C 257.328125 204.441406 256.890625 203.957031 256.425781 203.496094 C 255.964844 203.035156 255.480469 202.59375 254.972656 202.179688 C 254.46875 201.765625 253.945312 201.375 253.398438 201.011719 C 252.855469 200.648438 252.296875 200.3125 251.71875 200.003906 C 251.140625 199.695312 250.550781 199.414062 249.945312 199.164062 C 249.34375 198.914062 248.726562 198.691406 248.101562 198.503906 C 247.476562 198.3125 246.839844 198.152344 246.199219 198.023438 C 245.558594 197.894531 244.910156 197.800781 244.261719 197.734375 C 243.609375 197.671875 242.957031 197.636719 242.304688 197.636719 L 137.390625 197.636719 C 136.734375 197.636719 136.082031 197.671875 135.433594 197.734375 C 134.78125 197.800781 134.136719 197.894531 133.492188 198.023438 C 132.851562 198.152344 132.21875 198.3125 131.59375 198.503906 C 130.964844 198.691406 130.351562 198.914062 129.746094 199.164062 C 129.140625 199.414062 128.550781 199.695312 127.976562 200.003906 C 127.398438 200.3125 126.835938 200.648438 126.292969 201.011719 C 125.75 201.375 125.226562 201.765625 124.71875 202.179688 C 124.214844 202.59375 123.730469 203.035156 123.265625 203.496094 C 122.804688 203.957031 122.367188 204.441406 121.949219 204.949219 C 121.535156 205.453125 121.144531 205.980469 120.78125 206.523438 C 120.417969 207.066406 120.082031 207.628906 119.773438 208.203125 C 119.464844 208.78125 119.183594 209.371094 118.933594 209.976562 C 118.683594 210.582031 118.464844 211.195312 118.273438 211.820312 C 118.082031 212.449219 117.921875 213.082031 117.796875 213.722656 C 117.667969 214.363281 117.570312 215.011719 117.503906 215.660156 C 117.441406 216.3125 117.40625 216.964844 117.40625 217.621094 L 117.40625 286.414062 C 117.40625 287.144531 117.335938 287.867188 117.191406 288.585938 C 117.046875 289.304688 116.835938 290 116.554688 290.675781 C 116.277344 291.351562 115.933594 291.992188 115.527344 292.597656 C 115.121094 293.207031 114.660156 293.769531 114.140625 294.285156 C 113.625 294.804688 113.0625 295.265625 112.453125 295.671875 C 111.847656 296.078125 111.203125 296.421875 110.53125 296.699219 C 109.855469 296.980469 109.15625 297.191406 108.441406 297.335938 C 107.722656 297.480469 107 297.550781 106.269531 297.550781 C 105.816406 297.550781 105.363281 297.523438 104.914062 297.46875 C 104.464844 297.414062 104.019531 297.332031 103.578125 297.222656 C 103.140625 297.113281 102.707031 296.976562 102.285156 296.816406 C 101.859375 296.652344 101.449219 296.464844 101.046875 296.253906 C 100.648438 296.039062 100.261719 295.804688 99.890625 295.542969 C 99.519531 295.285156 99.164062 295.003906 98.828125 294.699219 C 98.488281 294.398438 98.171875 294.074219 97.875 293.734375 C 97.574219 293.390625 97.300781 293.035156 97.042969 292.65625 C 96.789062 292.28125 96.558594 291.894531 96.351562 291.488281 C 96.148438 291.085938 95.964844 290.671875 95.808594 290.246094 C 95.652344 289.820312 95.523438 289.386719 95.421875 288.945312 C 95.316406 288.503906 95.242188 288.058594 95.191406 287.605469 C 95.144531 287.15625 95.125 286.703125 95.128906 286.25 C 95.136719 285.796875 95.171875 285.347656 95.230469 284.898438 C 95.292969 284.449219 95.382812 284.003906 95.496094 283.566406 C 95.613281 283.128906 95.753906 282.699219 95.921875 282.277344 L 97.066406 279.425781 C 97.304688 278.828125 97.421875 278.210938 97.421875 277.570312 L 97.421875 212.621094 C 97.425781 211.476562 97.480469 210.335938 97.597656 209.195312 C 97.710938 208.058594 97.878906 206.925781 98.101562 205.804688 C 98.328125 204.679688 98.605469 203.570312 98.9375 202.476562 C 99.273438 201.378906 99.65625 200.304688 100.097656 199.246094 C 100.535156 198.1875 101.023438 197.15625 101.566406 196.144531 C 102.105469 195.136719 102.691406 194.15625 103.328125 193.203125 C 103.964844 192.25 104.648438 191.332031 105.375 190.449219 C 106.101562 189.5625 106.867188 188.714844 107.679688 187.90625 C 108.488281 187.097656 109.335938 186.328125 110.21875 185.601562 C 111.105469 184.875 112.023438 184.195312 112.976562 183.558594 C 113.925781 182.921875 114.90625 182.332031 115.917969 181.792969 C 116.925781 181.253906 117.960938 180.761719 119.019531 180.324219 C 120.074219 179.886719 121.152344 179.5 122.246094 179.167969 C 123.34375 178.832031 124.453125 178.554688 125.574219 178.332031 C 126.699219 178.105469 127.828125 177.9375 128.96875 177.824219 C 130.109375 177.710938 131.25 177.652344 132.394531 177.652344 L 154.148438 177.652344 C 155.410156 177.652344 156.511719 177.238281 157.457031 176.402344 C 158.828125 175.195312 160.363281 174.269531 162.070312 173.621094 C 163.777344 172.976562 165.542969 172.65625 167.367188 172.65625 L 169.121094 172.65625 C 170.742188 172.65625 172.320312 172.910156 173.859375 173.425781 L 185.929688 177.445312 C 197.421875 180.855469 213.539062 183.34375 228.429688 177.695312 L 247.476562 177.660156 C 248.617188 177.667969 249.753906 177.734375 250.890625 177.851562 C 252.023438 177.972656 253.152344 178.144531 254.269531 178.375 C 255.386719 178.601562 256.492188 178.886719 257.582031 179.222656 C 258.671875 179.558594 259.742188 179.949219 260.792969 180.390625 C 261.84375 180.832031 262.875 181.324219 263.878906 181.867188 C 264.882812 182.40625 265.855469 182.996094 266.804688 183.632812 C 267.75 184.269531 268.664062 184.953125 269.542969 185.679688 C 270.421875 186.40625 271.265625 187.171875 272.070312 187.980469 C 272.875 188.789062 273.636719 189.636719 274.359375 190.519531 C 275.082031 191.402344 275.761719 192.320312 276.394531 193.269531 C 277.027344 194.21875 277.609375 195.195312 278.148438 196.203125 C 278.683594 197.207031 279.171875 198.238281 279.609375 199.292969 C 280.046875 200.347656 280.429688 201.421875 280.761719 202.511719 C 281.09375 203.605469 281.371094 204.707031 281.59375 205.828125 C 281.816406 206.945312 281.988281 208.074219 282.101562 209.207031 C 282.214844 210.34375 282.273438 211.480469 282.273438 212.621094 L 282.273438 272.574219 C 282.273438 273.71875 282.214844 274.859375 282.101562 276 C 281.988281 277.140625 281.820312 278.269531 281.597656 279.394531 C 281.371094 280.515625 281.09375 281.625 280.761719 282.71875 C 280.425781 283.816406 280.039062 284.890625 279.601562 285.949219 C 279.164062 287.007812 278.675781 288.039062 278.132812 289.050781 C 277.59375 290.058594 277.003906 291.039062 276.367188 291.992188 C 275.734375 292.945312 275.050781 293.863281 274.324219 294.746094 C 273.597656 295.632812 272.832031 296.480469 272.019531 297.289062 C 271.210938 298.097656 270.363281 298.867188 269.480469 299.59375 C 268.59375 300.320312 267.675781 301 266.722656 301.636719 C 265.773438 302.273438 264.789062 302.863281 263.78125 303.402344 C 262.773438 303.941406 261.738281 304.433594 260.679688 304.871094 C 259.621094 305.308594 258.546875 305.695312 257.449219 306.027344 C 256.355469 306.363281 255.246094 306.640625 254.125 306.863281 C 253 307.089844 251.871094 307.257812 250.730469 307.371094 C 249.589844 307.484375 248.449219 307.542969 247.304688 307.542969 L 221.351562 307.542969 C 220.730469 307.542969 220.109375 307.574219 219.488281 307.636719 C 218.867188 307.699219 218.253906 307.789062 217.644531 307.914062 C 217.03125 308.035156 216.429688 308.1875 215.832031 308.367188 C 215.238281 308.546875 214.652344 308.757812 214.078125 308.996094 C 213.503906 309.234375 212.941406 309.5 212.390625 309.796875 C 211.84375 310.089844 211.308594 310.410156 210.792969 310.753906 C 210.273438 311.101562 209.773438 311.472656 209.292969 311.867188 C 208.8125 312.261719 208.351562 312.679688 207.910156 313.121094 C 207.472656 313.558594 207.054688 314.019531 206.660156 314.5 C 206.265625 314.984375 205.894531 315.480469 205.546875 316 C 205.203125 316.515625 204.882812 317.050781 204.589844 317.597656 C 204.292969 318.148438 204.027344 318.710938 203.789062 319.285156 C 203.550781 319.859375 203.339844 320.445312 203.160156 321.042969 C 202.980469 321.636719 202.828125 322.238281 202.707031 322.851562 C 202.582031 323.460938 202.492188 324.074219 202.429688 324.695312 C 202.367188 325.316406 202.335938 325.9375 202.335938 326.558594 L 202.335938 332.523438 C 202.335938 332.851562 202.367188 333.175781 202.433594 333.496094 C 202.496094 333.820312 202.589844 334.132812 202.714844 334.433594 C 202.84375 334.738281 202.996094 335.027344 203.179688 335.296875 C 203.359375 335.570312 203.566406 335.824219 203.800781 336.054688 C 204.03125 336.289062 204.285156 336.496094 204.558594 336.675781 C 204.828125 336.859375 205.117188 337.011719 205.421875 337.136719 C 205.722656 337.265625 206.035156 337.359375 206.359375 337.421875 C 206.679688 337.488281 207.003906 337.519531 207.332031 337.519531 C 207.660156 337.519531 207.984375 337.488281 208.308594 337.421875 C 208.628906 337.359375 208.941406 337.265625 209.242188 337.136719 C 209.546875 337.011719 209.835938 336.859375 210.109375 336.675781 C 210.378906 336.496094 210.632812 336.289062 210.863281 336.054688 C 211.097656 335.824219 211.304688 335.570312 211.484375 335.296875 C 211.667969 335.027344 211.820312 334.738281 211.949219 334.433594 C 212.074219 334.132812 212.167969 333.820312 212.230469 333.496094 C 212.296875 333.175781 212.328125 332.851562 212.328125 332.523438 L 212.328125 326.558594 C 212.328125 325.964844 212.386719 325.378906 212.503906 324.796875 C 212.617188 324.21875 212.789062 323.652344 213.015625 323.105469 C 213.246094 322.558594 213.523438 322.039062 213.851562 321.546875 C 214.179688 321.054688 214.554688 320.601562 214.972656 320.179688 C 215.390625 319.761719 215.847656 319.386719 216.339844 319.058594 C 216.832031 318.730469 217.351562 318.453125 217.898438 318.226562 C 218.445312 317.996094 219.011719 317.828125 219.589844 317.710938 C 220.171875 317.59375 220.757812 317.535156 221.351562 317.535156 L 247.300781 317.535156 C 248.769531 317.535156 250.238281 317.460938 251.703125 317.3125 C 253.167969 317.167969 254.625 316.953125 256.066406 316.664062 C 257.511719 316.375 258.9375 316.015625 260.34375 315.585938 C 261.753906 315.160156 263.136719 314.664062 264.496094 314.097656 C 265.855469 313.535156 267.1875 312.90625 268.484375 312.210938 C 269.78125 311.515625 271.042969 310.761719 272.265625 309.941406 C 273.488281 309.125 274.671875 308.246094 275.808594 307.3125 C 276.945312 306.378906 278.035156 305.390625 279.078125 304.351562 C 280.117188 303.308594 281.105469 302.21875 282.039062 301.082031 C 282.972656 299.945312 283.847656 298.765625 284.667969 297.539062 C 285.484375 296.316406 286.242188 295.054688 286.9375 293.757812 C 287.632812 292.460938 288.261719 291.128906 288.824219 289.769531 C 289.390625 288.410156 289.886719 287.027344 290.3125 285.617188 C 290.742188 284.210938 291.101562 282.785156 291.390625 281.339844 C 291.675781 279.898438 291.894531 278.441406 292.039062 276.976562 C 292.1875 275.511719 292.257812 274.046875 292.261719 272.574219 Z M 127.398438 217.617188 C 127.398438 216.960938 127.464844 216.3125 127.59375 215.671875 C 127.722656 215.027344 127.910156 214.402344 128.160156 213.796875 C 128.414062 213.191406 128.722656 212.613281 129.085938 212.070312 C 129.449219 211.523438 129.863281 211.019531 130.328125 210.554688 C 130.792969 210.09375 131.296875 209.679688 131.839844 209.3125 C 132.386719 208.949219 132.960938 208.640625 133.570312 208.390625 C 134.175781 208.140625 134.796875 207.949219 135.441406 207.820312 C 136.085938 207.691406 136.734375 207.628906 137.390625 207.628906 L 242.304688 207.628906 C 242.957031 207.628906 243.609375 207.691406 244.25 207.820312 C 244.894531 207.949219 245.519531 208.140625 246.125 208.390625 C 246.730469 208.640625 247.304688 208.949219 247.851562 209.3125 C 248.398438 209.679688 248.902344 210.09375 249.367188 210.554688 C 249.828125 211.019531 250.242188 211.523438 250.609375 212.070312 C 250.972656 212.613281 251.28125 213.191406 251.53125 213.796875 C 251.78125 214.402344 251.972656 215.027344 252.101562 215.671875 C 252.230469 216.3125 252.292969 216.960938 252.292969 217.617188 L 252.292969 267.578125 C 252.292969 268.234375 252.230469 268.882812 252.101562 269.527344 C 251.972656 270.167969 251.78125 270.792969 251.53125 271.398438 C 251.28125 272.003906 250.972656 272.582031 250.609375 273.125 C 250.242188 273.671875 249.828125 274.175781 249.367188 274.640625 C 248.902344 275.101562 248.398438 275.515625 247.851562 275.882812 C 247.304688 276.246094 246.730469 276.554688 246.125 276.804688 C 245.519531 277.058594 244.894531 277.246094 244.25 277.375 C 243.609375 277.503906 242.957031 277.566406 242.304688 277.570312 L 213.5625 277.570312 C 210.101562 277.644531 206.820312 276.914062 203.722656 275.375 C 202.300781 274.628906 200.816406 274.027344 199.277344 273.570312 C 197.734375 273.113281 196.164062 272.8125 194.5625 272.660156 C 192.964844 272.511719 191.363281 272.519531 189.765625 272.683594 C 188.167969 272.847656 186.601562 273.167969 185.0625 273.640625 C 182.261719 274.484375 179.699219 275.792969 177.371094 277.570312 L 152.378906 277.570312 C 152.050781 277.570312 151.726562 277.535156 151.402344 277.472656 C 151.082031 277.410156 150.769531 277.3125 150.464844 277.1875 C 150.164062 277.0625 149.875 276.910156 149.601562 276.726562 C 149.328125 276.542969 149.078125 276.335938 148.84375 276.105469 C 148.613281 275.875 148.40625 275.621094 148.222656 275.347656 C 148.042969 275.074219 147.886719 274.789062 147.761719 274.484375 C 147.636719 274.179688 147.542969 273.871094 147.476562 273.546875 C 147.414062 273.226562 147.382812 272.902344 147.382812 272.574219 C 147.382812 272.246094 147.414062 271.917969 147.476562 271.597656 C 147.542969 271.277344 147.636719 270.964844 147.761719 270.660156 C 147.886719 270.359375 148.042969 270.070312 148.222656 269.796875 C 148.40625 269.523438 148.613281 269.273438 148.84375 269.039062 C 149.078125 268.808594 149.328125 268.601562 149.601562 268.417969 C 149.875 268.238281 150.164062 268.082031 150.464844 267.957031 C 150.769531 267.832031 151.082031 267.738281 151.402344 267.671875 C 151.726562 267.609375 152.050781 267.578125 152.378906 267.578125 L 227.316406 267.578125 C 228.300781 267.578125 229.273438 267.480469 230.238281 267.289062 C 231.203125 267.097656 232.140625 266.8125 233.050781 266.4375 C 233.960938 266.058594 234.824219 265.597656 235.640625 265.050781 C 236.460938 264.503906 237.21875 263.882812 237.914062 263.1875 C 238.609375 262.492188 239.230469 261.734375 239.777344 260.917969 C 240.324219 260.097656 240.785156 259.234375 241.164062 258.324219 C 241.539062 257.414062 241.824219 256.480469 242.015625 255.511719 C 242.207031 254.546875 242.304688 253.574219 242.304688 252.589844 C 242.304688 251.605469 242.207031 250.628906 242.015625 249.664062 C 241.824219 248.699219 241.539062 247.761719 241.164062 246.855469 C 240.785156 245.945312 240.324219 245.082031 239.777344 244.261719 C 239.230469 243.445312 238.609375 242.6875 237.914062 241.992188 C 237.21875 241.296875 236.460938 240.675781 235.640625 240.128906 C 234.824219 239.582031 233.960938 239.121094 233.050781 238.742188 C 232.140625 238.367188 231.203125 238.082031 230.238281 237.890625 C 229.273438 237.699219 228.300781 237.601562 227.316406 237.601562 L 162.371094 237.601562 C 162.042969 237.601562 161.714844 237.570312 161.394531 237.507812 C 161.074219 237.441406 160.761719 237.347656 160.457031 237.222656 C 160.15625 237.097656 159.867188 236.941406 159.59375 236.761719 C 159.320312 236.578125 159.070312 236.371094 158.835938 236.140625 C 158.605469 235.90625 158.398438 235.65625 158.214844 235.382812 C 158.035156 235.109375 157.878906 234.820312 157.753906 234.519531 C 157.628906 234.214844 157.535156 233.902344 157.46875 233.582031 C 157.40625 233.257812 157.375 232.933594 157.375 232.605469 C 157.375 232.277344 157.40625 231.953125 157.46875 231.632812 C 157.535156 231.308594 157.628906 230.996094 157.753906 230.695312 C 157.878906 230.390625 158.035156 230.101562 158.214844 229.832031 C 158.398438 229.558594 158.605469 229.304688 158.835938 229.074219 C 159.070312 228.839844 159.320312 228.632812 159.59375 228.453125 C 159.867188 228.269531 160.15625 228.117188 160.457031 227.992188 C 160.761719 227.863281 161.074219 227.769531 161.394531 227.707031 C 161.714844 227.640625 162.042969 227.609375 162.371094 227.609375 L 212.328125 227.609375 C 212.65625 227.609375 212.980469 227.578125 213.300781 227.515625 C 213.625 227.449219 213.9375 227.355469 214.238281 227.230469 C 214.542969 227.105469 214.832031 226.949219 215.105469 226.769531 C 215.375 226.585938 215.628906 226.378906 215.859375 226.148438 C 216.09375 225.914062 216.300781 225.664062 216.480469 225.390625 C 216.664062 225.117188 216.816406 224.828125 216.945312 224.527344 C 217.070312 224.222656 217.164062 223.910156 217.226562 223.589844 C 217.292969 223.265625 217.324219 222.941406 217.324219 222.613281 C 217.324219 222.285156 217.292969 221.960938 217.226562 221.640625 C 217.164062 221.316406 217.070312 221.003906 216.945312 220.703125 C 216.816406 220.398438 216.664062 220.113281 216.480469 219.839844 C 216.300781 219.566406 216.09375 219.3125 215.859375 219.082031 C 215.628906 218.851562 215.375 218.644531 215.105469 218.460938 C 214.832031 218.277344 214.542969 218.125 214.238281 218 C 213.9375 217.875 213.625 217.777344 213.300781 217.714844 C 212.980469 217.652344 212.65625 217.617188 212.328125 217.617188 L 162.371094 217.617188 C 161.386719 217.617188 160.410156 217.714844 159.445312 217.90625 C 158.480469 218.097656 157.542969 218.382812 156.632812 218.757812 C 155.726562 219.136719 154.859375 219.597656 154.042969 220.144531 C 153.226562 220.691406 152.46875 221.3125 151.773438 222.007812 C 151.074219 222.703125 150.453125 223.460938 149.90625 224.28125 C 149.359375 225.097656 148.898438 225.960938 148.523438 226.871094 C 148.144531 227.78125 147.863281 228.71875 147.671875 229.683594 C 147.476562 230.648438 147.382812 231.621094 147.382812 232.605469 C 147.382812 233.589844 147.476562 234.566406 147.671875 235.53125 C 147.863281 236.496094 148.144531 237.433594 148.523438 238.339844 C 148.898438 239.25 149.359375 240.113281 149.90625 240.933594 C 150.453125 241.75 151.074219 242.507812 151.773438 243.203125 C 152.46875 243.898438 153.226562 244.519531 154.042969 245.066406 C 154.859375 245.613281 155.726562 246.074219 156.632812 246.453125 C 157.542969 246.828125 158.480469 247.113281 159.445312 247.304688 C 160.410156 247.496094 161.386719 247.59375 162.371094 247.59375 L 227.316406 247.59375 C 227.644531 247.59375 227.96875 247.625 228.289062 247.691406 C 228.613281 247.753906 228.925781 247.847656 229.226562 247.972656 C 229.53125 248.097656 229.816406 248.253906 230.089844 248.4375 C 230.363281 248.617188 230.617188 248.824219 230.847656 249.058594 C 231.082031 249.289062 231.289062 249.542969 231.46875 249.8125 C 231.652344 250.085938 231.804688 250.375 231.929688 250.675781 C 232.054688 250.980469 232.152344 251.292969 232.214844 251.613281 C 232.28125 251.9375 232.3125 252.261719 232.3125 252.589844 C 232.3125 252.917969 232.28125 253.242188 232.214844 253.5625 C 232.152344 253.886719 232.054688 254.199219 231.929688 254.5 C 231.804688 254.804688 231.652344 255.09375 231.46875 255.363281 C 231.289062 255.636719 231.082031 255.890625 230.847656 256.121094 C 230.617188 256.355469 230.363281 256.5625 230.089844 256.742188 C 229.816406 256.925781 229.53125 257.078125 229.226562 257.203125 C 228.925781 257.332031 228.613281 257.425781 228.289062 257.488281 C 227.96875 257.554688 227.644531 257.585938 227.316406 257.585938 L 152.378906 257.585938 C 151.394531 257.585938 150.417969 257.679688 149.453125 257.875 C 148.488281 258.066406 147.550781 258.347656 146.640625 258.726562 C 145.734375 259.101562 144.871094 259.5625 144.050781 260.109375 C 143.234375 260.65625 142.476562 261.277344 141.78125 261.976562 C 141.085938 262.671875 140.464844 263.429688 139.917969 264.246094 C 139.371094 265.0625 138.90625 265.929688 138.53125 266.835938 C 138.15625 267.746094 137.871094 268.683594 137.679688 269.648438 C 137.488281 270.613281 137.390625 271.589844 137.390625 272.574219 C 137.390625 273.558594 137.488281 274.53125 137.679688 275.496094 C 137.871094 276.460938 138.15625 277.398438 138.53125 278.308594 C 138.90625 279.21875 139.371094 280.082031 139.917969 280.898438 C 140.464844 281.71875 141.085938 282.476562 141.78125 283.171875 C 142.476562 283.867188 143.234375 284.488281 144.050781 285.035156 C 144.871094 285.582031 145.734375 286.042969 146.640625 286.417969 C 147.550781 286.796875 148.488281 287.082031 149.453125 287.273438 C 150.417969 287.464844 151.394531 287.558594 152.378906 287.558594 L 169.457031 287.558594 C 168.847656 288.910156 168.371094 290.304688 168.027344 291.746094 C 167.597656 293.65625 167.390625 295.59375 167.402344 297.550781 L 142.234375 297.550781 C 141.261719 297.550781 140.296875 297.457031 139.34375 297.265625 C 138.386719 297.074219 137.460938 296.792969 136.558594 296.417969 C 135.660156 296.046875 134.804688 295.589844 133.996094 295.046875 C 133.1875 294.503906 132.4375 293.890625 131.75 293.203125 C 131.058594 292.511719 130.445312 291.765625 129.902344 290.953125 C 129.363281 290.144531 128.90625 289.289062 128.53125 288.390625 C 128.160156 287.492188 127.878906 286.5625 127.6875 285.609375 C 127.496094 284.652344 127.398438 283.691406 127.398438 282.714844 Z M 127.398438 217.617188 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#e10e49\" d=\"M 232.3125 227.609375 L 237.308594 227.609375 C 237.636719 227.609375 237.960938 227.578125 238.28125 227.515625 C 238.605469 227.449219 238.914062 227.355469 239.21875 227.230469 C 239.523438 227.105469 239.808594 226.949219 240.082031 226.769531 C 240.355469 226.585938 240.609375 226.378906 240.839844 226.148438 C 241.070312 225.914062 241.277344 225.664062 241.460938 225.390625 C 241.644531 225.117188 241.796875 224.828125 241.921875 224.527344 C 242.046875 224.222656 242.144531 223.910156 242.207031 223.589844 C 242.269531 223.265625 242.304688 222.941406 242.304688 222.613281 C 242.304688 222.285156 242.269531 221.960938 242.207031 221.640625 C 242.144531 221.316406 242.046875 221.003906 241.921875 220.703125 C 241.796875 220.398438 241.644531 220.113281 241.460938 219.839844 C 241.277344 219.566406 241.070312 219.3125 240.839844 219.082031 C 240.609375 218.851562 240.355469 218.644531 240.082031 218.460938 C 239.808594 218.277344 239.523438 218.125 239.21875 218 C 238.914062 217.875 238.605469 217.777344 238.28125 217.714844 C 237.960938 217.652344 237.636719 217.617188 237.308594 217.617188 L 232.3125 217.617188 C 231.984375 217.617188 231.660156 217.652344 231.335938 217.714844 C 231.015625 217.777344 230.703125 217.875 230.398438 218 C 230.097656 218.125 229.808594 218.277344 229.535156 218.460938 C 229.261719 218.644531 229.011719 218.851562 228.777344 219.082031 C 228.546875 219.3125 228.339844 219.566406 228.15625 219.839844 C 227.976562 220.113281 227.820312 220.398438 227.695312 220.703125 C 227.570312 221.003906 227.476562 221.316406 227.410156 221.640625 C 227.347656 221.960938 227.316406 222.285156 227.316406 222.613281 C 227.316406 222.941406 227.347656 223.265625 227.410156 223.589844 C 227.476562 223.910156 227.570312 224.222656 227.695312 224.527344 C 227.820312 224.828125 227.976562 225.117188 228.15625 225.390625 C 228.339844 225.664062 228.546875 225.914062 228.777344 226.148438 C 229.011719 226.378906 229.261719 226.585938 229.535156 226.769531 C 229.808594 226.949219 230.097656 227.105469 230.398438 227.230469 C 230.703125 227.355469 231.015625 227.449219 231.335938 227.515625 C 231.660156 227.578125 231.984375 227.609375 232.3125 227.609375 Z M 232.3125 227.609375 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 227.316406 137.683594 C 227.316406 138.011719 227.347656 138.339844 227.410156 138.660156 C 227.476562 138.980469 227.570312 139.292969 227.695312 139.597656 C 227.820312 139.898438 227.976562 140.1875 228.15625 140.460938 C 228.339844 140.734375 228.546875 140.984375 228.777344 141.21875 C 229.011719 141.449219 229.261719 141.65625 229.535156 141.839844 C 229.808594 142.019531 230.097656 142.175781 230.398438 142.300781 C 230.703125 142.425781 231.015625 142.519531 231.335938 142.585938 C 231.660156 142.648438 231.984375 142.679688 232.3125 142.679688 L 237.308594 142.679688 C 237.636719 142.679688 237.960938 142.648438 238.28125 142.585938 C 238.605469 142.519531 238.914062 142.425781 239.21875 142.300781 C 239.523438 142.175781 239.808594 142.019531 240.082031 141.839844 C 240.355469 141.65625 240.609375 141.449219 240.839844 141.21875 C 241.070312 140.984375 241.277344 140.734375 241.460938 140.460938 C 241.644531 140.1875 241.796875 139.898438 241.921875 139.597656 C 242.046875 139.292969 242.144531 138.980469 242.207031 138.660156 C 242.269531 138.339844 242.304688 138.011719 242.304688 137.683594 C 242.304688 137.355469 242.269531 137.03125 242.207031 136.710938 C 242.144531 136.390625 242.046875 136.078125 241.921875 135.773438 C 241.796875 135.46875 241.644531 135.183594 241.460938 134.910156 C 241.277344 134.636719 241.070312 134.382812 240.839844 134.152344 C 240.609375 133.921875 240.355469 133.714844 240.082031 133.53125 C 239.808594 133.347656 239.523438 133.195312 239.21875 133.070312 C 238.914062 132.945312 238.605469 132.847656 238.28125 132.785156 C 237.960938 132.722656 237.636719 132.6875 237.308594 132.6875 L 232.3125 132.6875 C 231.984375 132.6875 231.660156 132.722656 231.335938 132.785156 C 231.015625 132.847656 230.703125 132.945312 230.398438 133.070312 C 230.097656 133.195312 229.808594 133.347656 229.535156 133.53125 C 229.261719 133.714844 229.011719 133.921875 228.777344 134.152344 C 228.546875 134.382812 228.339844 134.636719 228.15625 134.910156 C 227.976562 135.183594 227.820312 135.46875 227.695312 135.773438 C 227.570312 136.078125 227.476562 136.390625 227.410156 136.710938 C 227.347656 137.03125 227.316406 137.355469 227.316406 137.683594 Z M 227.316406 137.683594 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 227.316406 112.707031 L 222.320312 112.707031 C 221.992188 112.707031 221.667969 112.738281 221.34375 112.800781 C 221.023438 112.867188 220.710938 112.960938 220.40625 113.085938 C 220.105469 113.210938 219.816406 113.367188 219.542969 113.546875 C 219.269531 113.730469 219.019531 113.9375 218.789062 114.167969 C 218.554688 114.402344 218.347656 114.652344 218.164062 114.925781 C 217.984375 115.199219 217.828125 115.488281 217.703125 115.789062 C 217.578125 116.09375 217.484375 116.40625 217.417969 116.726562 C 217.355469 117.050781 217.324219 117.375 217.324219 117.703125 C 217.324219 118.03125 217.355469 118.355469 217.417969 118.675781 C 217.484375 119 217.578125 119.3125 217.703125 119.613281 C 217.828125 119.917969 217.984375 120.203125 218.164062 120.476562 C 218.347656 120.75 218.554688 121.003906 218.789062 121.234375 C 219.019531 121.464844 219.269531 121.671875 219.542969 121.855469 C 219.816406 122.039062 220.105469 122.191406 220.40625 122.316406 C 220.710938 122.441406 221.023438 122.539062 221.34375 122.601562 C 221.667969 122.664062 221.992188 122.699219 222.320312 122.699219 L 227.316406 122.699219 C 227.644531 122.699219 227.96875 122.664062 228.289062 122.601562 C 228.613281 122.539062 228.925781 122.441406 229.226562 122.316406 C 229.53125 122.191406 229.816406 122.039062 230.089844 121.855469 C 230.363281 121.671875 230.617188 121.464844 230.847656 121.234375 C 231.082031 121.003906 231.289062 120.75 231.46875 120.476562 C 231.652344 120.203125 231.804688 119.917969 231.929688 119.613281 C 232.054688 119.3125 232.152344 119 232.214844 118.675781 C 232.28125 118.355469 232.3125 118.03125 232.3125 117.703125 C 232.3125 117.375 232.28125 117.050781 232.214844 116.726562 C 232.152344 116.40625 232.054688 116.09375 231.929688 115.789062 C 231.804688 115.488281 231.652344 115.199219 231.46875 114.925781 C 231.289062 114.652344 231.082031 114.402344 230.847656 114.167969 C 230.617188 113.9375 230.363281 113.730469 230.089844 113.546875 C 229.816406 113.367188 229.53125 113.210938 229.226562 113.085938 C 228.925781 112.960938 228.613281 112.867188 228.289062 112.800781 C 227.96875 112.738281 227.644531 112.707031 227.316406 112.707031 Z M 227.316406 112.707031 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 207.332031 132.6875 L 202.335938 132.6875 C 202.007812 132.6875 201.683594 132.722656 201.363281 132.785156 C 201.039062 132.847656 200.726562 132.945312 200.425781 133.070312 C 200.121094 133.195312 199.832031 133.347656 199.5625 133.53125 C 199.289062 133.714844 199.035156 133.921875 198.804688 134.152344 C 198.570312 134.382812 198.363281 134.636719 198.183594 134.910156 C 198 135.183594 197.847656 135.46875 197.722656 135.773438 C 197.59375 136.078125 197.5 136.390625 197.4375 136.710938 C 197.371094 137.03125 197.339844 137.355469 197.339844 137.683594 C 197.339844 138.011719 197.371094 138.339844 197.4375 138.660156 C 197.5 138.980469 197.59375 139.292969 197.722656 139.597656 C 197.847656 139.898438 198 140.1875 198.183594 140.460938 C 198.363281 140.734375 198.570312 140.984375 198.804688 141.21875 C 199.035156 141.449219 199.289062 141.65625 199.5625 141.839844 C 199.832031 142.019531 200.121094 142.175781 200.425781 142.300781 C 200.726562 142.425781 201.039062 142.519531 201.363281 142.585938 C 201.683594 142.648438 202.007812 142.679688 202.335938 142.679688 L 207.332031 142.679688 C 207.660156 142.679688 207.984375 142.648438 208.308594 142.585938 C 208.628906 142.519531 208.941406 142.425781 209.242188 142.300781 C 209.546875 142.175781 209.835938 142.019531 210.109375 141.839844 C 210.378906 141.65625 210.632812 141.449219 210.863281 141.21875 C 211.097656 140.984375 211.304688 140.734375 211.484375 140.460938 C 211.667969 140.1875 211.820312 139.898438 211.949219 139.597656 C 212.074219 139.292969 212.167969 138.980469 212.230469 138.660156 C 212.296875 138.339844 212.328125 138.011719 212.328125 137.683594 C 212.328125 137.355469 212.296875 137.03125 212.230469 136.710938 C 212.167969 136.390625 212.074219 136.078125 211.949219 135.773438 C 211.820312 135.46875 211.667969 135.183594 211.484375 134.910156 C 211.304688 134.636719 211.097656 134.382812 210.863281 134.152344 C 210.632812 133.921875 210.378906 133.714844 210.109375 133.53125 C 209.835938 133.347656 209.546875 133.195312 209.242188 133.070312 C 208.941406 132.945312 208.628906 132.847656 208.308594 132.785156 C 207.984375 132.722656 207.660156 132.6875 207.332031 132.6875 Z M 207.332031 132.6875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 212.328125 152.671875 C 212 152.671875 211.675781 152.703125 211.351562 152.769531 C 211.03125 152.832031 210.71875 152.925781 210.417969 153.054688 C 210.113281 153.179688 209.824219 153.332031 209.550781 153.515625 C 209.28125 153.695312 209.027344 153.902344 208.796875 154.136719 C 208.5625 154.367188 208.355469 154.621094 208.175781 154.894531 C 207.992188 155.164062 207.839844 155.453125 207.710938 155.757812 C 207.585938 156.058594 207.492188 156.371094 207.429688 156.695312 C 207.363281 157.015625 207.332031 157.339844 207.332031 157.667969 C 207.332031 157.996094 207.363281 158.320312 207.429688 158.644531 C 207.492188 158.964844 207.585938 159.277344 207.710938 159.582031 C 207.839844 159.882812 207.992188 160.171875 208.175781 160.445312 C 208.355469 160.71875 208.5625 160.96875 208.796875 161.199219 C 209.027344 161.433594 209.28125 161.640625 209.550781 161.824219 C 209.824219 162.003906 210.113281 162.160156 210.417969 162.285156 C 210.71875 162.410156 211.03125 162.503906 211.351562 162.570312 C 211.675781 162.632812 212 162.664062 212.328125 162.664062 L 217.324219 162.664062 C 217.652344 162.664062 217.976562 162.632812 218.296875 162.570312 C 218.621094 162.503906 218.933594 162.410156 219.234375 162.285156 C 219.539062 162.160156 219.828125 162.003906 220.097656 161.824219 C 220.371094 161.640625 220.625 161.433594 220.855469 161.199219 C 221.089844 160.96875 221.296875 160.71875 221.476562 160.445312 C 221.660156 160.171875 221.8125 159.882812 221.9375 159.582031 C 222.066406 159.277344 222.160156 158.964844 222.222656 158.644531 C 222.289062 158.320312 222.320312 157.996094 222.320312 157.667969 C 222.320312 157.339844 222.289062 157.015625 222.222656 156.695312 C 222.160156 156.371094 222.066406 156.058594 221.9375 155.757812 C 221.8125 155.453125 221.660156 155.164062 221.476562 154.894531 C 221.296875 154.621094 221.089844 154.367188 220.855469 154.136719 C 220.625 153.902344 220.371094 153.695312 220.097656 153.515625 C 219.828125 153.332031 219.539062 153.179688 219.234375 153.054688 C 218.933594 152.925781 218.621094 152.832031 218.296875 152.769531 C 217.976562 152.703125 217.652344 152.671875 217.324219 152.671875 Z M 212.328125 152.671875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/cosmosan.ch\/en\/verdauungsprobleme\/\" target=\"_blank\">\n                                    digestive disorders                                    <\/a><\/h4><div class=\"sc_icons_item_description\"><span>those who are plagued chronically by either fullness, sour burping, flatulence, constipation, or diarrhea, in the worst case...<\/span><\/div><a href=\"https:\/\/cosmosan.ch\/en\/verdauungsprobleme\/\" class=\"sc_icons_item_more_link\" target=\"_blank\">\n                        <span class=\"link_text\">read more<\/span><span class=\"link_icon\"><\/span>\n                        <\/a><a href=\"https:\/\/cosmosan.ch\/en\/verdauungsprobleme\/\" class=\"sc_icons_item_link\" target=\"_blank\">\n                        <\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_icon sc_icon_type_svg\" style=\"color: #FFFFFF\" ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"500\" viewbox=\"0 0 375 374.999991\" height=\"500\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"087caebfc0\"><path d=\"M 74.0625 122 L 295 122 L 295 337.5 L 74.0625 337.5 Z M 74.0625 122 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><g clip-path=\"url(#087caebfc0)\"><path fill=\"#e10e49\" d=\"M 184.640625 122.988281 C 205.671875 122.988281 225.003906 131.503906 240.359375 145.800781 C 254.476562 158.953125 265.222656 177.007812 270.757812 197.800781 C 279.289062 194.695312 285.164062 195.492188 289.160156 198.757812 C 294.015625 202.722656 295.25 209.71875 294.804688 217.515625 C 294.34375 225.605469 293.355469 236.171875 290.066406 243.464844 C 286.574219 251.21875 281.226562 255.816406 272.917969 253.023438 C 268.730469 275.976562 258.355469 296.199219 243.984375 311.074219 C 228.101562 327.507812 207.359375 337.445312 184.640625 337.445312 C 161.917969 337.445312 141.183594 327.507812 125.304688 311.074219 C 110.933594 296.199219 100.558594 275.976562 96.363281 253.023438 C 88.054688 255.816406 82.707031 251.21875 79.214844 243.464844 C 75.925781 236.164062 74.9375 225.605469 74.472656 217.515625 C 74.03125 209.71875 75.265625 202.722656 80.121094 198.757812 C 84.117188 195.492188 89.992188 194.695312 98.523438 197.800781 C 104.058594 177.007812 114.804688 158.953125 128.921875 145.800781 C 144.285156 131.503906 163.609375 122.988281 184.640625 122.988281 Z M 233.285156 153.398438 C 219.820312 140.855469 202.933594 133.390625 184.640625 133.390625 C 166.34375 133.390625 149.460938 140.855469 135.992188 153.398438 C 122.035156 166.402344 111.714844 184.828125 107.207031 206.101562 L 107.191406 206.089844 C 107.101562 206.511719 106.960938 206.933594 106.753906 207.335938 C 105.476562 209.890625 102.371094 210.929688 99.816406 209.652344 C 92.339844 205.902344 88.386719 205.390625 86.664062 206.800781 C 84.925781 208.21875 84.5625 212.171875 84.832031 216.945312 C 85.238281 224.140625 86.078125 233.425781 88.683594 239.195312 C 90.148438 242.460938 92.703125 243.992188 97.203125 241 C 97.929688 240.433594 98.820312 240.042969 99.800781 239.929688 C 102.652344 239.589844 105.230469 241.625 105.566406 244.476562 C 108.453125 268.15625 118.414062 289.019531 132.769531 303.886719 C 146.722656 318.316406 164.855469 327.054688 184.640625 327.054688 C 204.425781 327.054688 222.558594 318.316406 236.507812 303.886719 C 250.875 289.019531 260.828125 268.15625 263.710938 244.476562 L 263.722656 244.476562 C 263.820312 243.671875 264.109375 242.863281 264.609375 242.144531 C 266.234375 239.789062 269.464844 239.195312 271.8125 240.820312 C 276.476562 244.050781 279.105469 242.523438 280.605469 239.195312 C 283.203125 233.425781 284.042969 224.140625 284.445312 216.945312 C 284.71875 212.171875 284.363281 208.21875 282.625 206.800781 C 280.921875 205.414062 277.0625 205.886719 269.8125 209.480469 C 269.332031 209.757812 268.804688 209.972656 268.230469 210.097656 C 265.425781 210.691406 262.675781 208.902344 262.082031 206.101562 C 257.574219 184.828125 247.253906 166.402344 233.285156 153.398438 Z M 233.285156 153.398438 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#e10e49\" d=\"M 166.683594 204.75 C 168.710938 202.714844 172.007812 202.714844 174.035156 204.75 C 176.0625 206.777344 176.0625 210.0625 174.035156 212.097656 C 171.050781 215.082031 167.5 217.429688 163.609375 219.039062 C 159.734375 220.644531 155.574219 221.496094 151.347656 221.496094 C 147.128906 221.496094 142.964844 220.644531 139.09375 219.039062 C 135.203125 217.429688 131.652344 215.082031 128.667969 212.097656 C 126.632812 210.0625 126.632812 206.777344 128.667969 204.75 C 130.695312 202.714844 133.984375 202.714844 136.019531 204.75 C 138.070312 206.800781 140.460938 208.390625 143.03125 209.453125 C 145.621094 210.523438 148.445312 211.09375 151.347656 211.09375 C 154.253906 211.09375 157.082031 210.523438 159.671875 209.453125 C 162.242188 208.390625 164.632812 206.800781 166.683594 204.75 Z M 166.683594 204.75 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 233.269531 204.75 C 235.296875 202.714844 238.59375 202.714844 240.621094 204.75 C 242.648438 206.777344 242.648438 210.0625 240.621094 212.097656 C 237.628906 215.082031 234.078125 217.429688 230.1875 219.039062 C 226.324219 220.644531 222.160156 221.496094 217.933594 221.496094 C 213.707031 221.496094 209.542969 220.644531 205.679688 219.039062 C 201.789062 217.429688 198.238281 215.082031 195.246094 212.097656 C 193.21875 210.0625 193.21875 206.777344 195.246094 204.75 C 197.28125 202.714844 200.570312 202.714844 202.597656 204.75 C 204.648438 206.800781 207.039062 208.390625 209.617188 209.453125 C 212.207031 210.523438 215.023438 211.09375 217.933594 211.09375 C 220.84375 211.09375 223.660156 210.523438 226.25 209.453125 C 228.828125 208.390625 231.21875 206.800781 233.269531 204.75 Z M 233.269531 204.75 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 169.304688 287.289062 C 167.277344 289.324219 163.988281 289.324219 161.953125 287.289062 C 159.925781 285.261719 159.925781 281.976562 161.953125 279.9375 C 164.945312 276.957031 168.496094 274.609375 172.386719 273 C 176.257812 271.394531 180.421875 270.542969 184.640625 270.542969 C 188.867188 270.542969 193.03125 271.394531 196.902344 273 C 200.785156 274.609375 204.335938 276.957031 207.328125 279.9375 C 209.355469 281.976562 209.355469 285.261719 207.328125 287.289062 C 205.300781 289.324219 202.003906 289.324219 199.976562 287.289062 C 197.925781 285.238281 195.535156 283.648438 192.957031 282.585938 C 190.367188 281.511719 187.550781 280.945312 184.640625 280.945312 C 181.730469 280.945312 178.914062 281.511719 176.324219 282.585938 C 173.753906 283.648438 171.363281 285.238281 169.304688 287.289062 Z M 169.304688 287.289062 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 223.390625 249.160156 C 223.390625 249.480469 223.359375 249.796875 223.296875 250.109375 C 223.234375 250.421875 223.140625 250.726562 223.019531 251.023438 C 222.894531 251.320312 222.746094 251.597656 222.570312 251.863281 C 222.390625 252.132812 222.1875 252.378906 221.964844 252.601562 C 221.738281 252.828125 221.492188 253.03125 221.226562 253.207031 C 220.960938 253.386719 220.679688 253.535156 220.382812 253.660156 C 220.085938 253.78125 219.78125 253.875 219.46875 253.9375 C 219.15625 254 218.839844 254.03125 218.519531 254.03125 C 218.199219 254.03125 217.882812 254 217.570312 253.9375 C 217.253906 253.875 216.949219 253.78125 216.65625 253.660156 C 216.359375 253.535156 216.078125 253.386719 215.8125 253.207031 C 215.546875 253.03125 215.300781 252.828125 215.074219 252.601562 C 214.847656 252.378906 214.648438 252.132812 214.46875 251.863281 C 214.292969 251.597656 214.140625 251.320312 214.019531 251.023438 C 213.898438 250.726562 213.804688 250.421875 213.742188 250.109375 C 213.679688 249.796875 213.648438 249.480469 213.648438 249.160156 C 213.648438 248.839844 213.679688 248.523438 213.742188 248.210938 C 213.804688 247.894531 213.898438 247.589844 214.019531 247.296875 C 214.140625 247 214.292969 246.71875 214.46875 246.453125 C 214.648438 246.1875 214.847656 245.941406 215.074219 245.714844 C 215.300781 245.488281 215.546875 245.289062 215.8125 245.109375 C 216.078125 244.933594 216.359375 244.78125 216.65625 244.660156 C 216.949219 244.539062 217.253906 244.445312 217.570312 244.382812 C 217.882812 244.320312 218.199219 244.289062 218.519531 244.289062 C 218.839844 244.289062 219.15625 244.320312 219.46875 244.382812 C 219.78125 244.445312 220.085938 244.539062 220.382812 244.660156 C 220.679688 244.78125 220.960938 244.933594 221.226562 245.109375 C 221.492188 245.289062 221.738281 245.488281 221.964844 245.714844 C 222.1875 245.941406 222.390625 246.1875 222.570312 246.453125 C 222.746094 246.71875 222.894531 247 223.019531 247.296875 C 223.140625 247.589844 223.234375 247.894531 223.296875 248.210938 C 223.359375 248.523438 223.390625 248.839844 223.390625 249.160156 Z M 223.390625 249.160156 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 137.207031 244.199219 C 137.207031 244.519531 137.175781 244.835938 137.113281 245.148438 C 137.050781 245.460938 136.957031 245.765625 136.835938 246.0625 C 136.710938 246.355469 136.5625 246.636719 136.382812 246.902344 C 136.207031 247.167969 136.003906 247.414062 135.777344 247.640625 C 135.550781 247.867188 135.304688 248.070312 135.039062 248.246094 C 134.773438 248.425781 134.492188 248.574219 134.199219 248.699219 C 133.902344 248.820312 133.597656 248.914062 133.285156 248.976562 C 132.972656 249.039062 132.65625 249.070312 132.335938 249.070312 C 132.015625 249.070312 131.699219 249.039062 131.382812 248.976562 C 131.070312 248.914062 130.765625 248.820312 130.472656 248.699219 C 130.175781 248.574219 129.894531 248.425781 129.628906 248.246094 C 129.363281 248.070312 129.117188 247.867188 128.890625 247.640625 C 128.664062 247.414062 128.460938 247.167969 128.285156 246.902344 C 128.105469 246.636719 127.957031 246.355469 127.835938 246.0625 C 127.710938 245.765625 127.621094 245.460938 127.558594 245.148438 C 127.496094 244.835938 127.464844 244.519531 127.464844 244.199219 C 127.464844 243.878906 127.496094 243.5625 127.558594 243.246094 C 127.621094 242.933594 127.710938 242.628906 127.835938 242.335938 C 127.957031 242.039062 128.105469 241.757812 128.285156 241.492188 C 128.460938 241.226562 128.664062 240.980469 128.890625 240.753906 C 129.117188 240.527344 129.363281 240.324219 129.628906 240.148438 C 129.894531 239.972656 130.175781 239.820312 130.472656 239.699219 C 130.765625 239.574219 131.070312 239.484375 131.382812 239.421875 C 131.699219 239.359375 132.015625 239.328125 132.335938 239.328125 C 132.65625 239.328125 132.972656 239.359375 133.285156 239.421875 C 133.597656 239.484375 133.902344 239.574219 134.199219 239.699219 C 134.492188 239.820312 134.773438 239.972656 135.039062 240.148438 C 135.304688 240.324219 135.550781 240.527344 135.777344 240.753906 C 136.003906 240.980469 136.207031 241.226562 136.382812 241.492188 C 136.5625 241.757812 136.710938 242.039062 136.835938 242.335938 C 136.957031 242.628906 137.050781 242.933594 137.113281 243.246094 C 137.175781 243.5625 137.207031 243.878906 137.207031 244.199219 Z M 137.207031 244.199219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 134.601562 267.914062 C 134.601562 268.234375 134.570312 268.550781 134.507812 268.867188 C 134.445312 269.179688 134.351562 269.484375 134.230469 269.78125 C 134.109375 270.074219 133.957031 270.355469 133.78125 270.621094 C 133.601562 270.886719 133.402344 271.132812 133.175781 271.359375 C 132.949219 271.585938 132.703125 271.789062 132.4375 271.964844 C 132.171875 272.144531 131.890625 272.292969 131.59375 272.414062 C 131.300781 272.539062 130.996094 272.628906 130.679688 272.691406 C 130.367188 272.753906 130.050781 272.785156 129.730469 272.785156 C 129.410156 272.785156 129.09375 272.753906 128.78125 272.691406 C 128.464844 272.628906 128.164062 272.539062 127.867188 272.414062 C 127.570312 272.292969 127.289062 272.144531 127.023438 271.964844 C 126.757812 271.789062 126.511719 271.585938 126.285156 271.359375 C 126.058594 271.132812 125.859375 270.886719 125.679688 270.621094 C 125.503906 270.355469 125.351562 270.074219 125.230469 269.78125 C 125.109375 269.484375 125.015625 269.179688 124.953125 268.867188 C 124.890625 268.550781 124.859375 268.234375 124.859375 267.914062 C 124.859375 267.597656 124.890625 267.277344 124.953125 266.964844 C 125.015625 266.652344 125.109375 266.347656 125.230469 266.050781 C 125.351562 265.757812 125.503906 265.476562 125.679688 265.210938 C 125.859375 264.945312 126.058594 264.699219 126.285156 264.472656 C 126.511719 264.246094 126.757812 264.042969 127.023438 263.867188 C 127.289062 263.6875 127.570312 263.539062 127.867188 263.417969 C 128.164062 263.292969 128.464844 263.203125 128.78125 263.140625 C 129.09375 263.078125 129.410156 263.046875 129.730469 263.046875 C 130.050781 263.046875 130.367188 263.078125 130.679688 263.140625 C 130.996094 263.203125 131.300781 263.292969 131.59375 263.417969 C 131.890625 263.539062 132.171875 263.6875 132.4375 263.867188 C 132.703125 264.042969 132.949219 264.246094 133.175781 264.472656 C 133.402344 264.699219 133.601562 264.945312 133.78125 265.210938 C 133.957031 265.476562 134.109375 265.757812 134.230469 266.050781 C 134.351562 266.347656 134.445312 266.652344 134.507812 266.964844 C 134.570312 267.277344 134.601562 267.597656 134.601562 267.914062 Z M 134.601562 267.914062 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 229.480469 171.082031 C 229.480469 171.402344 229.449219 171.71875 229.386719 172.035156 C 229.324219 172.347656 229.230469 172.652344 229.109375 172.949219 C 228.988281 173.242188 228.835938 173.523438 228.660156 173.789062 C 228.480469 174.054688 228.277344 174.300781 228.054688 174.527344 C 227.828125 174.753906 227.582031 174.957031 227.316406 175.132812 C 227.050781 175.3125 226.769531 175.460938 226.472656 175.582031 C 226.175781 175.707031 225.875 175.796875 225.558594 175.859375 C 225.246094 175.921875 224.929688 175.953125 224.609375 175.953125 C 224.289062 175.953125 223.972656 175.921875 223.660156 175.859375 C 223.34375 175.796875 223.039062 175.707031 222.746094 175.582031 C 222.449219 175.460938 222.167969 175.3125 221.902344 175.132812 C 221.636719 174.957031 221.390625 174.753906 221.164062 174.527344 C 220.9375 174.300781 220.738281 174.054688 220.558594 173.789062 C 220.382812 173.523438 220.230469 173.242188 220.109375 172.949219 C 219.988281 172.652344 219.894531 172.347656 219.832031 172.035156 C 219.769531 171.71875 219.738281 171.402344 219.738281 171.082031 C 219.738281 170.765625 219.769531 170.449219 219.832031 170.132812 C 219.894531 169.820312 219.988281 169.515625 220.109375 169.21875 C 220.230469 168.925781 220.382812 168.644531 220.558594 168.378906 C 220.738281 168.113281 220.9375 167.867188 221.164062 167.640625 C 221.390625 167.414062 221.636719 167.210938 221.902344 167.035156 C 222.167969 166.855469 222.449219 166.707031 222.746094 166.585938 C 223.039062 166.460938 223.34375 166.371094 223.660156 166.308594 C 223.972656 166.246094 224.289062 166.214844 224.609375 166.214844 C 224.929688 166.214844 225.246094 166.246094 225.558594 166.308594 C 225.875 166.371094 226.175781 166.460938 226.472656 166.585938 C 226.769531 166.707031 227.050781 166.855469 227.316406 167.035156 C 227.582031 167.210938 227.828125 167.414062 228.054688 167.640625 C 228.277344 167.867188 228.480469 168.113281 228.660156 168.378906 C 228.835938 168.644531 228.988281 168.925781 229.109375 169.21875 C 229.230469 169.515625 229.324219 169.820312 229.386719 170.132812 C 229.449219 170.449219 229.480469 170.765625 229.480469 171.082031 Z M 229.480469 171.082031 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 236.953125 271.417969 C 236.953125 271.738281 236.921875 272.054688 236.859375 272.367188 C 236.796875 272.683594 236.707031 272.988281 236.582031 273.28125 C 236.460938 273.578125 236.3125 273.859375 236.132812 274.125 C 235.957031 274.390625 235.753906 274.636719 235.527344 274.863281 C 235.300781 275.089844 235.054688 275.289062 234.789062 275.46875 C 234.523438 275.644531 234.242188 275.796875 233.949219 275.917969 C 233.652344 276.039062 233.347656 276.132812 233.035156 276.195312 C 232.71875 276.257812 232.402344 276.289062 232.082031 276.289062 C 231.765625 276.289062 231.449219 276.257812 231.132812 276.195312 C 230.820312 276.132812 230.515625 276.039062 230.21875 275.917969 C 229.925781 275.796875 229.644531 275.644531 229.378906 275.46875 C 229.113281 275.289062 228.867188 275.089844 228.640625 274.863281 C 228.414062 274.636719 228.210938 274.390625 228.035156 274.125 C 227.855469 273.859375 227.707031 273.578125 227.585938 273.28125 C 227.460938 272.988281 227.371094 272.683594 227.308594 272.367188 C 227.246094 272.054688 227.214844 271.738281 227.214844 271.417969 C 227.214844 271.097656 227.246094 270.78125 227.308594 270.46875 C 227.371094 270.15625 227.460938 269.851562 227.585938 269.554688 C 227.707031 269.257812 227.855469 268.976562 228.035156 268.710938 C 228.210938 268.445312 228.414062 268.199219 228.640625 267.972656 C 228.867188 267.75 229.113281 267.546875 229.378906 267.367188 C 229.644531 267.191406 229.925781 267.039062 230.21875 266.917969 C 230.515625 266.796875 230.820312 266.703125 231.132812 266.640625 C 231.449219 266.578125 231.765625 266.546875 232.082031 266.546875 C 232.402344 266.546875 232.71875 266.578125 233.035156 266.640625 C 233.347656 266.703125 233.652344 266.796875 233.949219 266.917969 C 234.242188 267.039062 234.523438 267.191406 234.789062 267.367188 C 235.054688 267.546875 235.300781 267.75 235.527344 267.972656 C 235.753906 268.199219 235.957031 268.445312 236.132812 268.710938 C 236.3125 268.976562 236.460938 269.257812 236.582031 269.554688 C 236.707031 269.851562 236.796875 270.15625 236.859375 270.46875 C 236.921875 270.78125 236.953125 271.097656 236.953125 271.417969 Z M 236.953125 271.417969 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 155.484375 256.707031 C 155.484375 255.273438 156.644531 254.105469 158.078125 254.105469 C 159.523438 254.105469 160.683594 255.273438 160.683594 256.707031 C 160.683594 259.148438 159.695312 261.355469 158.085938 262.953125 L 158.078125 262.972656 C 156.472656 264.570312 154.265625 265.558594 151.824219 265.558594 C 149.386719 265.558594 147.175781 264.570312 145.578125 262.972656 L 145.570312 262.953125 C 143.960938 261.355469 142.972656 259.148438 142.972656 256.707031 C 142.972656 254.269531 143.960938 252.058594 145.570312 250.453125 L 145.578125 250.445312 C 147.175781 248.847656 149.386719 247.847656 151.824219 247.847656 C 152.449219 247.847656 153.085938 247.921875 153.703125 248.054688 C 154.296875 248.1875 154.90625 248.382812 155.5 248.65625 C 156.800781 249.257812 157.371094 250.789062 156.777344 252.09375 C 156.183594 253.394531 154.644531 253.964844 153.347656 253.371094 C 153.136719 253.273438 152.878906 253.1875 152.609375 253.132812 C 152.359375 253.082031 152.097656 253.050781 151.824219 253.050781 C 150.8125 253.050781 149.894531 253.460938 149.238281 254.121094 C 148.578125 254.78125 148.175781 255.695312 148.175781 256.707031 C 148.175781 257.722656 148.578125 258.636719 149.238281 259.296875 C 149.894531 259.953125 150.8125 260.367188 151.824219 260.367188 C 152.839844 260.367188 153.761719 259.953125 154.421875 259.296875 C 155.078125 258.636719 155.484375 257.722656 155.484375 256.707031 Z M 155.484375 256.707031 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 236.566406 243.910156 C 235.421875 244.765625 233.796875 244.519531 232.941406 243.375 C 232.09375 242.21875 232.332031 240.597656 233.484375 239.746094 C 235.585938 238.183594 238.125 237.613281 240.53125 237.96875 C 242.9375 238.324219 245.210938 239.589844 246.777344 241.710938 C 248.34375 243.8125 248.910156 246.347656 248.558594 248.753906 C 248.210938 251.160156 246.933594 253.4375 244.824219 255.003906 C 242.714844 256.566406 240.175781 257.136719 237.769531 256.78125 C 235.363281 256.429688 233.097656 255.160156 231.523438 253.050781 C 231.113281 252.488281 230.765625 251.902344 230.484375 251.292969 C 230.214844 250.683594 230 250.039062 229.851562 249.367188 C 229.554688 247.964844 230.453125 246.589844 231.851562 246.292969 C 233.253906 245.996094 234.636719 246.894531 234.925781 248.292969 C 234.992188 248.589844 235.09375 248.878906 235.222656 249.167969 C 235.347656 249.449219 235.503906 249.71875 235.683594 249.957031 C 236.394531 250.914062 237.425781 251.484375 238.519531 251.648438 C 239.625 251.804688 240.777344 251.550781 241.734375 250.839844 C 242.691406 250.132812 243.257812 249.101562 243.421875 248.003906 C 243.578125 246.910156 243.324219 245.746094 242.617188 244.792969 C 241.90625 243.84375 240.878906 243.265625 239.78125 243.101562 C 238.683594 242.945312 237.523438 243.199219 236.566406 243.910156 Z M 236.566406 243.910156 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 145.238281 181.96875 C 145.238281 182.289062 145.207031 182.605469 145.148438 182.921875 C 145.085938 183.234375 144.992188 183.539062 144.871094 183.835938 C 144.746094 184.128906 144.597656 184.410156 144.417969 184.675781 C 144.242188 184.941406 144.039062 185.1875 143.8125 185.414062 C 143.585938 185.640625 143.339844 185.84375 143.074219 186.019531 C 142.808594 186.199219 142.527344 186.347656 142.234375 186.46875 C 141.9375 186.59375 141.632812 186.683594 141.320312 186.746094 C 141.007812 186.808594 140.691406 186.839844 140.371094 186.839844 C 140.050781 186.839844 139.734375 186.808594 139.417969 186.746094 C 139.105469 186.683594 138.800781 186.59375 138.503906 186.46875 C 138.210938 186.347656 137.929688 186.199219 137.664062 186.019531 C 137.398438 185.84375 137.152344 185.640625 136.925781 185.414062 C 136.699219 185.1875 136.496094 184.941406 136.320312 184.675781 C 136.140625 184.410156 135.992188 184.128906 135.871094 183.835938 C 135.746094 183.539062 135.65625 183.234375 135.59375 182.921875 C 135.53125 182.605469 135.5 182.289062 135.5 181.96875 C 135.5 181.652344 135.53125 181.332031 135.59375 181.019531 C 135.65625 180.707031 135.746094 180.402344 135.871094 180.105469 C 135.992188 179.8125 136.140625 179.53125 136.320312 179.265625 C 136.496094 179 136.699219 178.753906 136.925781 178.527344 C 137.152344 178.300781 137.398438 178.097656 137.664062 177.921875 C 137.929688 177.742188 138.210938 177.59375 138.503906 177.46875 C 138.800781 177.347656 139.105469 177.253906 139.417969 177.195312 C 139.734375 177.132812 140.050781 177.101562 140.371094 177.101562 C 140.691406 177.101562 141.007812 177.132812 141.320312 177.195312 C 141.632812 177.253906 141.9375 177.347656 142.234375 177.46875 C 142.527344 177.59375 142.808594 177.742188 143.074219 177.921875 C 143.339844 178.097656 143.585938 178.300781 143.8125 178.527344 C 144.039062 178.753906 144.242188 179 144.417969 179.265625 C 144.597656 179.53125 144.746094 179.8125 144.871094 180.105469 C 144.992188 180.402344 145.085938 180.707031 145.148438 181.019531 C 145.207031 181.332031 145.238281 181.652344 145.238281 181.96875 Z M 145.238281 181.96875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 106.21875 203.386719 C 107.214844 206.066406 105.855469 209.050781 103.179688 210.046875 C 100.492188 211.042969 97.507812 209.683594 96.511719 207 C 95.199219 203.480469 94.070312 200.101562 93.125 196.855469 C 84.007812 165.792969 88.542969 141.242188 102.066406 121.894531 C 115.367188 102.863281 137.304688 89.191406 163.402344 79.476562 C 168.992188 77.398438 174.695312 75.511719 180.488281 73.816406 C 183.238281 73.007812 186.117188 74.582031 186.921875 77.335938 C 187.730469 80.078125 186.15625 82.960938 183.414062 83.769531 C 177.726562 85.433594 172.238281 87.238281 167.019531 89.183594 C 142.757812 98.21875 122.519531 110.703125 110.554688 127.828125 C 98.800781 144.628906 94.953125 166.246094 103.078125 193.9375 C 103.992188 197.066406 105.039062 200.222656 106.21875 203.386719 Z M 106.21875 203.386719 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 180.015625 133.421875 C 177.304688 134.328125 174.371094 132.871094 173.457031 130.152344 C 172.550781 127.441406 174.019531 124.503906 176.730469 123.589844 C 176.867188 123.550781 225.878906 107.207031 238.875 89.679688 C 240.457031 87.535156 240.777344 84.757812 240.085938 81.703125 C 239.03125 76.996094 235.757812 71.789062 231.003906 66.949219 C 226.027344 61.898438 219.53125 57.375 212.257812 54.308594 C 201.128906 49.613281 188.21875 48.34375 176.339844 53.914062 C 142.941406 69.605469 149.320312 92.152344 149.335938 92.21875 C 150.054688 94.988281 148.386719 97.8125 145.621094 98.53125 C 142.851562 99.246094 140.023438 97.582031 139.304688 94.8125 C 139.28125 94.722656 130.628906 63.941406 171.957031 44.535156 C 186.808594 37.554688 202.703125 39.03125 216.277344 44.765625 C 224.855469 48.382812 232.527344 53.722656 238.394531 59.683594 C 244.46875 65.863281 248.714844 72.828125 250.199219 79.425781 C 251.539062 85.394531 250.734375 91.089844 247.199219 95.851562 C 232.25 116.015625 180.164062 133.371094 180.015625 133.421875 Z M 180.015625 133.421875 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 239.179688 96.238281 C 237.257812 94.105469 237.433594 90.824219 239.566406 88.90625 C 241.691406 86.992188 244.980469 87.164062 246.894531 89.292969 C 247.050781 89.464844 300.871094 148.355469 272.710938 205.21875 C 271.441406 207.78125 268.328125 208.835938 265.765625 207.566406 C 263.195312 206.304688 262.140625 203.191406 263.40625 200.628906 C 288.410156 150.136719 239.320312 96.394531 239.179688 96.238281 Z M 239.179688 96.238281 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/cosmosan.ch\/en\/hautprobleme\/\" target=\"_blank\">\n                                    skin problems                                    <\/a><\/h4><div class=\"sc_icons_item_description\"><span>the range of skin diseases is wide, and the number of those who suffer very large. chronic skin problems can put a strain on the psyche and severely impair the quality of life. it is therefore quite easy to understand that...<\/span><\/div><a href=\"https:\/\/cosmosan.ch\/en\/hautprobleme\/\" class=\"sc_icons_item_more_link\" target=\"_blank\">\n                        <span class=\"link_text\">read more<\/span><span class=\"link_icon\"><\/span>\n                        <\/a><a href=\"https:\/\/cosmosan.ch\/en\/hautprobleme\/\" class=\"sc_icons_item_link\" target=\"_blank\">\n                        <\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_icon sc_icon_type_svg\" style=\"color: #FFFFFF\" ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"500\" viewbox=\"0 0 375 374.999991\" height=\"500\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"c335076853\"><path d=\"M 68 39 L 308 39 L 308 337.5 L 68 337.5 Z M 68 39 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><g clip-path=\"url(#c335076853)\"><path fill=\"#e10e49\" d=\"M 297.773438 254.304688 C 297.015625 257.429688 293.601562 260.027344 290.167969 262.355469 C 274.21875 273.335938 257.378906 283.40625 240.148438 292.351562 C 237.859375 293.554688 235.917969 295.4375 234.542969 297.824219 C 231.863281 302.480469 228.816406 305.621094 225.304688 307.503906 C 220.574219 309.988281 215.160156 310.375 210.792969 308.589844 C 206.429688 306.804688 203.1875 302.539062 202.957031 298.210938 C 202.703125 293.207031 206.429688 287.832031 211.996094 285.25 C 215.160156 283.757812 218.980469 283.019531 223.40625 283.019531 C 225.152344 283.019531 227.035156 283.117188 228.972656 283.347656 C 231.746094 283.699219 234.484375 283.15625 236.832031 281.816406 C 250.488281 273.976562 263.9375 265.421875 276.855469 256.339844 C 279.28125 254.59375 280.835938 251.917969 281.027344 248.890625 C 281.222656 245.863281 280.039062 242.933594 277.808594 240.898438 L 276.257812 239.5 C 274.414062 237.871094 272.589844 236.222656 271.132812 234.726562 C 265.082031 228.421875 258.230469 221.417969 252.625 214.316406 C 246.960938 207.214844 242.535156 200.113281 241.136719 193.617188 C 239.605469 186.164062 239.703125 183.082031 243.234375 180.636719 C 245.523438 179.101562 248.589844 178.910156 251.070312 180.09375 C 254.601562 181.800781 257.6875 185.117188 260.269531 188.046875 C 275.167969 204.828125 287.140625 224.097656 295.871094 245.261719 C 297.171875 248.386719 298.414062 251.722656 297.773438 254.304688 Z M 280.71875 313.265625 C 279.882812 317.03125 278.796875 321.261719 276.21875 323.238281 C 274.082031 324.925781 270.589844 325.375 266.960938 325.683594 C 240.652344 327.914062 220.125 328.070312 196.183594 326.128906 C 192.128906 325.78125 190.675781 324.734375 190.539062 324.480469 C 190.480469 324.34375 190.324219 323.550781 191.722656 320.8125 C 193.699219 316.738281 195.542969 313.753906 197.679688 310.628906 C 200.121094 313.714844 203.304688 316.234375 207.070312 317.789062 C 210.054688 319.03125 213.277344 319.613281 216.613281 319.613281 C 221.117188 319.613281 225.753906 318.464844 229.925781 316.292969 C 235.183594 313.5 239.507812 309.09375 243.136719 302.730469 C 243.429688 302.226562 243.972656 301.546875 244.707031 301.140625 C 258.425781 294.097656 271.832031 286.238281 284.792969 277.839844 C 284.851562 290.761719 283.863281 299.257812 280.71875 313.265625 Z M 170.613281 284.359375 C 168.324219 282.457031 165.839844 280.089844 164.753906 277.414062 C 163.316406 273.726562 164.402344 268.914062 165.742188 264.296875 C 169.777344 250.675781 175.675781 237.523438 183.125 225.296875 C 182.523438 227.78125 181.980469 230.265625 181.632812 232.789062 C 180.292969 241.789062 180.140625 254.652344 186.054688 266.527344 C 183.632812 264.996094 181.246094 263.480469 178.761719 262.105469 C 176.375 260.707031 173.347656 261.5625 171.953125 263.949219 C 170.613281 266.3125 171.445312 269.359375 173.832031 270.738281 C 181.789062 275.257812 189.296875 280.574219 196.242188 286.589844 C 194.261719 289.90625 193.15625 293.59375 193.0625 297.355469 C 184.96875 294.292969 177.265625 289.90625 170.613281 284.359375 Z M 144.632812 199.066406 C 131.128906 193.867188 117.761719 182.285156 108.71875 172.058594 C 126.511719 162.066406 156.855469 137.679688 168.632812 121.59375 C 180.195312 131.179688 192.324219 138.535156 204.644531 143.25 C 204.585938 143.539062 204.488281 143.847656 204.488281 144.199219 C 205.632812 165.65625 200.066406 183.527344 189.238281 193.304688 C 178.414062 203.101562 160.929688 205.390625 144.632812 199.066406 Z M 202.355469 193.519531 C 206.273438 188.144531 208.949219 182.226562 210.851562 176.230469 C 211.238281 176.425781 211.648438 176.621094 212.09375 176.832031 C 214.578125 177.804688 218.300781 179.355469 218.882812 180.753906 C 219.136719 181.335938 218.941406 182.925781 218.84375 183.527344 C 218.089844 189.132812 216.652344 194.605469 214.617188 199.824219 C 213.335938 203.101562 212.035156 204.925781 210.640625 205.429688 C 209.359375 205.878906 207.320312 205.042969 205.925781 203.492188 C 205.378906 202.910156 203.632812 200.464844 202.355469 193.519531 Z M 209.941406 215.460938 C 211.296875 215.460938 212.636719 215.269531 213.917969 214.820312 C 219.582031 212.84375 222.320312 207.371094 223.851562 203.453125 C 226.199219 197.476562 227.828125 191.230469 228.683594 184.863281 C 228.914062 182.886719 229.070312 180.789062 228.566406 178.65625 C 229.808594 178.617188 231.011719 178.558594 232.195312 178.558594 C 229.167969 184.417969 230.507812 191.074219 231.457031 195.59375 C 234.484375 210.242188 247.40625 224.503906 263.992188 241.636719 C 265.585938 243.285156 267.5625 245.070312 269.601562 246.914062 L 271.132812 248.25 C 258.484375 257.078125 245.269531 265.539062 231.863281 273.222656 C 231.300781 273.53125 230.621094 273.53125 230.214844 273.472656 C 221.523438 272.386719 213.976562 273.335938 207.765625 276.25 C 207.515625 276.363281 207.261719 276.5 207.03125 276.65625 C 201.8125 272.171875 198.222656 268.15625 195.796875 263.949219 C 190.074219 253.898438 190.285156 242.238281 191.46875 234.242188 C 192.671875 225.996094 195.390625 217.847656 198.375 209.855469 C 198.433594 209.953125 198.472656 210.050781 198.53125 210.144531 C 201.597656 213.523438 205.886719 215.460938 209.941406 215.460938 Z M 92.285156 142.066406 C 95.816406 149.359375 100.085938 156.304688 104.957031 162.824219 C 103.714844 163.5625 102.472656 164.203125 101.328125 164.804688 C 99.328125 165.792969 97.058594 166.742188 95.0625 166.78125 C 90.597656 166.6875 86.972656 160.828125 85.632812 158.285156 C 78.570312 145.226562 76.339844 129.238281 79.328125 113.351562 C 81.617188 101.125 86.914062 84.035156 99.386719 71.773438 C 109.417969 61.894531 118.90625 56.113281 132.121094 51.75 C 144.1875 47.769531 157.148438 48.78125 166.828125 54.386719 C 169.71875 56.074219 173.25 56.675781 176.878906 56.074219 C 184.777344 54.792969 194.710938 57.570312 201.015625 62.925781 C 209.007812 69.695312 213.121094 73.421875 220.027344 84.382812 C 230.757812 101.378906 235.183594 108.421875 243.71875 124.972656 C 246.453125 130.289062 248.6875 134.691406 250.78125 138.765625 C 253.867188 144.878906 256.582031 150.253906 259.957031 156.617188 C 263.800781 163.757812 267.175781 171.867188 267.816406 175.476562 C 268.203125 177.570312 268.066406 179.550781 267.5625 181.296875 C 265.082031 178.5 262.246094 175.476562 258.714844 173.144531 C 256.582031 160.03125 250.683594 147.324219 241.992188 137.292969 C 241.101562 136.242188 239.546875 136.148438 238.5 137.039062 C 237.472656 137.933594 237.375 139.523438 238.265625 140.550781 C 245.5625 148.953125 250.722656 159.390625 253.167969 170.273438 C 252.46875 170.0625 251.769531 169.867188 251.035156 169.710938 C 250.722656 169.617188 250.488281 169.460938 250.179688 169.382812 C 244.066406 168.277344 234.039062 168.277344 219.582031 169.226562 C 218.339844 168.625 217.097656 168.140625 215.914062 167.636719 C 214.964844 167.230469 213.976562 166.839844 213.121094 166.433594 C 214.421875 159.097656 214.675781 152.074219 214.519531 146.46875 C 219.234375 147.769531 223.949219 148.699219 228.625 149.242188 L 229.167969 149.242188 C 231.710938 149.242188 233.84375 147.359375 234.132812 144.839844 C 234.445312 142.101562 232.445312 139.660156 229.710938 139.367188 C 210.792969 137.292969 191.277344 127.941406 173.191406 112.457031 C 173.734375 109.023438 172.941406 104.890625 171.117188 102.40625 C 167.78125 97.945312 163.453125 94.179688 158.640625 91.386719 C 156.253906 90.046875 153.226562 90.882812 151.832031 93.289062 C 150.492188 95.65625 151.347656 98.683594 153.734375 100.039062 C 157.359375 102.117188 160.621094 105.007812 163.105469 108.265625 C 163.414062 108.867188 163.609375 110.613281 163.414062 111.214844 C 161.824219 114.882812 157.496094 120.140625 151.792969 125.960938 C 146.28125 119.753906 140.308594 113.988281 133.902344 108.730469 C 132.855469 107.878906 131.285156 108.035156 130.429688 109.082031 C 129.539062 110.167969 129.695312 111.699219 130.78125 112.59375 C 137.027344 117.714844 142.847656 123.378906 148.203125 129.433594 C 142.886719 134.554688 136.738281 139.871094 130.371094 144.9375 C 124.863281 138.921875 119.605469 132.617188 114.890625 125.960938 C 114.09375 124.816406 112.542969 124.5625 111.457031 125.359375 C 110.3125 126.15625 110.058594 127.707031 110.855469 128.832031 C 115.570312 135.546875 120.886719 141.910156 126.511719 148 C 120.496094 152.636719 114.542969 156.847656 109.226562 160.226562 C 104.453125 153.878906 100.242188 147.070312 96.75 139.871094 C 96.167969 138.667969 94.671875 138.125 93.433594 138.726562 C 92.191406 139.308594 91.6875 140.824219 92.285156 142.066406 Z M 305.066406 241.480469 C 297.269531 222.621094 286.984375 205.179688 274.472656 189.542969 C 277.554688 185.3125 278.699219 179.605469 277.59375 173.652344 C 276.449219 167.480469 271.484375 157.101562 268.765625 151.941406 C 265.390625 145.632812 262.695312 140.320312 259.609375 134.265625 C 257.53125 130.191406 255.300781 125.765625 252.566406 120.394531 C 243.816406 103.511719 239.003906 95.847656 228.46875 79.066406 C 220.824219 66.960938 215.722656 62.382812 207.417969 55.339844 C 198.921875 48.121094 185.960938 44.511719 175.230469 46.296875 C 173.929688 46.492188 172.6875 46.335938 171.796875 45.851562 C 159.726562 38.789062 143.742188 37.488281 129.035156 42.320312 C 114.445312 47.132812 103.5 53.785156 92.441406 64.671875 C 78.125 78.738281 72.070312 97.90625 69.527344 111.507812 C 66.152344 129.6875 68.792969 147.960938 76.882812 163.019531 C 81.617188 171.808594 87.824219 176.5625 94.867188 176.714844 C 96.304688 176.714844 97.757812 176.484375 99.136719 176.171875 C 104.996094 183.175781 121.195312 200.660156 141.0625 208.359375 C 148.457031 211.195312 156.003906 212.628906 163.316406 212.628906 C 169.816406 212.628906 176.082031 211.445312 181.847656 209.253906 C 170.515625 225.046875 161.726562 242.933594 156.214844 261.464844 C 154.375 267.808594 152.976562 274.519531 155.519531 281.019531 C 157.398438 285.792969 160.96875 289.265625 164.25 292.003906 C 171.445312 298.015625 179.808594 302.828125 188.636719 306.300781 C 186.601562 309.289062 184.777344 312.414062 182.777344 316.390625 C 181.730469 318.464844 179.304688 323.394531 181.378906 328.304688 C 182.621094 331.386719 186.113281 335.269531 195.390625 336.007812 C 206.875 336.957031 217.546875 337.402344 228.429688 337.402344 C 240.847656 337.402344 253.515625 336.800781 267.816406 335.558594 C 272.839844 335.171875 278.039062 334.414062 282.308594 331.097656 C 287.9375 326.671875 289.566406 319.320312 290.417969 315.402344 C 294.085938 298.851562 295.035156 289.167969 294.628906 272.328125 C 294.628906 271.980469 294.53125 271.746094 294.433594 271.4375 C 294.882812 271.144531 295.328125 270.855469 295.773438 270.542969 C 300.585938 267.207031 305.863281 263.191406 307.394531 256.632812 C 308.734375 251.121094 306.910156 245.902344 305.066406 241.480469 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#e10e49\" d=\"M 159.4375 184.359375 C 158.136719 184.863281 156.703125 185.117188 155.304688 185.117188 C 152.976562 185.117188 150.648438 184.417969 148.707031 183.117188 C 145.585938 181.101562 143.546875 177.472656 143.390625 173.691406 C 143.351562 172.351562 144.382812 171.167969 145.777344 171.109375 C 147.214844 171.050781 148.320312 172.15625 148.359375 173.535156 C 148.417969 175.667969 149.660156 177.804688 151.445312 179.003906 C 153.226562 180.207031 155.652344 180.5 157.691406 179.703125 C 158.992188 179.257812 160.425781 179.859375 160.871094 181.140625 C 161.378906 182.441406 160.738281 183.875 159.4375 184.359375 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 122.476562 253.664062 C 121 252.265625 119.101562 251.53125 117.160156 251.53125 C 116.578125 251.53125 116.035156 251.628906 115.433594 251.722656 C 112.949219 252.304688 110.855469 254.109375 109.921875 256.496094 C 109.476562 257.621094 108.933594 258.785156 108.371094 259.871094 C 108.023438 260.511719 107.34375 260.863281 106.742188 260.707031 C 100.027344 258.4375 93.023438 255.140625 85.378906 250.734375 C 85.339844 250.675781 85.28125 250.386719 85.378906 249.976562 C 86.71875 245.960938 93.335938 232.304688 97.195312 227.238281 C 101.074219 230.964844 104.101562 234.4375 106.546875 237.910156 C 107.828125 239.753906 109.769531 240.898438 111.960938 241.246094 C 114.09375 241.597656 116.324219 240.996094 118.054688 239.65625 C 120.109375 238.066406 122.28125 236.726562 124.511719 235.582031 C 128.898438 243.613281 132.527344 252.714844 135.59375 263.191406 C 130.527344 260.222656 126.203125 257.078125 122.476562 253.664062 Z M 146.417969 265.035156 C 142.847656 251.722656 138.484375 240.453125 133.070312 230.460938 C 130.625 225.996094 125.113281 224.25 120.4375 226.539062 C 118.054688 227.683594 115.722656 229.0625 113.550781 230.613281 C 110.855469 227.082031 107.632812 223.515625 103.753906 219.789062 C 101.773438 217.886719 99.195312 216.996094 96.515625 217.207031 C 93.722656 217.402344 91.085938 218.839844 89.300781 221.1875 C 84.644531 227.277344 77.582031 241.945312 75.949219 246.855469 C 74.359375 251.761719 76.144531 256.886719 80.414062 259.328125 C 88.660156 264.082031 96.207031 267.613281 103.558594 270.097656 C 108.816406 271.882812 114.675781 269.398438 117.277344 264.335938 C 117.507812 263.890625 117.722656 263.402344 117.957031 262.898438 C 122.785156 267.011719 128.335938 270.699219 134.894531 274.171875 C 136.097656 274.8125 137.378906 275.121094 138.675781 275.121094 C 140.460938 275.121094 142.207031 274.519531 143.703125 273.335938 C 146.1875 271.339844 147.214844 268.117188 146.417969 265.035156 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 120.304688 300.09375 L 119.761719 300.09375 C 117.0625 299.996094 114.734375 301.296875 113.242188 303.429688 C 111.746094 305.507812 111.417969 308.203125 112.308594 310.628906 C 112.699219 311.675781 113.394531 312.761719 114.132812 314.003906 C 114.484375 314.605469 114.890625 315.148438 115.085938 315.59375 C 114.832031 315.75 114.484375 315.945312 113.902344 316.195312 C 106.742188 318.933594 99.988281 320.71875 92.09375 321.960938 C 91.6875 321.996094 91.492188 321.707031 91.394531 321.453125 C 89.492188 317.1875 86.371094 308.105469 85.882812 301.996094 L 86.175781 301.9375 C 88.601562 301.683594 90.792969 301.585938 92.984375 301.488281 C 95.46875 301.335938 97.992188 301.238281 100.980469 300.886719 C 107.03125 300.152344 108.585938 296.523438 108.972656 294.390625 C 109.417969 291.847656 110.117188 289.363281 111.066406 287.035156 C 119.449219 290.023438 127.988281 294.195312 136.988281 299.742188 C 130.972656 300.25 125.753906 300.191406 120.304688 300.09375 Z M 147.019531 294.332031 C 135.496094 286.785156 124.667969 281.332031 113.996094 277.546875 C 109.226562 275.859375 103.910156 278.246094 101.96875 283.019531 C 100.921875 285.601562 100.085938 288.277344 99.484375 291.070312 C 96.945312 291.363281 94.710938 291.460938 92.480469 291.554688 C 90.09375 291.652344 87.707031 291.75 85.03125 292.097656 C 79.460938 292.699219 75.542969 297.320312 75.988281 302.730469 C 76.589844 310.726562 80.375 321.066406 82.296875 325.433594 C 84.042969 329.449219 87.824219 331.929688 91.976562 331.929688 C 92.539062 331.929688 93.082031 331.894531 93.683594 331.796875 C 102.257812 330.398438 109.613281 328.457031 117.472656 325.488281 C 124.609375 322.695312 125.96875 317.378906 124.863281 313.304688 C 124.570312 312.316406 124.066406 311.328125 123.367188 310.085938 C 129.578125 310.125 136.136719 310.027344 144.03125 308.941406 C 147.214844 308.4375 149.753906 306.109375 150.453125 302.886719 C 151.191406 299.609375 149.792969 296.175781 147.019531 294.332031 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/cosmosan.ch\/en\/monatsbeschwerden\/\" target=\"_blank\">\n                                    menstrual problems                                    <\/a><\/h4><div class=\"sc_icons_item_description\"><span>pain and agony. in the best case only for a few hours, in the worst over days. many women are afflicted monthly by sometimes almost unbearable stabbing, pulling or cramp-like abdominal pain when...<\/span><\/div><a href=\"https:\/\/cosmosan.ch\/en\/monatsbeschwerden\/\" class=\"sc_icons_item_more_link\" target=\"_blank\">\n                        <span class=\"link_text\">read more<\/span><span class=\"link_icon\"><\/span>\n                        <\/a><a href=\"https:\/\/cosmosan.ch\/en\/monatsbeschwerden\/\" class=\"sc_icons_item_link\" target=\"_blank\">\n                        <\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_icon sc_icon_type_svg\" style=\"color: #FFFFFF\" ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"500\" viewbox=\"0 0 375 374.999991\" height=\"500\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"6e98e0f71c\"><path d=\"M 37.5 52.125 L 337.5 52.125 L 337.5 322.875 L 37.5 322.875 Z M 37.5 52.125 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><g clip-path=\"url(#6e98e0f71c)\"><path fill=\"#e10e49\" d=\"M 245.519531 76.300781 L 245.519531 95.636719 C 245.519531 98.300781 243.347656 100.472656 240.683594 100.472656 C 238.019531 100.472656 235.847656 98.300781 235.847656 95.636719 L 235.847656 76.300781 C 235.847656 73.636719 238.019531 71.464844 240.683594 71.464844 C 243.347656 71.464844 245.519531 73.636719 245.519531 76.300781 Z M 327.710938 95.636719 L 322.875 95.636719 C 317.550781 95.636719 313.207031 99.980469 313.207031 105.308594 L 313.207031 110.144531 L 226.179688 110.144531 L 226.179688 61.792969 L 313.207031 61.792969 L 313.207031 66.628906 C 313.207031 71.957031 317.550781 76.300781 322.875 76.300781 L 327.710938 76.300781 Z M 327.710938 66.628906 L 322.875 66.628906 L 322.875 61.792969 C 322.875 56.46875 318.53125 52.125 313.207031 52.125 L 226.179688 52.125 C 220.851562 52.125 216.507812 56.46875 216.507812 61.792969 L 216.507812 110.144531 C 216.507812 115.46875 220.851562 119.8125 226.179688 119.8125 L 313.207031 119.8125 C 318.53125 119.8125 322.875 115.46875 322.875 110.144531 L 322.875 105.308594 L 327.710938 105.308594 C 333.035156 105.308594 337.378906 100.964844 337.378906 95.636719 L 337.378906 76.300781 C 337.378906 70.972656 333.035156 66.628906 327.710938 66.628906 Z M 110.160156 148.347656 C 110.992188 140.039062 129.464844 114.976562 158.492188 114.976562 C 170.503906 114.976562 176.90625 117.242188 181.136719 118.753906 C 185.953125 120.453125 187.085938 120.851562 194.429688 115.828125 C 202.664062 110.199219 211.675781 133.996094 211.675781 143.988281 C 211.675781 152.84375 209.785156 158.171875 206.6875 166.554688 C 209.390625 169.066406 211.523438 172.730469 211.523438 177.980469 C 211.523438 186.234375 207.046875 192.015625 204.535156 194.601562 C 202.761719 209.898438 193.335938 235.847656 168.160156 235.847656 C 157.507812 235.847656 150.105469 232.277344 145.742188 229.292969 C 143.550781 227.785156 142.984375 224.761719 144.496094 222.570312 C 146.027344 220.363281 149.027344 219.8125 151.21875 221.324219 C 154.449219 223.535156 160 226.179688 168.160156 226.179688 C 192.015625 226.179688 194.960938 193.355469 195.074219 191.957031 C 195.1875 190.617188 195.847656 189.371094 196.90625 188.539062 C 197.074219 188.386719 201.851562 184.421875 201.851562 177.980469 C 201.851562 173.109375 197.640625 171.957031 196.359375 171.710938 C 194.996094 171.464844 193.769531 170.652344 193.050781 169.484375 C 191.164062 166.421875 184.722656 158.492188 177.832031 158.492188 C 174.941406 158.492188 173.335938 159.339844 170.9375 160.644531 C 165.988281 163.308594 159.832031 166.632812 143.023438 163.230469 C 136.714844 161.945312 138.734375 152.449219 144.949219 153.75 C 158.320312 156.46875 162.402344 154.261719 166.347656 152.125 C 169.21875 150.578125 172.484375 148.820312 177.832031 148.820312 C 187.386719 148.820312 194.789062 156.035156 198.546875 160.664062 C 200.851562 154.375 202.003906 150.332031 202.003906 143.988281 C 202.003906 136.640625 198.492188 130.046875 196 126.289062 C 188.351562 130.730469 184.269531 130.105469 177.925781 127.859375 C 143.742188 115.769531 121.003906 141.4375 119.773438 149.332031 C 119.378906 151.917969 116.980469 153.808594 114.390625 153.503906 C 111.785156 153.164062 109.917969 150.957031 110.160156 148.347656 Z M 76.507812 289.03125 L 95.636719 289.03125 C 98.300781 289.03125 100.472656 286.859375 100.472656 284.195312 C 100.472656 235.394531 107.347656 200.984375 109.859375 193.960938 C 113.089844 184.914062 112.824219 168.160156 124.648438 168.160156 C 128.40625 168.160156 139.152344 170.824219 139.152344 182.664062 C 139.152344 187.574219 137.867188 188.898438 135.753906 191.070312 C 133.109375 193.808594 129.480469 197.546875 129.480469 206.839844 L 129.480469 284.195312 C 129.480469 297.433594 125.289062 313.207031 105.308594 313.207031 C 87.214844 313.207031 77.941406 305.5 76.507812 289.03125 Z M 332.542969 313.207031 L 286.519531 313.207031 C 290.429688 304.859375 289.144531 293.355469 286.992188 284.441406 C 288.3125 282.535156 288.785156 281.003906 288.898438 280.476562 C 289.105469 279.625 289.070312 278.738281 288.804688 277.90625 C 288.144531 275.792969 272.488281 226.007812 264.007812 213.75 C 254.660156 200.265625 231.410156 196.734375 217.945312 192.542969 C 215.394531 191.769531 212.695312 193.183594 211.882812 195.734375 C 211.109375 198.285156 212.523438 200.984375 215.074219 201.796875 C 227.632812 205.6875 249.085938 209.21875 256.039062 219.265625 C 262.136719 228.046875 274.148438 263.6875 279.003906 278.964844 C 277.058594 281.609375 268.9375 288.710938 239.757812 284.707031 L 235.695312 268.519531 C 235.054688 265.933594 232.410156 264.347656 229.84375 265.007812 C 227.253906 265.648438 225.667969 268.277344 226.328125 270.863281 L 231.164062 290.203125 C 231.636719 292.089844 233.183594 293.507812 235.09375 293.808594 C 248.445312 295.886719 266.40625 297.152344 278.550781 291.261719 C 279.003906 293.753906 279.363281 296.433594 279.363281 298.699219 C 279.363281 308.523438 277.925781 313.207031 269.691406 313.207031 L 158.679688 313.207031 C 160.097656 294.546875 171.332031 293.867188 216.507812 293.867188 C 219.171875 293.867188 221.34375 291.695312 221.34375 289.03125 C 221.34375 286.367188 219.171875 284.195312 216.507812 284.195312 C 172.390625 284.195312 151.070312 284.253906 149.027344 313.207031 L 129.59375 313.207031 C 135.769531 306.558594 139.152344 296.679688 139.152344 284.195312 L 139.152344 206.839844 C 139.152344 201.476562 140.566406 200.019531 142.703125 197.8125 C 145.289062 195.148438 148.820312 191.503906 148.820312 182.664062 C 148.820312 165.988281 134.695312 158.492188 124.648438 158.492188 C 107.894531 158.492188 104.382812 174.808594 102.285156 184.574219 C 100.546875 192.617188 91.371094 219.71875 90.824219 279.363281 L 71.539062 279.363281 C 72.445312 252.410156 80.71875 219.925781 93.597656 210.785156 C 95.789062 209.238281 96.300781 206.214844 94.75 204.042969 C 93.203125 201.851562 90.179688 201.34375 88.007812 202.890625 C 68.914062 216.433594 61.792969 259.945312 61.792969 284.195312 C 61.792969 286.859375 63.964844 289.03125 66.628906 289.03125 L 66.800781 289.03125 C 67.574219 299.511719 71.03125 307.539062 76.847656 313.207031 L 42.457031 313.207031 C 39.792969 313.207031 37.621094 315.378906 37.621094 318.039062 C 37.621094 320.703125 39.792969 322.875 42.457031 322.875 L 332.542969 322.875 C 335.207031 322.875 337.378906 320.703125 337.378906 318.039062 C 337.378906 315.378906 335.207031 313.207031 332.542969 313.207031 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><\/svg><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/cosmosan.ch\/en\/chronische-muedigkeit\/\" target=\"_blank\">\n                                    chronic fatigue                                    <\/a><\/h4><div class=\"sc_icons_item_description\"><span>the everyday commitments seem tedious, the professional demands overtaxing, the social contacts draining, and you don't understand what's the matter with you. chronic fatigue is usually detected when...<\/span><\/div><a href=\"https:\/\/cosmosan.ch\/en\/chronische-muedigkeit\/\" class=\"sc_icons_item_more_link\" target=\"_blank\">\n                        <span class=\"link_text\">read more<\/span><span class=\"link_icon\"><\/span>\n                        <\/a><a href=\"https:\/\/cosmosan.ch\/en\/chronische-muedigkeit\/\" class=\"sc_icons_item_link\" target=\"_blank\">\n                        <\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_icon sc_icon_type_svg\" style=\"color: #FFFFFF\" ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"500\" viewbox=\"0 0 375 374.999991\" height=\"500\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"289fefdb1e\"><path d=\"M 49.015625 60.613281 L 325.765625 60.613281 L 325.765625 314.113281 L 49.015625 314.113281 Z M 49.015625 60.613281 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><g clip-path=\"url(#289fefdb1e)\"><path fill=\"#e10e49\" d=\"M 212.6875 75.402344 C 207.460938 66.277344 197.820312 60.613281 187.496094 60.613281 C 177.171875 60.613281 167.527344 66.277344 162.164062 75.675781 L 53.804688 269.660156 L 52.675781 271.574219 C 50.320312 275.832031 49.074219 280.664062 49.074219 285.542969 C 49.074219 301.453125 62.007812 314.382812 77.914062 314.382812 L 297.078125 314.382812 C 312.984375 314.382812 325.914062 301.453125 325.914062 285.542969 C 325.914062 280.664062 324.667969 275.832031 322.222656 271.390625 Z M 297.078125 302.847656 L 77.914062 302.847656 C 68.375 302.847656 60.609375 295.085938 60.609375 285.542969 C 60.609375 282.570312 61.335938 279.742188 62.6875 277.320312 L 172.316406 81.121094 C 175.488281 75.597656 181.300781 72.148438 187.496094 72.148438 C 193.6875 72.148438 199.503906 75.597656 202.753906 81.304688 L 311.265625 275.589844 L 312.210938 277.148438 C 313.652344 279.742188 314.378906 282.570312 314.378906 285.542969 C 314.378906 295.085938 306.617188 302.847656 297.078125 302.847656 Z M 297.078125 302.847656 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/g><path fill=\"#e10e49\" d=\"M 199.03125 268.242188 C 199.03125 269 198.957031 269.75 198.808594 270.492188 C 198.660156 271.234375 198.441406 271.957031 198.152344 272.65625 C 197.863281 273.355469 197.507812 274.019531 197.085938 274.652344 C 196.664062 275.28125 196.1875 275.863281 195.652344 276.398438 C 195.117188 276.933594 194.535156 277.414062 193.902344 277.832031 C 193.273438 278.253906 192.609375 278.609375 191.910156 278.898438 C 191.210938 279.1875 190.488281 279.40625 189.746094 279.554688 C 189.003906 279.703125 188.253906 279.777344 187.496094 279.777344 C 186.738281 279.777344 185.988281 279.703125 185.246094 279.554688 C 184.5 279.40625 183.78125 279.1875 183.082031 278.898438 C 182.382812 278.609375 181.714844 278.253906 181.085938 277.832031 C 180.457031 277.414062 179.875 276.933594 179.339844 276.398438 C 178.804688 275.863281 178.324219 275.28125 177.902344 274.652344 C 177.484375 274.019531 177.128906 273.355469 176.839844 272.65625 C 176.546875 271.957031 176.328125 271.234375 176.183594 270.492188 C 176.035156 269.75 175.960938 269 175.960938 268.242188 C 175.960938 267.484375 176.035156 266.734375 176.183594 265.992188 C 176.328125 265.25 176.546875 264.527344 176.839844 263.828125 C 177.128906 263.128906 177.484375 262.464844 177.902344 261.832031 C 178.324219 261.203125 178.804688 260.621094 179.339844 260.085938 C 179.875 259.550781 180.457031 259.070312 181.085938 258.652344 C 181.714844 258.230469 182.382812 257.875 183.082031 257.585938 C 183.78125 257.296875 184.5 257.078125 185.246094 256.929688 C 185.988281 256.78125 186.738281 256.707031 187.496094 256.707031 C 188.253906 256.707031 189.003906 256.78125 189.746094 256.929688 C 190.488281 257.078125 191.210938 257.296875 191.910156 257.585938 C 192.609375 257.875 193.273438 258.230469 193.902344 258.652344 C 194.535156 259.070312 195.117188 259.550781 195.652344 260.085938 C 196.1875 260.621094 196.664062 261.203125 197.085938 261.832031 C 197.507812 262.464844 197.863281 263.128906 198.152344 263.828125 C 198.441406 264.527344 198.660156 265.25 198.808594 265.992188 C 198.957031 266.734375 199.03125 267.484375 199.03125 268.242188 Z M 199.03125 268.242188 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><path fill=\"#e10e49\" d=\"M 187.496094 129.824219 C 181.152344 129.824219 175.960938 135.011719 175.960938 141.359375 C 175.960938 141.601562 176.085938 141.808594 176.097656 142.050781 L 175.960938 142.050781 L 181.726562 239.40625 L 181.726562 239.75 C 181.957031 242.867188 184.378906 245.171875 187.496094 245.171875 C 190.609375 245.171875 193.03125 242.867188 193.261719 239.75 L 193.261719 239.40625 L 199.03125 142.050781 L 198.890625 142.050781 C 198.902344 141.808594 199.03125 141.601562 199.03125 141.359375 C 199.03125 135.011719 193.839844 129.824219 187.496094 129.824219 Z M 187.496094 129.824219 \" fill-opacity=\"1\" fill-rule=\"nonzero\"><\/path><\/svg><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/cosmosan.ch\/en\/angst-und-panikattacken\/\" target=\"_blank\">\n                                    anxiety &amp; panic disorders                                    <\/a><\/h4><div class=\"sc_icons_item_description\"><span>es beginnt, so scheint es, v\u00f6llig unvermittelt. pl\u00f6tzlich bricht der schweiss aus, das herz beginnt zu rasen, der k\u00f6rper zu zittern, die atmung wird flach, die sinne sind wie benebelt, nichts wirkt mehr real, und alles im k\u00f6rper schreit nach...<\/span><\/div><a href=\"https:\/\/cosmosan.ch\/en\/angst-und-panikattacken\/\" class=\"sc_icons_item_more_link\" target=\"_blank\">\n                        <span class=\"link_text\">read more<\/span><span class=\"link_icon\"><\/span>\n                        <\/a><a href=\"https:\/\/cosmosan.ch\/en\/angst-und-panikattacken\/\" class=\"sc_icons_item_link\" target=\"_blank\">\n                        <\/a><\/div><\/div><\/div><div class=\"slider-slide swiper-slide\"><div class=\"sc_icons_item sc_icons_item_linked with_more\"><div class=\"sc_icons_icon sc_icon_type_svg\" style=\"color: #FFFFFF\" ><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" width=\"500\" viewbox=\"0 0 375 374.999991\" height=\"500\" preserveaspectratio=\"xMidYMid meet\"><defs><clippath id=\"477058e227\"><path d=\"M 37.5 80.25 L 337.5 80.25 L 337.5 294.75 L 37.5 294.75 Z M 37.5 80.25 \" clip-rule=\"nonzero\"><\/path><\/clippath><\/defs><g clip-path=\"url(#477058e227)\"><path fill=\"#e10e49\" d=\"M 149.902344 235.042969 L 149.902344 289.335938 C 149.902344 292.289062 152.300781 294.6875 155.257812 294.6875 L 243 294.6875 C 253.382812 294.6875 263.304688 290.378906 270.390625 282.785156 C 290.570312 261.164062 335.804688 212.699219 335.804688 212.699219 C 337.003906 211.414062 337.496094 209.625 337.121094 207.90625 C 336.746094 206.1875 335.550781 204.765625 333.925781 204.097656 C 287.261719 184.90625 256.296875 153.734375 240.570312 110.871094 C 239.949219 109.191406 238.53125 107.925781 236.785156 107.507812 C 235.042969 107.089844 233.207031 107.578125 231.894531 108.804688 L 187.355469 150.363281 L 187.355469 85.9375 C 187.355469 84.117188 186.433594 82.425781 184.902344 81.441406 C 183.378906 80.457031 181.457031 80.3125 179.804688 81.0625 C 157.375 91.179688 134.960938 96.664062 112.53125 96.644531 C 90.03125 96.621094 67.53125 91.066406 45.03125 81.046875 C 43.371094 80.3125 41.457031 80.460938 39.933594 81.449219 C 38.414062 82.4375 37.5 84.125 37.5 85.9375 L 37.5 183.804688 C 37.5 194.214844 41.832031 204.160156 49.457031 211.246094 C 68.828125 229.253906 108.886719 266.492188 108.886719 266.492188 C 110.941406 268.40625 114.128906 268.402344 116.175781 266.484375 Z M 187.355469 165.007812 L 187.355469 183.832031 C 187.355469 194.226562 183.042969 204.148438 175.441406 211.238281 L 160.609375 225.0625 L 160.609375 283.984375 C 160.609375 283.984375 243 283.984375 243 283.984375 C 250.417969 283.984375 257.5 280.90625 262.5625 275.484375 C 262.5625 275.484375 322.792969 210.953125 322.785156 210.953125 C 279.664062 191.507812 250.0625 161.726562 233.441406 122.003906 Z M 183.703125 235.515625 C 192.183594 232.667969 200.046875 234.53125 205.035156 239.464844 C 210.019531 244.394531 211.945312 252.238281 209.058594 260.875 C 208.125 263.675781 209.632812 266.710938 212.4375 267.648438 C 215.238281 268.582031 218.273438 267.074219 219.207031 264.269531 C 223.597656 251.144531 220.128906 239.34375 212.5625 231.855469 C 204.996094 224.371094 193.15625 221.046875 180.300781 225.367188 C 177.496094 226.308594 175.988281 229.34375 176.929688 232.144531 C 177.871094 234.941406 180.90625 236.453125 183.703125 235.515625 Z M 176.648438 94.058594 L 176.648438 183.832031 C 176.648438 191.253906 173.566406 198.347656 168.140625 203.40625 C 168.140625 203.40625 112.527344 255.261719 112.527344 255.261719 C 112.527344 255.261719 56.746094 203.40625 56.746094 203.40625 C 51.300781 198.34375 48.203125 191.238281 48.203125 183.804688 C 48.203125 183.804688 48.203125 94.019531 48.203125 94.019531 C 69.640625 102.648438 91.089844 107.328125 112.527344 107.347656 C 133.898438 107.363281 155.277344 102.75 176.648438 94.058594 Z M 246.394531 214.398438 C 246.394531 223.382812 248.796875 229.910156 253.144531 234.300781 C 257.5 238.707031 264.003906 241.164062 273.011719 241.164062 C 275.96875 241.164062 278.363281 238.765625 278.363281 235.808594 C 278.363281 232.855469 275.96875 230.457031 273.011719 230.457031 C 267.527344 230.457031 263.40625 229.457031 260.75 226.773438 C 258.085938 224.078125 257.097656 219.914062 257.097656 214.398438 C 257.097656 211.445312 254.703125 209.046875 251.746094 209.046875 C 248.792969 209.046875 246.394531 211.445312 246.394531 214.398438 Z M 82.460938 202.527344 C 92.476562 210.566406 102.550781 214.414062 112.558594 214.398438 C 122.5625 214.382812 132.625 210.507812 142.628906 202.539062 C 144.9375 200.703125 145.320312 197.332031 143.480469 195.019531 C 141.640625 192.707031 138.265625 192.324219 135.953125 194.167969 C 128.132812 200.402344 120.367188 203.683594 112.542969 203.695312 C 104.734375 203.707031 96.976562 200.449219 89.164062 194.179688 C 86.859375 192.332031 83.488281 192.699219 81.636719 195.003906 C 79.789062 197.308594 80.160156 200.675781 82.460938 202.527344 Z M 203.429688 171.578125 C 203.429688 180.367188 205.855469 186.914062 210.25 191.363281 C 214.648438 195.808594 221.199219 198.34375 230.191406 198.34375 C 233.148438 198.34375 235.542969 195.945312 235.542969 192.988281 C 235.542969 190.035156 233.148438 187.636719 230.191406 187.636719 C 224.699219 187.636719 220.546875 186.550781 217.859375 183.832031 C 215.171875 181.113281 214.132812 176.957031 214.132812 171.578125 C 214.132812 168.625 211.734375 166.226562 208.78125 166.226562 C 205.828125 166.226562 203.429688 168.625 203.429688 171.578125 Z M 132.828125 153.371094 C 136.855469 147.984375 140.535156 144.816406 144.5625 144.828125 C 148.597656 144.839844 152.296875 148.027344 156.332031 153.386719 C 158.109375 155.746094 161.464844 156.222656 163.824219 154.445312 C 166.1875 152.667969 166.664062 149.3125 164.886719 146.953125 C 158.226562 138.105469 151.246094 134.144531 144.589844 134.121094 C 137.917969 134.105469 130.921875 138.035156 124.253906 146.96875 C 122.484375 149.335938 122.96875 152.691406 125.335938 154.457031 C 127.707031 156.222656 131.0625 155.742188 132.828125 153.371094 Z M 68.738281 153.371094 C 72.761719 147.984375 76.445312 144.816406 80.46875 144.828125 C 84.507812 144.839844 88.203125 148.027344 92.242188 153.386719 C 94.019531 155.746094 97.378906 156.222656 99.738281 154.445312 C 102.101562 152.667969 102.570312 149.3125 100.792969 146.953125 C 94.136719 138.105469 87.15625 134.144531 80.496094 134.121094 C 73.828125 134.105469 66.832031 138.035156 60.164062 146.96875 C 58.394531 149.335938 58.878906 152.691406 61.25 154.457031 C 63.613281 156.222656 66.972656 155.742188 68.738281 153.371094 Z M 68.738281 153.371094 \" fill-opacity=\"1\" fill-rule=\"evenodd\"><\/path><\/g><\/svg><\/div><div class=\"sc_icons_item_details\"><h4 class=\"sc_icons_item_title\"><a href=\"https:\/\/cosmosan.ch\/en\/stimmungsschwankungen\/\" target=\"_blank\">\n                                    mood swings                                    <\/a><\/h4><div class=\"sc_icons_item_description\"><span>nowadays, as professional demands and private desires are increasing, often accompanied by frustration and self-doubt, inner peace and balance are an invaluable asset. but what to do when you get up in the morning...<\/span><\/div><a href=\"https:\/\/cosmosan.ch\/en\/stimmungsschwankungen\/\" class=\"sc_icons_item_more_link\" target=\"_blank\">\n                        <span class=\"link_text\">read more<\/span><span class=\"link_icon\"><\/span>\n                        <\/a><a href=\"https:\/\/cosmosan.ch\/en\/stimmungsschwankungen\/\" class=\"sc_icons_item_link\" target=\"_blank\">\n                        <\/a><\/div><\/div><\/div><\/div><\/div><div class=\"slider_controls_wrap\"><a class=\"slider_prev swiper-button-prev\" href=\"#\"><\/a><a class=\"slider_next swiper-button-next\" href=\"#\"><\/a><\/div><\/div><\/div><!-- \/.sc_icons -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b19264 sc_height_medium sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"3b19264\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f4b3569 scheme_default sc_fly_static elementor-widget elementor-widget-trx_sc_button\" data-id=\"f4b3569\" data-element_type=\"widget\" data-widget_type=\"trx_sc_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div\tclass=\"sc_item_button sc_button_wrap sc_align_center\" ><a href=\"mailto:info@cosmosan.ch\" class=\"sc_button sc_button_hover sc_button_size_normal sc_button_with_icon sc_button_icon_left color_style_link2\" ><span class=\"sc_button_icon\"><span class=\"icon-lightbulb-light\"><\/span><\/span><span class=\"sc_button_text\"><span class=\"sc_button_title\">any questions?<\/span><\/span><\/a><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e0c270 sc_fly_static elementor-widget elementor-widget-spacer\" data-id=\"4e0c270\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>gut zu wissen gut zu wissen gut zu wissen gut zu wissen gut zu wissen:&hellip;<\/p>","protected":false},"author":1,"featured_media":29351,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-22185","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/cosmosan.ch\/en\/wp-json\/wp\/v2\/pages\/22185"}],"collection":[{"href":"https:\/\/cosmosan.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/cosmosan.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/cosmosan.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cosmosan.ch\/en\/wp-json\/wp\/v2\/comments?post=22185"}],"version-history":[{"count":76,"href":"https:\/\/cosmosan.ch\/en\/wp-json\/wp\/v2\/pages\/22185\/revisions"}],"predecessor-version":[{"id":29789,"href":"https:\/\/cosmosan.ch\/en\/wp-json\/wp\/v2\/pages\/22185\/revisions\/29789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cosmosan.ch\/en\/wp-json\/wp\/v2\/media\/29351"}],"wp:attachment":[{"href":"https:\/\/cosmosan.ch\/en\/wp-json\/wp\/v2\/media?parent=22185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}